{"id":84337,"date":"2023-05-26T22:40:44","date_gmt":"2023-05-27T02:40:44","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=84337"},"modified":"2023-05-29T14:09:28","modified_gmt":"2023-05-29T18:09:28","slug":"resultats-et-video-pour-le-wwe-friday-night-smackdown-du-26-mai-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/05\/26\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-26-mai-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 26 Mai 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/26\/avant-gout-pour-le-wwe-friday-night-smackdown-du-26-mai-2023\/\" target=\"_blank\"><strong>Pour voir Smackdown, cliquez ici<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p><strong>WWE SmackDown Columbia, Caroline du Sud, 26 mai 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Michael Cole et Wade Barrett.<\/p>\n\n\n\n<p>&#8211; Le WWE SmackDown d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue puis les catcheurs arrivent pour le premier match de la soir\u00e9e.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Championnat des USA<\/strong><\/p>\n\n\n\n<p><strong>Sheamus (accompagn\u00e9 de Butch &amp; Ridge Holland) vs Austin Theory (c)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Sheamus se pr\u00e9pare \u00e0 faire son Brogue Kick sur Austin Theory mais Pretty Deadly arrive pour attaquer Butch et Ridge Holland en ringside. Sheamus arrive \u00e0 attraper Elton Prince sur le tablier mais Austin Theory en profite pour faire un roll up et l&#8217;emporter.<\/p>\n\n\n\n<p><strong>Gagnant : Austin Theory <\/strong><\/p>\n\n\n\n<p>&#8211;&nbsp;Dans les coulisses, Paul Heyman dit aux Usos qu&rsquo;ils ne seront pas \u00e0 Night of Champions, mais il sont invit\u00e9s pour la c\u00e9l\u00e9bration des 1 000 jours de r\u00e8gne de Roman Reigns.&nbsp;Jimmy Uso allait s&rsquo;en aller mais Roman Reigns lui dit de s&rsquo;asseoir, Jimmy refuse.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Raquel Rodriguez et Shotzi vs Damage CTRL (Bayley &amp; Iyo Sky)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Raquel Rodriguez arrive \u00e0 faire un tomb\u00e9 sp\u00e9cial sur Bayley alors que Iyo Sky venait de sauter sur Rodriguez de la troisi\u00e8me corde.<\/p>\n\n\n\n<p><strong>Gagnantes : Shotzi et Raquel Rodriguez<\/strong><\/p>\n\n\n\n<p>&#8211; On nous remontre l&rsquo;interview de Seth Rollins suivie d&rsquo;une vid\u00e9o sur la carri\u00e8re d&rsquo;AJ Styles en vue de leur match \u00e0&nbsp;Night of Champions.<\/p>\n\n\n\n<p><strong>Ashante Adonis (accompagn\u00e9 de B-Fab &amp; Top Dolla) vs Cameron Grimes<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Cameron Grimes fait son Cave In sur Ashante Adonis pour la victoire par tomb\u00e9.<\/p>\n\n\n\n<p><strong>Gagnant : Cameron Grimes<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Cameron Grimes va commenter sur la sc\u00e8ne mais Baron Corbin l&rsquo;attaque par derri\u00e8re !<\/p>\n\n\n\n<p>&#8211; Bianca Belair fait son entr\u00e9e puis nous dit qu&rsquo;elle mettra sa ceinture en jeu face \u00e0 Asuka lors de Night of Champions ce samedi. Ce n&rsquo;est pas la m\u00eame Asuka qu&rsquo;\u00e0 WrestleMania, elle veut plus que son titre. Si Asuka voulait un rematch, elle n&rsquo;avait qu&rsquo;\u00e0 demander. Asuka a plut\u00f4t pr\u00e9f\u00e9r\u00e9 attendre d&rsquo;\u00eatre dans la ville natale de Bianca Belair pour lui faire un mist devant sa famille et amis. Mais elle ne va pas lui donner un rematch, elle lui donne un combat !<\/p>\n\n\n\n<p>La musique d&rsquo;Asuka retentit&#8230; elle arrive par derri\u00e8re pour attaquer Bianca Belair. Une bagarre \u00e9clate mais les officiels arrivent \u00e0 s\u00e9parer les deux catcheuses.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Les Street Profits sont \u00e0 la table des commentateurs pour le prochain match.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>LA Knight vs Rick Boogs<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, LA Knight fait son BFT sur Rick Boogs pour la victoire par tomb\u00e9.<\/p>\n\n\n\n<p><strong>Gagnant : LA Knight<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, LA Knight va parler aux Street Profits et leur dit qu&rsquo;il sait qu&rsquo;ils parlent mal de lui, ils vont bient\u00f4t se faire fumer.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&#8211; Une vid\u00e9o sur Alba Fyre et Isla Dawn est diffus\u00e9e.<\/p>\n\n\n\n<p><strong>Singles Match<\/strong><\/p>\n\n\n\n<p><strong>AJ Styles vs Karrion Kross (accompagn\u00e9 de Scarlett)<\/strong><\/p>\n\n\n\n<p>Pendant le match, Mia Yim vient s&rsquo;en prendre \u00e0 Scarlett qui arrive \u00e0 s&rsquo;enfuir.<\/p>\n\n\n\n<p>\u00c0 la fin du match, AJ Styles fait son Phenomenal Forearm sur Karrion Kross pour l&#8217;emporter par tomb\u00e9.<\/p>\n\n\n\n<p><strong>Gagnant : AJ Styles<\/strong><\/p>\n\n\n\n<p>&#8211; On retrouve AJ Styles dans la Gorilla Position et ils dit que \u00e7a peut \u00eatre Seth \u00ab\u00a0Freakin\u00a0\u00bb Rollins, il ne peut pas \u00eatre \u00ab\u00a0Ph\u00e9nom\u00e9nal\u00a0\u00bb. AJ Styles affirme qu&rsquo;il va gagner le titre World Heavyweight.<\/p>\n\n\n\n<p>&#8211; Les commentateurs font le tour de la carte de&nbsp;<a href=\"https:\/\/catch-newz.com\/wwe\/newz\/34989-carte-wwe-night-of-champions-2023\" target=\"_blank\" rel=\"noreferrer noopener\">Night of Champions qui a lieu ce samedi 27 mai<\/a>.<\/p>\n\n\n\n<p>&#8211; Une vid\u00e9o sur la rivalit\u00e9 entre Cody Rhodes et Brock Lesnar est diffus\u00e9e.<\/p>\n\n\n\n<p>&#8211; La semaine prochaine \u00e0 SmackDown, Roman Reigns va c\u00e9l\u00e9brer ses 1 000 jours de r\u00e8gne et nous aurons des matchs de qualification pour Money in the Bank : Zelina Vega vs Lacey Evans &#8211; Montez Ford vs LA Knight.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Kevin Owens et Sami Zayn font leur entr\u00e9e et nous souhaitent la bienvenue pour le KO Show. Kevin Owens nous pr\u00e9sente ses invit\u00e9s du soir mais Paul Heyman arrive pour dire que Roman Reigns ne vient pas quand ils le souhaitent. Les Usos coupent Paul Heyman et arrivent sur le ring.<\/p>\n\n\n\n<p>Kevin Owens dit \u00e0 Paul Heyman qu&rsquo;il a un petit spoiler, il savait que Romna Reigns n&rsquo;allait pas venir mais peu importe, il veut quand m\u00eame parler aux Usos.&nbsp;Il leur dit que Sami Zayn s&rsquo;inqui\u00e8te toujours des Usos. Lui ne comprend pas car Sami Zayn dit qu&rsquo;ils m\u00e9ritent mieux mais Owens s&rsquo;en fout.<\/p>\n\n\n\n<p>Les Usos peuvent reconnaitre ce qu&rsquo;il va dire : Sami Zayn a raison lorsqu&rsquo;il parle de la fa\u00e7on dont sont trait\u00e9s les Usos par Roman Reigns, ils m\u00e9ritent mieux. Roman Reigns peut s&rsquo;autoproclamer \u00ab\u00a0Head of the Table\u00a0\u00bb, mais il regarde en ce moment le \u00ab\u00a0Heart of the Table.\u00a0\u00bb Que serait la Bloodline sans eux ? Roman Reigns les utilise. Qu&rsquo;est-ce que \u00e7a leur fait de se regarder dans un miroir et de se dire qu&rsquo;ils sont pass\u00e9s de la plus grande \u00e9quipe de l&rsquo;histoire de la WWE aux larbins de Roman Reigns ?<strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>Jimmy Uso r\u00e9pond qu&rsquo;ils sont en face de la plus grande \u00e9quipe et lui, c&rsquo;est le&nbsp;Tribal Chief&nbsp;!<\/p>\n\n\n\n<p>La musique de Roman Reigns retentit et il arrive sur le ring. Il se met face \u00e0 Jey Uso et jette son micro au sol, il se met ensuite face \u00e0 Jimmy et jette \u00e9galement son micro au sol. Sami Zayn dit \u00e0 Roman Reigns que la Bloodline est finie et que tout \u00e7a est de sa faute&#8230; Roman Reigns s&rsquo;approche de Zayn mais Kevin Owens lui fait un Stunner ! <\/p>\n\n\n\n<p>Une bagarre \u00e9clate et Solo Sikoa vient aider la Bloodline. Roman Reigns finit par faire un Spear sur Sami Zayn.&nbsp;Jey Uso offre les ceintures par \u00e9quipe \u00e0 Solo Sikoa, Jimmy Uso quant \u00e0 lui h\u00e9site \u00e0 les donner \u00e0 Roman Reigns.&nbsp;Jey Uso lui prend les ceintures et les donne \u00e0 Roman Reigns. Le show se termine sur une c\u00e9l\u00e9bration de la Bloodline.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/26\/avant-gout-pour-le-wwe-friday-night-smackdown-du-26-mai-2023\/\" target=\"_blank\"><strong>Pour voir Smackdown, cliquez ici<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"w6mpnVUU33\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/26\/avant-gout-pour-le-wwe-friday-night-smackdown-du-26-mai-2023\/\">Vid\u00e9os et Programme pour le WWE Friday Night Smackdown du 26 Mai 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vid\u00e9os et Programme pour le WWE Friday Night Smackdown du 26 Mai 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/26\/avant-gout-pour-le-wwe-friday-night-smackdown-du-26-mai-2023\/embed\/#?secret=xGD7bX64aD#?secret=w6mpnVUU33\" data-secret=\"w6mpnVUU33\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE SmackDown Columbia, Caroline du Sud, 26 mai 2023 Les commentateurs sont Michael Cole et Wade Barrett. &#8211; Le WWE SmackDown d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue puis les catcheurs arrivent pour le premier match de la soir\u00e9e. Championnat des USA Sheamus (accompagn\u00e9 de Butch &amp; Ridge Holland) vs Austin Theory (c)&#8230;<\/p>\n","protected":false},"author":609,"featured_media":84339,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88,21,36,23],"tags":[],"ppma_author":[295],"class_list":["post-84337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-night-of-champions","category-resultats","category-smackdown","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=84337"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84337\/revisions"}],"predecessor-version":[{"id":84520,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84337\/revisions\/84520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/84339"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=84337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=84337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=84337"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=84337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}