{"id":84150,"date":"2023-05-22T22:27:30","date_gmt":"2023-05-23T02:27:30","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=84150"},"modified":"2023-05-22T22:31:04","modified_gmt":"2023-05-23T02:31:04","slug":"deuxieme-heure-de-raw-77","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/05\/22\/deuxieme-heure-de-raw-77\/","title":{"rendered":"Deuxi\u00e8me Heure de RAW"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=84151\">Pour la premi\u00e8re heure de RAW, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>&#8211; De retour, en coulisse, Byron Saxton demande \u00e0 Mustafa Ali ses commentaires sur son match \u00e0 Night of Champions contre Gunther. Ali dit que Saxton s&rsquo;attend surement \u00e0 des citations de positivit\u00e9, mais c&rsquo;est trop \u00e9norme. Il r\u00eavait \u00e0 ce match depuis qu&rsquo;il est un enfant. Il n&rsquo;a jamais eu la chance d&rsquo;\u00eatre proche d&rsquo;un titre si on regarde sa carri\u00e8re. Et ce samedi c&rsquo;est sa chance&#8230; Brock Lesnar d\u00e9barque et pousse la cam\u00e9ra. Lesnar dit que son moment est termin\u00e9.<\/p>\n\n\n\n<p>Brock Lesnar d\u00e9barque sur le ring et prend le micro. Lesnar demande en rigolant aux fans de quoi ils veulent parler. Malheureusement Cody Rhodes ne sera pas ici ce soir. Cody ne va pas affronter Brock Lesnar \u00e0 Night of Champions ce samedi non plus. Mais il ne faut pas s&rsquo;inqui\u00e9ter,\u00a0Brock Lesnar ne va pas nous laisser tomber. Il va lancer un Open Challenge pour n&rsquo;importe qui en coulisse. Il suffit de venir sur le ring et confronter Brock Lesnar. Lesnar attend.<\/p>\n\n\n\n<p>SURPRIRSE Cody Rhodes arrive avec une \u00e9charpe au bras sur le ring.\u00a0Les officiels veulent l&rsquo;arr\u00eater, mais Cody va quand m\u00eame sur le ring. Cody retire son \u00e9charpe et l&rsquo;affrontement \u00e9clate. Lesnar applique son Kimura Lock sur Cody ! Cody hurle de douleur, Lesnar d\u00e9cide finalement d&rsquo;arr\u00eater sa soumission. Lesnar donne un coup de pied sur le bras de Cody pour en ajouter et quitte le ring.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-medium-font-size\">Alpha Academy\u00a0(Chad Gable et Otis)\u00a0acc de Maxxine Dupri\u00a0vs Viking Raiders\u00a0(Erik et Ivar) acc de Valhalla<\/p>\n\n\n\n<p>En fin de match, Otis veut charger Ivar, mais Valhalla le sauve. Gable prend la tag, mais Erik le surprend avec un coup de genou. Dupri n&rsquo;est pas contente, mais Valhalla la chasse sur la rampe. Les Viking veulent faire leur finisher sur Gable, mais Gable repousse Ivar en bas du ring et fait un compte rapide \u00e0 Erik pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Alpha Academy<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Byron Saxton veut une mise \u00e0 jour au sujet de la sant\u00e9 de Cody Rhodes. Cody est en col\u00e8re contre Adam Pearce et demande \u00e0 tout le monde de partir.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Shinsuke Nakamura vs Finn Balor<\/strong><\/p>\n\n\n\n<p>En fin de match Nakamura se lance en Kinshasa, mais Balor le bloque avec un Double Stomp. Balor se lance en Coup de Gr\u00e2ce du coin, mais Nakamura l&rsquo;\u00e9vite et lui porte un coup de pied derri\u00e8re la t\u00eate. Priest tire Balor en bas du ring pour l&rsquo;aider, mais Nakamura commence \u00e0 rouer de coups Priest en ringside. Balor en profite pour faire un Drop Kick \u00e0 Nakamura contre la barricade. Balor enchaine avec son Coup de Gr\u00e2ce pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Finn Balor<\/strong><\/p>\n\n\n\n<p>&#8211; Les commentateurs annoncent\u00a0que Liv Morgan est bless\u00e9e \u00e0 l&rsquo;\u00e9paule\u00a0et de nouvelles championnes par \u00e9quipe seront couronn\u00e9es lundi prochain \u00e0 RAW.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-medium-font-size\"><strong>Raquel Rodriguez vs Sonya Deville\u00a0acc de Chelsea Green<\/strong><\/p>\n\n\n\n<p>En fin de match Rodriguez fait son ChokeSlam sur Deville pour l&#8217;emporter rapidement.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Raquel Rodriguez<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Deville et Green attaquent directement Raquel. Shotzi arrive sur le ring pour venir en aide \u00e0 Raquel et les chasser du ring.<\/p>\n\n\n\n<p>&#8211; En coulisse, un officiel explique \u00e0 Adam Pearce que Cody Rhodes ne veut parler \u00e0 personne. <\/p>\n\n\n\n<p>Trish Stratus arrive et dit qu&rsquo;elle s&rsquo;est lib\u00e9r\u00e9e pour la signature de contrat ce soir malgr\u00e9 son agenda charg\u00e9 (Elle vient de terminer Canada Got Tallents). Becky est vive en \u00e9motion, alors elle aimerait un r\u00e8glement sur l&rsquo;interdiction de contact pour ce soir. Pearce dit qu&rsquo;il pense que ce n&rsquo;est pas n\u00e9cessaire, alors non.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=84149\">Pour la suite de RAW, cliquez ici<\/a><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"Ilmb3lDjgH\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/22\/troisieme-heure-de-raw-73\/\">Troisi\u00e8me Heure de RAW<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Troisi\u00e8me Heure de RAW\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/22\/troisieme-heure-de-raw-73\/embed\/#?secret=WjtY6SYt1N#?secret=Ilmb3lDjgH\" data-secret=\"Ilmb3lDjgH\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; De retour, en coulisse, Byron Saxton demande \u00e0 Mustafa Ali ses commentaires sur son match \u00e0 Night of Champions contre Gunther. Ali dit que Saxton s&rsquo;attend surement \u00e0 des citations de positivit\u00e9, mais c&rsquo;est trop \u00e9norme. Il r\u00eavait \u00e0 ce match depuis qu&rsquo;il est un enfant. Il n&rsquo;a jamais eu la chance d&rsquo;\u00eatre proche&#8230;<\/p>\n","protected":false},"author":4,"featured_media":84172,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-84150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=84150"}],"version-history":[{"count":7,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84150\/revisions"}],"predecessor-version":[{"id":84182,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84150\/revisions\/84182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/84172"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=84150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=84150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=84150"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=84150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}