{"id":84035,"date":"2023-05-18T18:50:16","date_gmt":"2023-05-18T22:50:16","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=84035"},"modified":"2023-05-18T18:54:35","modified_gmt":"2023-05-18T22:54:35","slug":"wwe-aew-paul-heyman-vince-russo-billy-corgan-et-dautres-rendent-hommage-a-la-superstar-billy-graham","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/05\/18\/wwe-aew-paul-heyman-vince-russo-billy-corgan-et-dautres-rendent-hommage-a-la-superstar-billy-graham\/","title":{"rendered":"WWE, AEW, Paul Heyman, Vince Russo, Billy Corgan et d&rsquo;autres rendent hommage \u00e0 la \u00ab\u00a0superstar\u00a0\u00bb Billy Graham"},"content":{"rendered":"\n<p>Le monde de la lutte professionnelle rend hommage \u00e0 Billy Graham, membre du Hall of Famer de la WWE, d\u00e9c\u00e9d\u00e9&nbsp;mercredi&nbsp;soir \u00e0 l&rsquo;\u00e2ge de 79 ans.<\/p>\n\n\n\n<p>Les m\u00e9decins de Graham ont voulu le retirer du respirateur artificiel plus t\u00f4t dans la semaine, mais sa femme de longue date, Val\u00e9rie, a refus\u00e9.&nbsp;Graham avait fait face \u00e0 de nombreux probl\u00e8mes de sant\u00e9 au fil des ans et avait \u00e9t\u00e9 absent de chez lui, hospitalis\u00e9 ou dans un centre de r\u00e9adaptation, pendant 6 mois.&nbsp;L&rsquo;ancien champion de la WWE a subi une intervention chirurgicale d&rsquo;urgence le 10 mai en raison d&rsquo;une infection \u00e0 la hanche gauche et d&rsquo;une d\u00e9faillance d&rsquo;organe.&nbsp;Il \u00e9tait compl\u00e8tement sourd \u00e0 cause de l&rsquo;infection et souffrait de probl\u00e8mes r\u00e9naux, cardiaques et pulmonaires, de plaies au lit pendant des mois et de d\u00e9pression, selon sa femme.&nbsp;Le d\u00e9c\u00e8s de Graham a \u00e9t\u00e9 confirm\u00e9 hier soir par Ric Flair, Hall of Famer de la WWE.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>La WWE a publi\u00e9 une longue d\u00e9claration sur le d\u00e9c\u00e8s de Graham, que vous pouvez voir ci-dessous.<\/p>\n\n\n\n<p>Le pr\u00e9sident de la NWA, Billy Corgan, a publi\u00e9 une d\u00e9claration sur le d\u00e9c\u00e8s de Graham, \u00e9crivant sur Twitter : <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab La NWA est profond\u00e9ment attrist\u00e9e d&rsquo;apprendre le d\u00e9c\u00e8s de la l\u00e9gendaire superstar Billy Graham ;&nbsp;qui incarnait singuli\u00e8rement un esprit qui a chang\u00e9 \u00e0 jamais le sport et s&rsquo;est impos\u00e9 comme une figure transcendantale dans tous les m\u00e9dias.&nbsp;Nos condol\u00e9ances \u00e0 tous ceux qui l&rsquo;ont aim\u00e9 et v\u00e9n\u00e9r\u00e9.<\/p>\n<\/blockquote>\n\n\n\n<p>AEW a tweet\u00e9 un graphique \u00e0 la m\u00e9moire de Graham et a \u00e9crit: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00abAEW rejoint le monde de la lutte pour pleurer le d\u00e9c\u00e8s de la superstar Billy Graham.&nbsp;Nos pens\u00e9es vont \u00e0 sa famille, ses amis et ses fans. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Nick Aldis se souvenait de Graham comme \u00e9tant peut-\u00eatre le plus grand changeur de jeu de tous les temps.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0RIP Superstar.&nbsp;Probablement le plus grand changeur de jeu de tous les temps.&nbsp;Gr\u00e2ce \u00e0 Billy Graham, nous avons eu Hulk Hogan et Ric Flair, sans parler d&rsquo;innombrables autres personnes qui ont fait fortune en empruntant \u00e0 cet homme.&nbsp;Dites son nom et souvenez-vous de lui \u00bb, a-t-il \u00e9crit.<\/p>\n<\/blockquote>\n\n\n\n<p>Paul Heyman a \u00e9galement comment\u00e9 la fa\u00e7on dont \u00ab\u00a0Superstar\u00a0\u00bb a influenc\u00e9 l&rsquo;industrie.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00abAvant Billy Graham, les artistes de la WWWF \/ WWF \/ WWE \u00e9taient connus comme des lutteurs professionnels.&nbsp;Apr\u00e8s que Billy Graham ait laiss\u00e9 sa marque, Vincent Kennedy McMahon a d\u00e9cid\u00e9 que tout le monde serait une superstar de la WWE.&nbsp;Un RIP des plus sinc\u00e8res \u00e0 l&rsquo;homme de l&rsquo;heure, l&rsquo;homme au pouvoir, trop doux pour \u00eatre aigre&nbsp;!\u00a0\u00bb, a \u00e9crit Heyman.<\/p>\n<\/blockquote>\n\n\n\n<p>Le Temple de la renomm\u00e9e de la WWE, Jesse Ventura, a d\u00e9clar\u00e9 qu&rsquo;il n&rsquo;y aurait pas de \u00ab\u00a0The Body\u00a0\u00bb sans Graham.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Il n&rsquo;y aurait pas de Jesse &lsquo;The Body&rsquo; Ventura sans le succ\u00e8s sur le ring et le sens du spectacle avant-gardiste de la superstar Billy Graham.&nbsp;L&rsquo;un de mes souvenirs de lutte les plus fiers a \u00e9t\u00e9 d&rsquo;avoir l&rsquo;honneur d&rsquo;\u00eatre intronis\u00e9 dans la m\u00eame classe du Temple de la renomm\u00e9e de la WWE que Graham.&nbsp;Rest In Power Superstar \u00bb, a \u00e9crit Ventura.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Vince Russo a comment\u00e9 \u00e0 quel point Graham \u00e9tait en avance sur son temps.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00abIl n&rsquo;y avait aucun lutteur dans l&rsquo;HISTOIRE de l&rsquo;entreprise qui \u00e9tait si en avance sur son temps que\u00ab SuperStar \u00bbBilly Graham.&nbsp;Si vous n&rsquo;\u00e9tiez pas l\u00e0 pour le voir, vous avez vraiment rat\u00e9 quelque chose.&nbsp;Il l&rsquo;\u00e9tait, mec.&nbsp;Il l&rsquo;\u00e9tait \u00bb, a \u00e9crit Russo.<\/p>\n<\/blockquote>\n\n\n\n<p>Natalya a rendu hommage et a rappel\u00e9 comment son grand-p\u00e8re, le Temple de la renomm\u00e9e de la WWE Stu Hart, a toujours fait l&rsquo;\u00e9loge de Superstar.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab C&rsquo;est en 1970 que la superstar Billy Graham a \u00ab fait irruption dans le business \u00bb gr\u00e2ce \u00e0 la Stampede Wrestling.&nbsp;Il s&rsquo;est entra\u00een\u00e9 avec mon grand-p\u00e8re Stu au Dungeon apr\u00e8s avoir jou\u00e9 dans la LCF.&nbsp;Stu a toujours fait l&rsquo;\u00e9loge de Billy Graham, en particulier de son \u00e9thique de travail et de sa volont\u00e9 de r\u00e9ussir \u00bb, a-t-elle \u00e9crit.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Vous trouverez ci-dessous d&rsquo;autres hommages de WWE Hall of Famers, Superstars, d&rsquo;autres lutteurs et promotions, tels que The Iron Sheik, Bully Ray, Sean Waltman, Zelina Vega, Diamond Dallas Page, The Honky Tonk Man, Sgt.&nbsp;Slaughter, Frankie Kazarian, Marc Mero et Bryan Clark.&nbsp;La d\u00e9claration compl\u00e8te de la WWE se lit comme suit&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La WWE est attrist\u00e9e d&rsquo;apprendre que Billy Graham, membre du Temple de la renomm\u00e9e de la WWE, Billy Graham, est d\u00e9c\u00e9d\u00e9.<\/p>\n\n\n\n<p>Ancien champion de la WWE, le style de mode flashy de Graham, ses interviews exag\u00e9r\u00e9es et son physique de bodybuilder ont cr\u00e9\u00e9 l&rsquo;arch\u00e9type d&rsquo;une g\u00e9n\u00e9ration de superstars qui ont suivi ses traces.<\/p>\n\n\n\n<p>N\u00e9 en Arizona, Graham a d\u00e9velopp\u00e9 une passion pour le monde de la musculation et a cr\u00e9\u00e9 ses propres poids en ciment pour commencer \u00e0 construire son physique.&nbsp;Il s&rsquo;est entra\u00een\u00e9 avec tant de diligence qu&rsquo;il a finalement \u00e9t\u00e9 capable de faire un d\u00e9velopp\u00e9 couch\u00e9 de 605 livres, \u00e0 seulement 11 livres de moins que le record du monde.&nbsp;Le premier go\u00fbt de gloire de Graham est survenu lorsqu&rsquo;une de ses s\u00e9ances photo avec Arnold Schwarzenegger a \u00e9t\u00e9 pr\u00e9sent\u00e9e dans le magazine \u00ab\u00a0Muscle and Fitness\u00a0\u00bb de Joe Weider.<\/p>\n\n\n\n<p>Lorsque l&rsquo;homme n\u00e9 Eldridge Wayne Coleman est entr\u00e9 dans l&rsquo;industrie du divertissement sportif en 1970, il a chang\u00e9 son nom pour Billy Graham en r\u00e9f\u00e9rence \u00e0 l&rsquo;\u00e9vang\u00e9liste.&nbsp;Il a ajout\u00e9 le surnom de \u00ab\u00a0Superstar\u00a0\u00bb lorsqu&rsquo;il a rejoint l&rsquo;AWA en 1972. Avec une combinaison de capacit\u00e9 dans le ring et un physique de bodybuilder, il s&rsquo;est impos\u00e9 comme un pionnier du genre.&nbsp;Graham a \u00e9galement continu\u00e9 \u00e0 participer \u00e0 des comp\u00e9titions de musculation et d&rsquo;hommes forts et a remport\u00e9 des distinctions pour ses biceps sculpt\u00e9s et d\u00e9chiquet\u00e9s de 22 pouces.<\/p>\n\n\n\n<p>Graham a commenc\u00e9 \u00e0 imiter l&rsquo;ic\u00f4ne de la boxe Muhammad Ali dans ses interviews, inventant la ligne embl\u00e9matique, \u00ab\u00a0Je suis l&rsquo;homme de l&rsquo;heure, l&rsquo;homme avec le pouvoir, trop doux pour \u00eatre aigre!\u00a0\u00bb&nbsp;Aux c\u00f4t\u00e9s de son manager tout aussi extravagant, The Grand Wizard, Graham a jailli ce genre de prose po\u00e9tique chaque semaine \u00e0 la t\u00e9l\u00e9vision, utilisant son don de bavardage pour se faire une attraction au box-office qui vendrait toutes les ar\u00e8nes qu&rsquo;il organisait.<\/p>\n\n\n\n<p>Pour se d\u00e9marquer encore plus, Graham a teint ses cheveux et sa barbichette de diff\u00e9rentes couleurs, et a perfectionn\u00e9 un look distinctif qui comprenait des boucles d&rsquo;oreilles extravagantes, des t-shirts moulants et de longs collants teints par n\u0153uds color\u00e9s.&nbsp;Le m\u00e9lange de style exceptionnel, de corps sculpt\u00e9 et de domination dans le ring du WWE Hall of Famer a jet\u00e9 les bases de futures stars telles que Hulk Hogan, Ric Flair, Jesse Ventura, Scott Steiner et plus encore.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>La plus grande r\u00e9ussite de Graham \u00e0 la WWE est survenue le 30 avril 1977 lorsqu&rsquo;il a accompli l&rsquo;exploit presque impossible de renverser Bruno Sammartino de son perchoir de championnat de la WWE.&nbsp;La superstar a d\u00e9tenu le titre pendant pr\u00e8s d&rsquo;un an, d\u00e9fendant avec succ\u00e8s le prix le plus riche du divertissement sportif contre des ic\u00f4nes comme Dusty Rhodes, Gorilla Monsoon et le \u00ab\u00a0High Chief\u00a0\u00bb Peter Maivia avant d&rsquo;\u00eatre d\u00e9tr\u00f4n\u00e9 par Bob Backlund de mani\u00e8re controvers\u00e9e.<\/p>\n\n\n\n<p>En 1987, \u00e0 44 ans, Graham a pris sa retraite du ring et est devenu manager puis commentateur couleur.<\/p>\n\n\n\n<p>La \u00ab superstar \u00bb Billy Graham a \u00e9t\u00e9 intronis\u00e9e au Temple de la renomm\u00e9e de la WWE par Triple H en 2004. Deux ans plus tard, l&rsquo;histoire inspirante de Graham et son influence sur l&rsquo;industrie du divertissement sportif ont \u00e9t\u00e9 pr\u00e9sent\u00e9es dans le documentaire de la WWE, \u00ab 20 Years Too Soon : The &lsquo;Superstar &lsquo; L&rsquo;histoire de Billy Graham.<\/p>\n\n\n\n<p>La WWE pr\u00e9sente ses condol\u00e9ances \u00e0 la famille, aux amis et aux fans de Graham.<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le monde de la lutte professionnelle rend hommage \u00e0 Billy Graham, membre du Hall of Famer de la WWE, d\u00e9c\u00e9d\u00e9&nbsp;mercredi&nbsp;soir \u00e0 l&rsquo;\u00e2ge de 79 ans. Les m\u00e9decins de Graham ont voulu le retirer du respirateur artificiel plus t\u00f4t dans la semaine, mais sa femme de longue date, Val\u00e9rie, a refus\u00e9.&nbsp;Graham avait fait face \u00e0 de&#8230;<\/p>\n","protected":false},"author":665,"featured_media":84043,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,77,22,4,23],"tags":[],"ppma_author":[289],"class_list":["post-84035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-hall-of-fame","category-indy","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=84035"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84035\/revisions"}],"predecessor-version":[{"id":84045,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84035\/revisions\/84045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/84043"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=84035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=84035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=84035"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=84035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}