{"id":84029,"date":"2023-05-18T13:11:52","date_gmt":"2023-05-18T17:11:52","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=84029"},"modified":"2023-05-18T13:11:54","modified_gmt":"2023-05-18T17:11:54","slug":"sami-zayn-parle-de-lassension-de-cody-rhodes-a-la-wwe-depuis-son-arrive-de-la-aew-il-aurait-aime-ajoute-une-corde-a-son-arc","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/05\/18\/sami-zayn-parle-de-lassension-de-cody-rhodes-a-la-wwe-depuis-son-arrive-de-la-aew-il-aurait-aime-ajoute-une-corde-a-son-arc\/","title":{"rendered":"Sami Zayn parle de l&rsquo;assension de Cody Rhodes \u00e0 la WWE depuis son arriv\u00e9 de la AEW!  Il aurait aim\u00e9 ajout\u00e9 une corde \u00e0 son arc!"},"content":{"rendered":"\n<p>Sami Zayn donne son avis sur l&rsquo;ascension de Cody Rhodes \u00e0 la WWE.<\/p>\n\n\n\n<p>Le champion actuel du tag a parl\u00e9 du cauchemar am\u00e9ricain lors d&rsquo;une r\u00e9cente apparition sur le podcast <a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/mark-andrews-my-love-letter-to-wrestling\/id1567396634\" target=\"_blank\" rel=\"noreferrer noopener\">My Love Letter To Wrestling<\/a> avec l&rsquo;h\u00f4te Mark Andrews. <\/p>\n\n\n\n<p>Zayn commence par parler du retour de Cody \u00e0 la WWE \u00e0 WrestleMania 38 et comment sa malheureuse blessure \u00e0 l&rsquo;\u00e9t\u00e9 2022 n&rsquo;a fait que pousser les fans \u00e0 l&rsquo;encourager davantage.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Il y avait deux parties. Premi\u00e8rement, Cody avait vraiment beaucoup de respect et d&rsquo;\u00e9quit\u00e9 avec le public, en particulier en revenant de cette blessure, et ils l&rsquo;aimaient tout simplement. Donc, ce n&rsquo;\u00e9tait pas la m\u00eame chose que le retour de Batista, qu&rsquo;ils n&rsquo;avaient pas vu depuis des ann\u00e9es \u00e0 ce moment-l\u00e0, et ils le consid\u00e9raient comme un employ\u00e9 \u00e0 temps partiel. Vous avez touch\u00e9 quelque chose, qui \u00e9tait la confiance. <\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00c0 ce stade, le public avait appris \u00e0 faire confiance \u00e0 l&rsquo;endroit o\u00f9 se d\u00e9roulait l&rsquo;histoire. M\u00eame s&rsquo;ils \u00e9taient sceptiques et m\u00eame s&rsquo;il y avait des gens qui disaient: \u00ab\u00a0Non, je veux vraiment voir Sami et Roman ou ils devraient aller dans cette direction.\u00a0\u00bb Au cours des huit mois ou quoi que ce soit avant ce point, ils ont appris \u00e0 \u2026 m\u00eame si ce n&rsquo;\u00e9tait pas exactement ce qu&rsquo;ils voulaient, nous avons gagn\u00e9 suffisamment de confiance pour qu&rsquo;ils se disent : &lsquo;<em>Eh bien, d&rsquo;accord, voyons o\u00f9 \u00e7a m\u00e8ne.<\/em>&lsquo;<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Zayn \u00e9voquerait ensuite la d\u00e9faite de Cody face \u00e0 Roman Reigns \u00e0 WrestleMania 39, une d\u00e9faite qui continue de choquer l&rsquo;univers de la WWE. Il dit que regarder Cody \u00ab\u00a0mettre une corde \u00e0 son arc\u00a0\u00bb durant son voyage aurait \u00e9t\u00e9 formidable, mais comprend qu&rsquo;il y a une histoire plus longue \u00e0 raconter.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Je pense que, strictement du point de vue de l&rsquo;histoire, il aurait \u00e9t\u00e9 formidable de voir Cody mettre une corde \u00e0 son arc, mais il est toujours en construction. C&rsquo;est la chose que les gens, c&rsquo;est si difficile \u00e0 comprendre \u00e0 propos de la WWE. Nous construisons ces choses qui semblent \u00eatre ces points culminants, mais il y a toujours une \u00e9mission t\u00e9l\u00e9vis\u00e9e la semaine prochaine. Nous regardons ces choses \u00e0 travers le prisme des \u00e9missions de t\u00e9l\u00e9vision et des finales de saison. M\u00eame moi, \u00ab\u00a0Ouais, bien s\u00fbr, Cody doit gagner\u00a0\u00bb, mais vous devez conserver cette confiance. Je suis un fan, je suis investi et j&rsquo;esp\u00e8re qu&rsquo;ils paieront correctement au bon moment et voyons o\u00f9 cela va.<\/p>\n<\/blockquote>\n\n\n\n<p>Zayn et Kevin Owens d\u00e9fendront le championnat par \u00e9quipe de la WWE contre Solo Sikoa et le champion universel incontest\u00e9 Roman Reigns lors du prochain \u00e9v\u00e9nement en direct Night Of Champions le 27 mai. Vous pouvez consulter la derni\u00e8re carte du spectacle ici.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.jdx.info\/lutte\/2023\/05\/15\/carte-et-info-pour-le-wwe-night-of-champions-2023\/\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sami Zayn donne son avis sur l&rsquo;ascension de Cody Rhodes \u00e0 la WWE. Le champion actuel du tag a parl\u00e9 du cauchemar am\u00e9ricain lors d&rsquo;une r\u00e9cente apparition sur le podcast My Love Letter To Wrestling avec l&rsquo;h\u00f4te Mark Andrews. Zayn commence par parler du retour de Cody \u00e0 la WWE \u00e0 WrestleMania 38 et comment&#8230;<\/p>\n","protected":false},"author":609,"featured_media":84030,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,88,4,23],"tags":[],"ppma_author":[295],"class_list":["post-84029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-night-of-champions","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=84029"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84029\/revisions"}],"predecessor-version":[{"id":84031,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/84029\/revisions\/84031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/84030"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=84029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=84029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=84029"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=84029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}