{"id":83748,"date":"2023-05-10T14:19:00","date_gmt":"2023-05-10T18:19:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=83748"},"modified":"2023-05-11T18:30:33","modified_gmt":"2023-05-11T22:30:33","slug":"les-matchs-du-tournoi-pour-le-titre-mondial-des-poids-lourds-de-la-wwe-devoiles-pour-smackdown","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/05\/10\/les-matchs-du-tournoi-pour-le-titre-mondial-des-poids-lourds-de-la-wwe-devoiles-pour-smackdown\/","title":{"rendered":"Les matchs du tournoi pour le titre mondial des poids lourds de la WWE d\u00e9voil\u00e9s pour SmackDown"},"content":{"rendered":"\n<p>La WWE a officiellement annonc\u00e9 que les matchs Triple Threat de la marque bleue pour le tournoi du titre poids lourd mondial de la WWE,  seront diffus\u00e9s vendredi \u00e0 SmackDown.<\/p>\n\n\n\n<p>WWE Hall of Famers Edge et Rey Mysterio enfermeront AJ Styles, tandis que Bobby Lashley contre Sheamus contre le champion des \u00c9tats-Unis de la WWE Austin Theory aura \u00e9galement lieu.<\/p>\n\n\n\n<p>Les vainqueurs de ces deux matchs se rencontreront lors de l&rsquo;\u00e9v\u00e9nement principal de SmackDown de vendredi.\u00a0Le vainqueur de ce match affrontera ensuite Seth Rollins lors de la WWE Night of Champions le samedi 27 mai en Arabie Saoudite pour couronner le nouveau WWE World Heavyweight Champion.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>L&rsquo;\u00e9v\u00e9nement principal RAW de lundi a vu Rollins battre Finn Balor pour assurer sa place \u00e0 Night of Champions.&nbsp;Rollins a remport\u00e9 une triple menace plus t\u00f4t dans la nuit contre Shinsuke Nakamura et Damian Priest, tandis que Balor a remport\u00e9 une triple menace contre Cody Rhodes et The Miz.<\/p>\n\n\n\n<p>Le nouveau champion du monde des poids lourds de la WWE sera exclusif \u00e0 la marque RAW en raison du fait que SmackDown a r\u00e9cup\u00e9r\u00e9 le champion universel incontest\u00e9 de la WWE, Roman Reigns, lors du rep\u00eachage de la WWE.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La WWE a officiellement annonc\u00e9 que les matchs Triple Threat de la marque bleue pour le tournoi du titre poids lourd mondial de la WWE, seront diffus\u00e9s vendredi \u00e0 SmackDown. WWE Hall of Famers Edge et Rey Mysterio enfermeront AJ Styles, tandis que Bobby Lashley contre Sheamus contre le champion des \u00c9tats-Unis de la WWE&#8230;<\/p>\n","protected":false},"author":665,"featured_media":83771,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88,4,36,23],"tags":[],"ppma_author":[289],"class_list":["post-83748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-night-of-champions","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/83748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=83748"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/83748\/revisions"}],"predecessor-version":[{"id":83773,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/83748\/revisions\/83773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/83771"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=83748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=83748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=83748"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=83748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}