{"id":83486,"date":"2023-05-02T21:34:00","date_gmt":"2023-05-03T01:34:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=83486"},"modified":"2023-05-08T09:44:57","modified_gmt":"2023-05-08T13:44:57","slug":"resultats-et-video-pour-le-wwe-nxt-du-2-mai-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/05\/02\/resultats-et-video-pour-le-wwe-nxt-du-2-mai-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 2 mai 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/02\/avant-gout-pour-le-wwe-nxt-du-2-mai-2023-lapres-draft-wwe\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir ce NXT, cliquez ici<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE NXT, Orlando, Floride, 2 mai 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Booker T.<\/p>\n\n\n\n<p>&#8211; Ce soir, c&rsquo;est WWE NXT. Le show d\u00e9marre avec une vid\u00e9o r\u00e9capitulative&nbsp;sur les \u00e9changes du WWE Draft de NXT. <\/p>\n\n\n\n<p>&#8211; Wes Lee arrive ensuite le premier sur le ring.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat Nord Am\u00e9ricain<\/strong><\/p>\n\n\n\n<p><strong>Wes Lee \u00a9&nbsp;<em>accompagn\u00e9 de Tyler Bate<\/em>&nbsp;vs Drew Gulak&nbsp;<em>accompagn\u00e9 de Charlie Dempsey<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Gulak sort du ring pour prendre une pause. Lee se lance en saut suicide sur Gulak et le ram\u00e8ne sur le ring, mais Dempsey lui tire la jambe pour le ramener en bas du ring. Bate intervient et frappe Dempsey en plein visage. Lee repousse Gulak avec un coup et lui fait son Cardiac Kick pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Wes Lee<\/strong><\/p>\n\n\n\n<p>&#8211; En vid\u00e9o, on retrouve Isla Dawn et Alba Fyre. Fyre dit que le futur est incertain. Elles se laissent guider et le futur m\u00e8ne \u00e0 SmackDown. Dawn dit que c&rsquo;est leur derni\u00e8re soir\u00e9e \u00e0 NXT. Fyre dit que ce soir elles vont \u00e9teindre l&rsquo;\u00e9cran de Chance et Carter.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211;<strong>&nbsp;Trick Williams<\/strong>&nbsp;est sur le ring avec un micro. Williams dit qu&rsquo;on a tous vu ce qui est arriv\u00e9 la semaine derni\u00e8re avec Bron Breakker. Breakker a envoy\u00e9 son fr\u00e8re \u00e0 l&rsquo;h\u00f4pital, mais son fr\u00e8re est un combattant. Il le sait depuis leur passage ensemble au lyc\u00e9e. Hayes est son fr\u00e8re et il va toujours le d\u00e9fendre et ils seront toujours ici !<\/p>\n\n\n\n<p> Williams dit qu&rsquo;on sait que Hayes ne rate jamais, mais lorsque \u00e7a arrive il est l\u00e0 pour attraper le rebond. Bron Breakker arrive et dit qu&rsquo;on sait qui est le dur \u00e0 cuire chez les deux. Il a fait un Spear \u00e0 Williams et il est encore ici,&nbsp;il a fait un Spear \u00e0 Hayes et Hayes est \u00e0 l&rsquo;h\u00f4pital. Alors Battleground sera plus facile qu&rsquo;il pensait.&nbsp;Williams demande s&rsquo;il accepte vraiment le challenge de Hayes pour Battleground. <\/p>\n\n\n\n<p>Breakker dit qu&rsquo;il ne le fait pas pour les fans. Il n&rsquo;aime pas voir Hayes avec le titre et en prime il pourra l&rsquo;humilier devant sa famille et ses amis. Alors Williams peut aller transmettre le message. Williams dit que Hayes surveille d\u00e9j\u00e0 le show par la t\u00e9l\u00e9vision. La semaine derni\u00e8re, Breakker l&rsquo;a aussi attaqu\u00e9 dans le dos, alors il veut r\u00e9gler \u00e7a comme des hommes. Breakker dit qu&rsquo;il d\u00e9testerait envoyer Williams \u00e0 l&rsquo;h\u00f4pital. Ce n&rsquo;est pas important ce que Williams ou les fans veulent. C&rsquo;est lui qui d\u00e9cide, ils vont le faire la semaine prochaine dans un match preview de Battleground lorsqu&rsquo;il va le briser en deux.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie demande \u00e0 JD McDonagh ses commentaires pour son dernier match \u00e0 NXT. McDonagh dit qu&rsquo;il a attendu 21 ans pour \u00eatre McDonRAW. Noam Dar arrive et dit qu&rsquo;il a besoin d&rsquo;une faveur au nom de leur pass\u00e9. Il veut voir Dar briser le genou de Dragon Lee pour que Lee reste loin de sa coupe. McDonagh dit que Dar devrait rester loin de lui sinon il va amener la coupe avec lui \u00e0 RAW.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Gigi Dolin vs Jacy Jayne<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Dolin cogne la t\u00eate de Jayne contre la marche d&rsquo;acier et la ram\u00e8ne sur le ring, mais Jayne lui tire le bras contre le coin. Jayne enchaine avec un Round Kick pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnante : Jacy Jayne<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Jayne poursuit l&rsquo;attaque sur Dolin devant le fr\u00e8re de Dolin en ringside. Les officiels arrivent pour l&rsquo;arr\u00eater.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Axiom vs Scrypts<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Axiom bloque une charge de Scrypts et lui porte un coup de genou. Axiom enchaine avec son Golden Ratio, mais Scrypts l&rsquo;\u00e9vite et lui fait un Cross Body. Scrypts se lance du coin, mais Axiom le bloque avec un coup de pied. Axiom enchaine avec son Golden Ratio pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Axiom<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Axiom c\u00e9l\u00e8bre sa victoire et il d\u00e9cide d&rsquo;aider Scrypts \u00e0 se relever, mais Scrypts le frappe. Axiom le frappe \u00e0 son tour et d\u00e9masque Scrypts pour lui faire un Superkick (et d\u00e9voiler officiellement que c&rsquo;est Reggie).<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de plus t\u00f4t au bar de Fallon Henley. Brooks Jensen dit qu&rsquo;il veut s&rsquo;excuser. Henley dit qu&rsquo;il peut arr\u00eater de s&rsquo;excuser. Jensen dit qu&rsquo;il doit au moins dire merci pour le sauver. Josh Briggs dit qu&rsquo;il le remercie pour la Clothesline. Deux femmes arrivent et invitent Jensen pour boire un verre, mais Jensen refuse. Henley le f\u00e9licite pour avoir appris la le\u00e7on.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Dragon Lee vs JD McDonagh<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, McDonagh veut faire son Devil Inside, mais Lee le renverse avec un Canadian Destroyer. McDonagh roule en bas du ring, Lee va le chercher, mais Noam Dar veut le frapper, Lee \u00e9vite le coup et le frappe. McDonagh attend Lee avec un coup lorsqu&rsquo;il arrive sur le ring. McDonagh enchaine avec son Devil Inside pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : JD McDonagh<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Dragon Lee est furieuse et pourchasse Noam Dar en coulisse.<\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Kayden Carter et Katana Chance. Chance dit que ce n&rsquo;est jamais arriv\u00e9 de voir une \u00e9quipe de RAW contre une \u00e9quipe de SmackDown pour les titres par \u00e9quipe de NXT. Elles ont le plus long r\u00e8gne de NXT, c&rsquo;est dans la poche pour ce soir.<\/p>\n\n\n\n<p>&#8211; Le Schism regarde une vid\u00e9o sur l&rsquo;entrainement de Joe Coffey. Joe Gacy dit que Coffey est impressionnant, mais il va endurer toute la douleur pour le Schism et prendre la victoire. Ava dit \u00e0 Gacy de gagner pour eux et ensuite faire quelque chose pour lui.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur les derni\u00e8res attaques myst\u00e8re sur Nikkita Lyons, Wendy Choo et Sol Ruca.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Joe Gacy&nbsp;<em>accompagn\u00e9 du Schism<\/em>&nbsp;vs Joe Coffey&nbsp;<em>accompagn\u00e9 de Gallus<\/em><\/strong><br><em>Si Joe Gacy gagne, ils auront une chance pour les titres par \u00e9quipe.<\/em><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Coffey arrive \u00e0 faire sa Clothesline sur Gacy et le couvre, mais Fowler met le pied de Gacy sur un c\u00e2ble. L&rsquo;affrontement \u00e9clate entre les deux clans en ringside. Ava joue un faux coup de poing de Coffey pour causer une distraction. Gacy en profite pour faire sa Handspring Clothesline sur Coffey pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Joe Gacy<\/strong><\/p>\n\n\n\n<p>&#8211; En coulisse, Dani Palmer se fait motiver au t\u00e9l\u00e9phone.<\/p>\n\n\n\n<p>&#8211; Dans une vid\u00e9o plus t\u00f4t, Eddy Thorpe se fait poser des questions sur ses entrainements. Thorpe dit qu&rsquo;il travaille sur ses d\u00e9placements lat\u00e9raux. Damon Kemp arrive et lui dit de ramasser ses d\u00e9chets comme Thorpe est le nouveau. Thorpe dit qu&rsquo;il est bien dr\u00f4le&#8230; Kemp dit que la blague est Thorpe qui pense rivaliser contre lui sur le ring.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Dani Palmer vs Tatum Paxley<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Palmer fait une Slam \u00e0 Paxley et enchaine avec un Frog Splash du coin pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnante : Dani Palmer<\/strong><\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve les \u00e9tudiants de Chase U. Thea Hail dit qu&rsquo;elle ne comprend pas pourquoi Andre Chase est en retard pour la classe. Elle re\u00e7oit un SMS de Chase disant qu&rsquo;il sera absent \u00e0 cause de son match contre Breakker. Hail demande ce qu&rsquo;ils peuvent faire. Duke Hudson prend la parole et dit qu&rsquo;il va enseigner pour aujourd&rsquo;hui. Hudson commence une formation sur un WWE Draft, mais un \u00e9tudiant lui demande ce qui arrive avec le pop quiz de pr\u00e9vu.&nbsp;Hudson fait d\u00e9chirer les quiz et nomme l&rsquo;Universit\u00e9 Duke.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Von Wagner et Robert Stone. Wagner pr\u00e9sente des photos de sa jeunesse \u00e0 Stone. Stone pose des questions sur une photo, mais Wagner refuse de r\u00e9pondre \u00e0 ses questions.&nbsp;Stone dit que Wagner est un agent libre du Draft, il pourrait \u00eatre appel\u00e9 n&rsquo;importe quand, il veut en savoir plus sur cette photo&nbsp;(une photo de Wagner comme b\u00e9b\u00e9 avec une cicatrice \u00e0 la t\u00eate).<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat F\u00e9minin par \u00c9quipe NXT<\/strong><\/p>\n\n\n\n<p><strong>Katana Chance et Kayden Carter vs Isla Dawn et Alba Fyre (c)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Chance prend la tag pour pr\u00e9parer leur finisher \u00e0 deux. Dawn veut intervenir, mais Chance se lance en Cross Body sur Dawn. Fyre bloque une charge de Chance et utilise le corps de Chance pour frapper Carter. Dawn et Fyre font ensuite leur Flapjack \u00e0 deux pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnantes : Isla Dawn et Alba Fyre (les titres par \u00e9quipe iront \u00e0 SmackDown)<\/strong><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Dijak. Dijak dit qu&rsquo;il avait avis\u00e9 Ilja Dragunov de ne pas venir au show, alors il lui a \u00e9cras\u00e9 les c\u00f4tes. Maintenant la semaine il veut en finir pour de bon avec Dragunov.<\/p>\n\n\n\n<p>&#8211; Sur le parking, Trick Williams croise Apollo Crews et le f\u00e9licite sur son transfert \u00e0 RAW. Crews dit qu&rsquo;avant d&rsquo;aller \u00e0 RAW il doit lui dire qu&rsquo;il voit beaucoup de potentiel chez Williams. Hayes a la lumi\u00e8re qu&rsquo;il m\u00e9rite, mais Williams m\u00e9rite aussi la lumi\u00e8re. Il doit continuer de travailler et il sera le prochain \u00e0 avoir l&rsquo;appel pour RAW ou SmackDown. Williams le remercie.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; La championne<strong>&nbsp;Indi Hartwell<\/strong>&nbsp;est sur le ring en b\u00e9quilles. Indi Hartwell dit qu&rsquo;\u00e0 23 ans elle arrivait \u00e0 NXT avec un r\u00eave car elle \u00e9tait une fan de NXT noir et or avec Bayley, Asuka et les autres. Des femmes qui ont aid\u00e9 \u00e0 construire le titre f\u00e9minin de NXT comme un championnat important. Personne ne croyait possible son r\u00eave de devenir championne jusqu&rsquo;au moment o\u00f9 elle a trouv\u00e9 The Way. Une famille avec Johnny, Candice et Sexy Dexy. Elle a fond\u00e9 un lien avec cette famille et les fans. Elle s&rsquo;est mari\u00e9e sur le ring, un mariage WWE sans interruption, elle ne pouvait pas le croire. Comme remporter le titre \u00e0 Stand and Deliver. Beaucoup de personnes veulent dire qu&rsquo;ils sont un champion qui d\u00e9fend son titre. Elle \u00e9tait dans le bureau du m\u00e9decin et elle ne pouvait pas laisser son r\u00e8gne de championnat se terminer au bureau du m\u00e9decin.<\/p>\n\n\n\n<p>Hartwell dit qu&rsquo;ensuite elle a \u00e9t\u00e9 \u00e9chang\u00e9 \u00e0 RAW.&nbsp;Elle ne peut toujours pas le croire, RAW sera sa nouvelle maison \u00e0 partir de lundi. Mais pr\u00e9sentement NXT et le titre sont les plus importants. Alors d\u00e8s la semaine prochaine il y aura un tournoi pour le titre f\u00e9minin avec la grande finale \u00e0 Battleground.&nbsp;Bonne chance aux participantes. Elle doit pas pleurer car c&rsquo;est termin\u00e9, mais bien sourire car c&rsquo;est arriv\u00e9. Hartwell embrasse le titre et le d\u00e9pose au sol.<\/p>\n\n\n\n<p>Hartwell dit que maintenant elle doit trouver une fa\u00e7on de sortir du ring. Dexter Lumis sort de sous le ring ! Dexter Lumis prend Indi dans ses bras et l&rsquo;am\u00e8ne avec lui en coulisse. Tiffany Stratton et Cora Jade arrivent sur le ring pour se battre pour prendre le titre. D&rsquo;autres catcheuses arrivent et l&rsquo;affrontement \u00e9clate entre tout le monde. Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-large-font-size\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/02\/avant-gout-pour-le-wwe-nxt-du-2-mai-2023-lapres-draft-wwe\/\" target=\"_blank\"><strong>Pour voir ce NXT, cliquez ici<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"BUnddrEJ2G\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/02\/avant-gout-pour-le-wwe-nxt-du-2-mai-2023-lapres-draft-wwe\/\">Vid\u00e9o et Programme pour le WWE NXT du 2 Mai 2023! L&rsquo;apr\u00e8s Draft WWE!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vid\u00e9o et Programme pour le WWE NXT du 2 Mai 2023! L&rsquo;apr\u00e8s Draft WWE!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/05\/02\/avant-gout-pour-le-wwe-nxt-du-2-mai-2023-lapres-draft-wwe\/embed\/#?secret=48Sn5xqVXi#?secret=BUnddrEJ2G\" data-secret=\"BUnddrEJ2G\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE NXT, Orlando, Floride, 2 mai 2023 Les commentateurs sont Vic Joseph et Booker T. &#8211; Ce soir, c&rsquo;est WWE NXT. Le show d\u00e9marre avec une vid\u00e9o r\u00e9capitulative&nbsp;sur les \u00e9changes du WWE Draft de NXT. &#8211; Wes Lee arrive ensuite le premier sur le ring. Championnat Nord Am\u00e9ricain Wes Lee \u00a9&nbsp;accompagn\u00e9 de Tyler Bate&nbsp;vs Drew&#8230;<\/p>\n","protected":false},"author":609,"featured_media":83487,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,21,23],"tags":[],"ppma_author":[295],"class_list":["post-83486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nxt","category-resultats","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/83486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=83486"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/83486\/revisions"}],"predecessor-version":[{"id":83609,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/83486\/revisions\/83609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/83487"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=83486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=83486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=83486"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=83486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}