{"id":83066,"date":"2023-04-22T04:53:00","date_gmt":"2023-04-22T08:53:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=83066"},"modified":"2023-04-22T16:58:24","modified_gmt":"2023-04-22T20:58:24","slug":"la-knight-veut-la-place-de-roman-reigns","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/04\/22\/la-knight-veut-la-place-de-roman-reigns\/","title":{"rendered":"LA Knight veut la place de Roman Reigns!"},"content":{"rendered":"\n<p>Comme depuis sont arriv\u00e9 \u00e0 la NXT puis \u00e0 la WWE, LA Knight vise toujours l&rsquo;or.<\/p>\n\n\n\n<p>Lors d&rsquo;une apparition sur \u00ab\u00a0KTAL NBC 6\u00a0\u00bb, Knight est revenu sur son d\u00e9sir de devenir champion.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00abNon seulement ils veulent que je devienne champion du monde bient\u00f4t, mais je veux aussi devenir champion Universel de la WWE plus t\u00f4t que tard.\u00bb<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Il continue en expliquant son Dream Match :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00abLes matchs de r\u00eave, vous pensez aux gens du pass\u00e9 qui ne sont plus l\u00e0. Il y en a quelques-uns. Tout le monde en parle \u00e0 nouveau, le champion Universel incontest\u00e9 de la WWE, cela me fait penser \u00e0 Roman Reigns. M\u00eame Gunther, avec le championnat intercontinental. Austin Theory pour le championnat des \u00c9tats-Unis. N&rsquo;importe lequel de ces gars, \u00e0 qui je pourrais prendre un morceau d&rsquo;or, ce serait le match de mes r\u00eaves.\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p>Comme vous le savez, LA Knight s\u2019est r\u00e9cemment inclin\u00e9 face \u00e0 Xavier Wood ce qui ne l&rsquo;a pas fait monter vers le haut pour le moment. Malgr\u00e9 qu\u2019il aimerait \u00eatre sur la route d\u2019un titre, il est pour l\u2019instant un peu loin de cet objectif comme vous l&rsquo;aurez devin\u00e9. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme depuis sont arriv\u00e9 \u00e0 la NXT puis \u00e0 la WWE, LA Knight vise toujours l&rsquo;or. Lors d&rsquo;une apparition sur \u00ab\u00a0KTAL NBC 6\u00a0\u00bb, Knight est revenu sur son d\u00e9sir de devenir champion. \u00abNon seulement ils veulent que je devienne champion du monde bient\u00f4t, mais je veux aussi devenir champion Universel de la WWE plus t\u00f4t&#8230;<\/p>\n","protected":false},"author":2,"featured_media":83068,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[287],"class_list":["post-83066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/83066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=83066"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/83066\/revisions"}],"predecessor-version":[{"id":83069,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/83066\/revisions\/83069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/83068"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=83066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=83066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=83066"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=83066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}