{"id":82989,"date":"2023-04-20T01:22:00","date_gmt":"2023-04-20T05:22:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=82989"},"modified":"2023-04-20T12:40:50","modified_gmt":"2023-04-20T16:40:50","slug":"plusieurs-superstars-craignent-pour-leur-job-a-la-wwe-des-nouvelles-de-robert-roode-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/04\/20\/plusieurs-superstars-craignent-pour-leur-job-a-la-wwe-des-nouvelles-de-robert-roode-et-plus\/","title":{"rendered":"Plusieurs Superstars craignent pour leur job \u00e0 la WWE! \/ Des nouvelles de Robert Roode et plus!"},"content":{"rendered":"\n<p>Robert Roode est absent des rings depuis 10 mois, un peu plus d&rsquo;un an pour les shows t\u00e9l\u00e9vis\u00e9s.\u00a0Il s&rsquo;est fait op\u00e9rer en fin d&rsquo;ann\u00e9e 2022\u00a0et son retour n&rsquo;est pas pour maintenant.<\/p>\n\n\n\n<p>D&rsquo;apr\u00e8s les informations de Fightful,\u00a0le retour de Robert Roode ne serait pas pas pr\u00e9vu pour bient\u00f4t.\u00a0Il se dit en effet qu&rsquo;il va rester absent pendant encore un certain temps. La date de son retour n&rsquo;est pas connue \u00e0 l&rsquo;heure actuelle.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Depuis quelques semaines,\u00a0certains catcheurs et catcheuses craignent pour leur place \u00e0 la WWE selon le PWInsider.<\/p>\n\n\n\n<p>Selon le site sp\u00e9cialis\u00e9 dans le catch, une l\u00e9g\u00e8re \u00ab\u00a0parano\u00efa\u00a0\u00bb s&rsquo;est install\u00e9e parmi quelques Superstars, surtout aupr\u00e8s de celles qui ont \u00e9t\u00e9 ramen\u00e9es par Triple H depuis sa prise au pouvoir durant l&rsquo;\u00e9t\u00e9 2022. <\/p>\n\n\n\n<p>Avec le retour de Vince McMahon et le rachat de la compagnie,\u00a0ces personnes ont peur d&rsquo;\u00eatre d\u00e9plac\u00e9es vers le bas de la carte ou encore pire : d&rsquo;\u00eatre renvoy\u00e9es si une prochaine vague de licenciements touche les Superstars, comme il arrive tr\u00e8s souvent \u00e0 chaque ann\u00e9e apr\u00e8s WrestleMania.<\/p>\n\n\n\n<p>Le PWInsider a pu s&rsquo;entretenir avec des personnes de l&rsquo;\u00e9quipe cr\u00e9ative et elles affirment n&rsquo;avoir pas re\u00e7u de consignes \u00e0 ce sujet. Toutefois, \u00e7a n&#8217;emp\u00eache pas certains talents d&rsquo;avoir quelques craintes.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Robert Roode est absent des rings depuis 10 mois, un peu plus d&rsquo;un an pour les shows t\u00e9l\u00e9vis\u00e9s.\u00a0Il s&rsquo;est fait op\u00e9rer en fin d&rsquo;ann\u00e9e 2022\u00a0et son retour n&rsquo;est pas pour maintenant. D&rsquo;apr\u00e8s les informations de Fightful,\u00a0le retour de Robert Roode ne serait pas pas pr\u00e9vu pour bient\u00f4t.\u00a0Il se dit en effet qu&rsquo;il va rester absent&#8230;<\/p>\n","protected":false},"author":4,"featured_media":82990,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[292],"class_list":["post-82989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=82989"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82989\/revisions"}],"predecessor-version":[{"id":82991,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82989\/revisions\/82991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/82990"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=82989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=82989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=82989"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=82989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}