{"id":82848,"date":"2023-04-17T12:15:18","date_gmt":"2023-04-17T16:15:18","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=82848"},"modified":"2023-04-17T12:15:21","modified_gmt":"2023-04-17T16:15:21","slug":"impact-et-la-njpw-annonce-le-multiverse-united-2","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/04\/17\/impact-et-la-njpw-annonce-le-multiverse-united-2\/","title":{"rendered":"Impact et la NJPW annonce le Multiverse United 2!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Impact Wrestling et NJPW ont d\u00e9j\u00e0 annonc\u00e9 le deuxi\u00e8me \u00e9v\u00e9nement Multiverse United. Impact x NJPW \u00ab\u00a0Multiverse United 2: Pour qui sonne le glas\u00a0\u00bb aura lieu le dimanche 20 ao\u00fbt au 2300 Arena de Philadelphie, Pennsylvanie.<\/p>\n\n\n\n<p>Multiverse United 2 sera diffus\u00e9 en direct sur FITE TV. Les d\u00e9tails sur les billets seront annonc\u00e9s dans les prochaines semaines. Bien s\u00fbre nous vous passerons des liens pour le voir en direct ou en reprise au moment venu. <\/p>\n\n\n\n<p>Comme indiqu\u00e9, NJPW a pr\u00e9c\u00e9demment annonc\u00e9 que le All Star Junior Festival 2023 USA aura lieu le samedi 19 ao\u00fbt, \u00e9galement depuis la 2300 Arena de Philadelphie. C&rsquo;est la veille de Multiverse United 2.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Impact x NJPW \u00ab\u00a0Multiverse United: Only The STRONG Survive\u00a0\u00bb a eu lieu le jeudi 30 mars dans un Globe Theatre \u00e0 guichets ferm\u00e9s \u00e0 Los Angeles pendant le week-end de WrestleMania. L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 titr\u00e9 par Hiroshi Tanahashi battant Mike Bailey. D&rsquo;autres matchs de haut niveau ont vu KENTA, le champion des poids libres du NJPW, retenir Minoru Suzuki, Kushida vaincre Lio Rush, les champions du monde par \u00e9quipe de l&rsquo;Impact Ace Austin et Chris Bey conserver dans un Fatal 4 Way contre TMDK, The Motor City Machine Guns et l&rsquo;actuel IWGP Tag Team &amp; NJPW Les solides champions par \u00e9quipe Openweight Tag Aussie Open, ainsi que le champion X-Division Trey Miguel conservent dans une course \u00e0 six contre Rocky Romero, Clark Connors, Frankie Kazarian, Kevin Knight et Rich Swann, entre autres combats sur la carte de 9 matchs.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Multiverse United returns!<br><br>August 20 will see NJPW and <a href=\"https:\/\/twitter.com\/IMPACTWRESTLING?ref_src=twsrc%5Etfw\">@impactwrestling<\/a> back together for Multiverse United 2: For Whom the Bell Tolls, in Philadelphia!<a href=\"https:\/\/t.co\/0Q7yX6HGvB\">https:\/\/t.co\/0Q7yX6HGvB<\/a><a href=\"https:\/\/twitter.com\/hashtag\/IMPACTxNJPW?src=hash&amp;ref_src=twsrc%5Etfw\">#IMPACTxNJPW<\/a> <a href=\"https:\/\/t.co\/bVa3rj58JC\">pic.twitter.com\/bVa3rj58JC<\/a><\/p>&mdash; NJPW Global (@njpwglobal) <a href=\"https:\/\/twitter.com\/njpwglobal\/status\/1647799441699803136?ref_src=twsrc%5Etfw\">April 17, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Impact Wrestling et NJPW ont d\u00e9j\u00e0 annonc\u00e9 le deuxi\u00e8me \u00e9v\u00e9nement Multiverse United. Impact x NJPW \u00ab\u00a0Multiverse United 2: Pour qui sonne le glas\u00a0\u00bb aura lieu le dimanche 20 ao\u00fbt au 2300 Arena de Philadelphie, Pennsylvanie. Multiverse United 2 sera diffus\u00e9 en direct sur FITE TV. Les d\u00e9tails sur les billets seront annonc\u00e9s dans les prochaines&#8230;<\/p>\n","protected":false},"author":609,"featured_media":82849,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,55,4,41],"tags":[],"ppma_author":[295],"class_list":["post-82848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-njpw","category-news","category-tna-impact"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=82848"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82848\/revisions"}],"predecessor-version":[{"id":82850,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82848\/revisions\/82850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/82849"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=82848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=82848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=82848"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=82848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}