{"id":82790,"date":"2023-04-14T22:57:00","date_gmt":"2023-04-15T02:57:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=82790"},"modified":"2023-04-17T16:11:32","modified_gmt":"2023-04-17T20:11:32","slug":"resultats-et-video-pour-le-aew-rampage-du-14-avril-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/04\/14\/resultats-et-video-pour-le-aew-rampage-du-14-avril-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Rampage du 14 Avril 2023!"},"content":{"rendered":"\n<p><em>* Les vid\u00e9os sont au bas de la page.<\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Rampage Milwaukee, Wisconsin, 14 avril 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Jim Ross, Excalibur, Tony Schiavone et Chris Jericho.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>IWGP World Tag Team Championship <\/strong><\/p>\n\n\n\n<p><strong>Aussie Open&nbsp;<em>(Kyle Fletcher et Mark Davis)<\/em>&nbsp;(c) vs Best Friends<em>&nbsp;(Chuck Taylor et Trent Beretta)<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, David attrape Trent et lui fait son Pile Driver. Aussie Open font leurs doubles coups de coude sur Taylor et ils font leur Corealis pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnants : Aussie Open<\/strong><\/p>\n\n\n\n<p>&#8211; On retrouve le clan de Sonjay Dutt en coulisse. Mark Briscoe dit que Jay Lethal l&rsquo;a arnaqu\u00e9 avec cet accord. Dutt am\u00e8ne Briscoe \u00e0 l&rsquo;\u00e9cart pour lui expliquer que lui et Lethal sont de grands amis de la campagne. Sans oublier qu&rsquo;il a pr\u00e9par\u00e9 un tee-shirt pour leur \u00e9quipe. Dutt pr\u00e9sente le tee-shirt avec Mark qui est bien en bas du tee-shirt. Dutt dit que c&rsquo;est le moment de gagner le match.<\/p>\n\n\n\n<p>&#8211; Tony Schiavone est sur le ring avec&nbsp;<strong>FTR<\/strong>. Cash Wheeler qu&rsquo;ils ont eu besoin de deux ans et cinq mois pour remporter les titres par \u00e9quipe AEW une seconde fois. Alors il y a eu des sp\u00e9culations sur le futur de FTR. Il doit annoncer qu&rsquo;on est encore pris avec FTR pour un autre quatre ans car ils sont toujours All Elite. Lorsqu&rsquo;ils ont perdu les titres, c&rsquo;\u00e9tait l&rsquo;ascension la plus difficile, mais ils n&rsquo;ont jamais \u00e9t\u00e9 abandonn\u00e9 par les fans.&nbsp;<strong>Il leur reste quatre ans, et quand le quatre ans arriverai ils vont arr\u00eater le catch. Mais ils vont tout donner pendant ces quatre ans pour devenir la meilleure \u00e9quipe de l&rsquo;histoire.<\/strong>&nbsp;Dax Harwood dit qu&rsquo;il se demande encore pourquoi les fans aiment FTR. C&rsquo;est leur histoire r\u00e9demption. On a tous pass\u00e9 par l\u00e0, chercher une solution \u00e0 nourrir notre famille, surmonter une \u00e9preuve. Alors les fans se reconnaissent en eux. Depuis les dix derni\u00e8res ann\u00e9es les fans ont toujours \u00e9t\u00e9 l\u00e0. Pour ces quatre ans, FTR va rembourser les fans pour ce soutien. Ils vont tout donner pour les fans, le catch et l&rsquo;AEW.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, on retrouve<strong>&nbsp;Lexy avec le clan des Hardys.<\/strong>&nbsp;Jeff Hardy dit que c&rsquo;est g\u00e9nial d&rsquo;\u00eatre de retour. Depuis les derniers neuf mois il a travaill\u00e9 sur lui. Matt Hardy dit que c&rsquo;est si bon de revoir les Hardys. Ils sont pr\u00eats pour le match contre The Firm et ils seront lib\u00e9r\u00e9s du Firm pour de bon. Big Bill, Moriarty, Hathaway et Page seront dans ce match pour ce match \u00e0 la ferme des Hardys dans un Firm Deletion Match.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Hobbs et Wardlow. Wardlow promet de retrouver son titre TNT la semaine prochaine.<\/p>\n\n\n\n<p><strong>8-Man Tag Team Match<\/strong><\/p>\n\n\n\n<p><strong>Mark Briscoe, Jeff Jarrett, Jay Lethal et Satnam Singh vs Jake Manning, Luther, Serpentico et Angelico<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Singh fait un ChokeSlam sur Manning. Briscoe enchaine avec son Elbow Drop pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnants : Mark Briscoe, Jeff Jarrett, Jay Lethal et Satnam Singh<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Mark ne semble pas heureux et refuse de c\u00e9l\u00e9brer avec l&rsquo;\u00e9quipe.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 The Elite contre Blackpool Combat Club.<\/p>\n\n\n\n<p><strong>Taya Valkyrie vs Emi Sakura<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Valkyrie fait un Spear et son Road to Valhalla \u00e0 Sakura pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnante : Taya Valkyrie<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Leila Grey entre sur le ring, mais Valkyrie la frappe directement et lui fait son Road to Valhalla. Jade Cargill entre sur le ring et les deux \u00e9changent les coups ! Valkyrie veut lui faire son finisher, mais Grey la frappe sur le dos. Cargill fait son Pump Kick \u00e0 Valkyrie et enchaine avec son Jaded.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En vid\u00e9o, Jos\u00e9 annonce que Dralistico challenge Hijo Del Vikingo la semaine prochaine.<\/p>\n\n\n\n<p>&#8211; On retrouve le Jericho Appreciation sur le ring. Matt Menard et Angelo Parker lancent un rap pour montrer que c&rsquo;est facile \u00eatre The Acclaimed. Ils chantent qu&rsquo;ils ont surpris The Acclaimed la semaine derni\u00e8re. C&rsquo;est \u00e9vident de rejoindre le JAS, tout le monde veut \u00eatre un divertisseur sportif. Jake Hager chante que The Acclaimed n&rsquo;est pas si cool car ils n&rsquo;ont pas son chapeau. The Acclaimed d\u00e9barque sur la sc\u00e8ne, mais ils vont directement sur le ring pour aller se battre avec le JAS. Ils expulsent le JAS du ring. Billy Gunn veut couper les cheveux de Menard, mais le JAS Le sort du ring.<strong>&nbsp;Anthony Bowens prend le micro et dit qu&rsquo;ils peuvent s&rsquo;affronter en Trios Match \u00e0 Dynamite pour r\u00e9gler \u00e7a.<\/strong><\/p>\n\n\n\n<p><strong>Jack Perry Jungle Boy vs Shawn Spears<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Spears bloque une charge avec un DDT et le couvre, mais il r\u00e9siste. Spears le prend pour son C4, mais Perry le renverse en compte rapide et il r\u00e9siste. Perry enchaine avec un Flatliner et le couvre, mais il r\u00e9siste. Perry le charge, mais Spears lui fait un Back Breaker. Spears veut faire un compte rapide, mais Perry le bloque pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Jack Perry<\/strong><\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration de Perry et ils se serrent la main.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p class=\"has-text-align-center\">PvP HD Fullshow<br><a href=\"https:\/\/dailyhowtos.com\/Latest\/Main\/m2023.php?minify=M23&amp;mirror=tuberep_1&amp;mainid=041423ARp\" target=\"_blank\" rel=\"noreferrer noopener\">PvPHD Fullshow<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\">Dailymotion FHD<br><a href=\"https:\/\/dailyhowtos.com\/Latest\/Main\/m2023.php?minify=M23&amp;mirror=dmrep_1&amp;mainid=041423ARp\" target=\"_blank\" rel=\"noreferrer noopener\">Dailymotion FHD<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\">FSC HD<br><a href=\"https:\/\/dailyhowtos.com\/Latest\/Main\/m2023.php?minify=M23&amp;mirror=fscfull&amp;mainid=041423ARp\" target=\"_blank\" rel=\"noreferrer noopener\">Fullshow<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\">DailyMotion HD Live<br><a rel=\"noreferrer noopener\" href=\"https:\/\/dailyhowtos.com\/Latest\/Main\/m2023.php?minify=M23&amp;mirror=dmlp_1&amp;mainid=041423ARp\" target=\"_blank\">Part 1<\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/dailyhowtos.com\/Latest\/Main\/m2023.php?minify=M23&amp;mirror=dmlp_2&amp;mainid=041423ARp\" target=\"_blank\">  <\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/dailyhowtos.com\/Latest\/Main\/m2023.php?minify=M23&amp;mirror=dmlp_2&amp;mainid=041423ARp\" target=\"_blank\">Part 2<\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/dailyhowtos.com\/Latest\/Main\/m2023.php?minify=M23&amp;mirror=dmlp_3&amp;mainid=041423ARp\" target=\"_blank\">  <\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/dailyhowtos.com\/Latest\/Main\/m2023.php?minify=M23&amp;mirror=dmlp_3&amp;mainid=041423ARp\" target=\"_blank\">Part 3  <\/a><a rel=\"noreferrer noopener\" href=\"https:\/\/dailyhowtos.com\/Latest\/Main\/m2023.php?minify=M23&amp;mirror=dmlp_4&amp;mainid=041423ARp\" target=\"_blank\">Last<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>* Les vid\u00e9os sont au bas de la page. AEW Rampage Milwaukee, Wisconsin, 14 avril 2023 Les commentateurs sont Jim Ross, Excalibur, Tony Schiavone et Chris Jericho. IWGP World Tag Team Championship Aussie Open&nbsp;(Kyle Fletcher et Mark Davis)&nbsp;(c) vs Best Friends&nbsp;(Chuck Taylor et Trent Beretta) \u00c0 la fin du combat, David attrape Trent et lui&#8230;<\/p>\n","protected":false},"author":55,"featured_media":82791,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,21,49,20],"tags":[],"ppma_author":[288],"class_list":["post-82790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-resultats","category-roh","category-videos"],"authors":[{"term_id":288,"user_id":55,"is_guest":0,"slug":"mark-green","display_name":"Watch Wrestling","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/48aa7229968e08b18e4ac74ae48666f742d5f4460d3a972818733f8de3e505c2?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=82790"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82790\/revisions"}],"predecessor-version":[{"id":82863,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82790\/revisions\/82863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/82791"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=82790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=82790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=82790"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=82790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}