{"id":82721,"date":"2023-04-13T15:18:00","date_gmt":"2023-04-13T19:18:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=82721"},"modified":"2023-04-14T03:24:15","modified_gmt":"2023-04-14T07:24:15","slug":"une-date-pour-le-retour-de-cm-punk-a-la-all-elite-wrestling","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/04\/13\/une-date-pour-le-retour-de-cm-punk-a-la-all-elite-wrestling\/","title":{"rendered":"Une date pour le \u00ab\u00a0Retour\u00a0\u00bb de CM Punk \u00e0 la All Elite Wrestling!"},"content":{"rendered":"\n<p>Mercredi dernier, une source laissait savoir que CM Punk avait inform\u00e9 la AEW qu&rsquo;il souhaitait faire son retour au sein de la compagnie\u00a0et qu&rsquo;il avait m\u00eame propos\u00e9 certaines id\u00e9es cr\u00e9atives, comme le fait de travailler avec Kenny Omega et les Young Bucks.<\/p>\n\n\n\n<p>La source ajoute de nouveaux d\u00e9tails et avance m\u00eame une date pour le potentiel retour de CM Punk dans les shows de la All Elite Wrestling.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Peu de temps suite \u00e0 l&rsquo;annonce de la compagnie des Khan qui organisera l&rsquo;\u00e9pisode de Dynamite du 21 juin 2023 dans la Wintrust Arena de Chicago, notre contact dit avoir \u00e9t\u00e9 inform\u00e9e que\u00a0le plan actuel est que le retour de CM Punk se fasse lors de ce show en question, soit le 21 juin, ou aux alentours de cet \u00e9v\u00e8nement. Certaines personnes ont propos\u00e9 d&rsquo;annonce le retour \u00e0 l&rsquo;avance, dont des employ\u00e9s de Warner, mais ce n&rsquo;est pas encore s\u00fbr que \u00e7a sera le cas.<\/p>\n\n\n\n<p>Personne ne sait si la situation s&rsquo;est calm\u00e9 en interne, tandis que Kenny Omega et les Young Bucks sont en pleines n\u00e9gociations pour de nouveaux contrats. Une r\u00e9union est pr\u00e9vue entre CM Punk et Chris Jericho pour voir s&rsquo;ils peuvent travailler ensemble.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"NPoGKQ5YlJ\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/04\/12\/resultats-pour-le-aew-dynamite-du-12-avril-2023\/\">R\u00e9sultats pour le AEW Dynamite du 12 Avril 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats pour le AEW Dynamite du 12 Avril 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/04\/12\/resultats-pour-le-aew-dynamite-du-12-avril-2023\/embed\/#?secret=jKjygBJ7vX#?secret=NPoGKQ5YlJ\" data-secret=\"NPoGKQ5YlJ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Mercredi dernier, une source laissait savoir que CM Punk avait inform\u00e9 la AEW qu&rsquo;il souhaitait faire son retour au sein de la compagnie\u00a0et qu&rsquo;il avait m\u00eame propos\u00e9 certaines id\u00e9es cr\u00e9atives, comme le fait de travailler avec Kenny Omega et les Young Bucks. La source ajoute de nouveaux d\u00e9tails et avance m\u00eame une date pour le&#8230;<\/p>\n","protected":false},"author":4,"featured_media":82723,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,4],"tags":[],"ppma_author":[292],"class_list":["post-82721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-news"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=82721"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82721\/revisions"}],"predecessor-version":[{"id":82724,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/82721\/revisions\/82724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/82723"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=82721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=82721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=82721"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=82721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}