{"id":81604,"date":"2023-03-17T20:34:09","date_gmt":"2023-03-18T00:34:09","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=81604"},"modified":"2023-03-21T14:38:27","modified_gmt":"2023-03-21T18:38:27","slug":"resultats-et-video-pour-le-wwe-friday-night-smackdown-du-17-mars-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/03\/17\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-17-mars-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 17 Mars 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/17\/avant-gout-pour-le-wwe-friday-night-smackdown-du-17-mars-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce Smackdown, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>WWE SmackDown Kansas City, Missouri, 17 mars 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Michael Cole et Wade Barrett.<\/p>\n\n\n\n<p>&#8211; Le  WWE SmackDown d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue. Cody Rhodes fait ensuite son entr\u00e9e et prend un micro. Il nous dit qu&rsquo;on peut parler de WrestleMania. Il a beaucoup de respect pour l&rsquo;actuel champion, Roman Reigns. Il pense que c&rsquo;est le plus grand champion dans le sport et divertissement sportif. Il a h\u00e2te de le voir \u00e0 RAW et de le battre \u00e0 WrestleMania.<\/p>\n\n\n\n<p>Cody Rhodes demande \u00e0 Kevin Owens de venir et il arrive. Cody Rhodes dit vouloir une discussion avec deux personnes, il demande \u00e0 Sami Zayn de venir et il arrive \u00e9galement. Cody Rhodes dit \u00e0 Kevin Owens qu&rsquo;il a beaucoup de respect pour lui. Il y a 7 ans, lorsqu&rsquo;il a quitt\u00e9 la WWE qui lui avait souhaitait bonne chance pour ses futurs projets, c&rsquo;est Owens qui lui a pr\u00e9sent\u00e9 de nouveaux amis. Il lui doit une faveur.<\/p>\n\n\n\n<p>Owens dit avoir d\u00e9j\u00e0 entendu tout ce que Zayn avait \u00e0 dire. Sami Zayn lui dit qu&rsquo;ils ont toujours trouv\u00e9 un moyen de retourner ensemble durant ces derni\u00e8res ann\u00e9es&#8230; mais pas cette fois. Si Owens a besoin de lui crier dessus, qu&rsquo;il le fasse ! S&rsquo;il veut le frapper, qu&rsquo;il le fasse ! Qu&rsquo;il fasse tout ce qu&rsquo;il faut pour qu&rsquo;ils reviennent sur la m\u00eame longueur d&rsquo;onde. Kevin Owens r\u00e9pond avoir entendu Sami Zayn, c&rsquo;est bon, Cody Rhodes a eu ce qu&rsquo;il voulait ? Cody Rhodes r\u00e9pond que c&rsquo;est ce que veulent les fans, tous les fans veulent les revoir ensemble.<\/p>\n\n\n\n<p>Kevin Owens demande pourquoi il se battrait pour quelqu&rsquo;un qui ne veut pas \u00eatre son ami puis quitte le ring.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Sur le parking, Kevin Owens allait prendre sa voiture mais il est rejoint par Sami Zayn qui lui dit qu&rsquo;ils sont fr\u00e8res, il veut qu&rsquo;Owens sache qu&rsquo;il l&rsquo;aime&#8230; Kevin Owens prend sa voiture et s&rsquo;en va.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Mixed Tag Team Match<\/strong><\/p>\n\n\n\n<p><strong>Legado Del Fantasma (Santos Escobar &amp; Zelina Vega) vs Judgment Day (Dominik Mysterio &amp; Rhea Ripley)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Zelina Vega fait un Hurricanrana sur Dominik Mysterio mais elle se fait surprendre par Rhea Ripley qui lui fait sa&nbsp;Riptide pour la victoire par tomb\u00e9.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Judgment Day<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Dominik Mysterio prend un micro et dit que Rey Mysterio n&rsquo;\u00e9tait qu&rsquo;un p\u00e8re bon \u00e0 rien. Nous voyons Rey Mysterio marcher dans les coulisses.<\/p>\n\n\n\n<p>&#8211; Apr\u00e8s la pause publicitaire, Rey Mysterio fait son entr\u00e9e et monte sur le ring. Dominik Mysterio dit que Rey a enfin d\u00e9cid\u00e9 de venir. Ce dernier demande \u00e0 Rhea Ripley de les laisser seuls. Dominik dit que Rey veut parler maintenant qu&rsquo;ils sont sur le ring. Rey n&rsquo;a jamais \u00e9t\u00e9 l\u00e0 pour lui, c&rsquo;est un l\u00e2che. Rey admet avoir rat\u00e9 des anniversaires ou encore des No\u00ebls, mais il a tout l&rsquo;amour du monde pour son fils. Il a fait des sacrifices pour que sa m\u00e8re, sa s\u0153ur et lui puissent avoir la meilleure vie.<\/p>\n\n\n\n<p>Rey sera intronis\u00e9 au Hall of Fame cette ann\u00e9e et il aimerait avoir son fils \u00e0 ses c\u00f4t\u00e9s sur la sc\u00e8ne. Son plus grand regret est de savoir ce qu&rsquo;est devenu Dominik. C&rsquo;est un gosse path\u00e9tique et si une personne comme lui le d\u00e9fiait pour WrestleMania, il serait tr\u00e8s content de lui botter le cul ! H\u00e9las, Dominik est son fils et l&rsquo;affronter serait une \u00e9norme honte en tant que p\u00e8re. Ils ne vont pas s&rsquo;affronter \u00e0 WrestleMania. Rey Mysterio quitte le ring.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Les commentateurs annoncent que deux Fatal 4-Way par \u00e9quipe auront lieu \u00e0 WrestleMania 39, un masculin et un autre f\u00e9minin. Les matchs de qualification commencent d\u00e8s ce soir.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Liv Morgan et Raquel Rodriguez vs Tegan Nox et Emma<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Liv Morgan fait son Oblivion sur Emma pour l&#8217;emporter par tomb\u00e9.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnantes : Liv Morgan et Raquel Rodriguez<\/em><\/p>\n\n\n\n<p>&#8211; Liv Morgan et Raquel Rodriguez int\u00e8grent le Fatal 4-Way par \u00e9quipe f\u00e9minin de WrestleMania 39.<\/p>\n\n\n\n<p>&#8211; Charlotte Flair fait son entr\u00e9e. La championne de SmackDown dit que lorsqu&rsquo;elle \u00e9tait petite, le business \u00e9tait fait \u00e0 base de Rhodes en tant que challenger et Flair en tant que champion. En 2023, c&rsquo;est la m\u00eame chose : Rhodes est challenger, Flair est championne. C&rsquo;est son septi\u00e8me WrestleMania et elle a toujours \u00e9t\u00e9 soit championne, soit challengeuse. Rhea Ripley fait son entr\u00e9e avec Dominik Mysterio.<\/p>\n\n\n\n<p>Rhea Ripley dit avoir choisi Charlotte Flair pour une raison. C&rsquo;est la championne de SmackDown pour une raison. C&rsquo;est une 14 fois championne pour une raison. C&rsquo;est l&rsquo;une des plus grandes stars de la WWE. Rhea Ripley veut cette ceinture, elle a besoin d&rsquo;\u00eatre une star ! Charlotte Flair va apprendre \u00e0 dire \u00ab\u00a0Rhea championne\u00a0\u00bb et va apprendre \u00e0 avoir peur d&rsquo;elle.<\/p>\n\n\n\n<p>Dominik Mysterio se met face \u00e0 Charlotte Flair et Rhea Ripley lui met un gifle avant de quitter le ring. Charlotte Flair se rel\u00e8ve puis une bagarre \u00e9clate entre les deux catcheuses. Les officiels viennent pour les s\u00e9parer mais Charlotte Flair et Rhea Ripley continue de se bagarrer !<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Dans les coulisses, Sami Zayn dit qu&rsquo;un mec qu&rsquo;il pensait \u00eatre un fr\u00e8re est parti. L&rsquo;autre mec qui le prenait comme un fr\u00e8re cherche \u00e0 le d\u00e9molir. Mais tout \u00e7a est \u00e0 cause de lui, alors il doit r\u00e9gler les probl\u00e8mes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Xavier Woods vs LA Knight<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, LA Knight porte Xavier Woods mais ce dernier arrive \u00e0 le contrer pour faire un roll up et l&#8217;emporter.<\/p>\n\n\n\n<p><em>Gagnant : Xavier Woods<\/em><\/p>\n\n\n\n<p>&#8211; On nous rappelle que le Great Muta sera intronis\u00e9 au Hall of Fame cette ann\u00e9e.&nbsp;<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, LA Knight rejoint Rey Mysterio par hasard et dit que lui peut affronter Dominik, mais Rey le frappe !<\/p>\n\n\n\n<p>&#8211; Sheamus et Drew McIntyre font leur entr\u00e9e pour leur match. L&rsquo;Imperium arrive en ringside pour regarder le match.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Sheamus vs Drew McIntyre<\/strong><br><em>Le vainqueur affrontera Gunther \u00e0 WrestleMania 39.<\/em><\/p>\n\n\n\n<p>\u00c0 la fin du match, Gunther monte sur le ring tandis que Sheamus et Drew McIntyre sont au sol. Ces derniers se rel\u00e8vent et Ludwig Kaiser ainsi que Giovanni Vinci les attaquent par derri\u00e8re ! L&rsquo;arbitre met fin au match.<\/p>\n\n\n\n<p><em>Pas de Gagnant<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, Gunther s&rsquo;attaque aussi \u00e0 McIntyre et Sheamus. Adam Pearce apparait sur l&rsquo;\u00e9cran g\u00e9ant et informe Gunther qu&rsquo;il va d\u00e9fendra sa ceinture du titre Intercontinental contre Sheamus et Drew McIntyre \u00e0 WrestleMania 39 !<\/p>\n\n\n\n<p>&#8211; La semaine prochaine \u00e0 SmackDown : Rey Mysterio vs LA Knight.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Jey Uso est sur le ring. Sami Zayn arrive et dit que c&rsquo;est ce que voulait Jey Uso, il est l\u00e0. Jey Uso lui dit que d\u00e8s le premier jour, il ne sentait pas Sami Zayn, il ne voulait pas de lui dans sa famille. Mais ils ont commenc\u00e9 \u00e0 s&rsquo;appr\u00e9cier semaine apr\u00e8s semaine. Tout le monde dans la Bloodline l&rsquo;appr\u00e9ciait. L&rsquo;objectif de Jey est de prot\u00e9ger sa famille, mais la seule fois o\u00f9 il \u00e9tait vuln\u00e9rable, Sami Zayn a pr\u00e9f\u00e9r\u00e9 les trahir devant le monde entier. D\u00e8s le premier jour, Sami Zayn \u00e9tait un Fake Ass Uce ! Jey Uso n&rsquo;avait pas d&rsquo;autre choix. Sami Zayn r\u00e9pond que c&rsquo;est faux. Jey Uso a choisi la maltraitance de Roman Reigns toutes les semaines.<\/p>\n\n\n\n<p>En r\u00e9alit\u00e9, Jey Uso est juste \u00e9nerv\u00e9 de ne pas avoir \u00e9t\u00e9 le premier \u00e0 avoir frapp\u00e9 Roman Reigns avec une chaise. Jey Uso avait le choix. Jey Uso le frappe et une bagarre \u00e9clate. Jimmy vient aider son fr\u00e8re mais&#8230; la musique de Kevin Owens retentit et il attaque les Usos !&nbsp;<\/p>\n\n\n\n<p>Sami Zayn et Kevin Owens se regardent puis se font un bro-hug !&nbsp;Cody Rhodes regardait ce moment \u00e0 la t\u00e9l\u00e9vision dans les coulisses et il a l&rsquo;air content de la tournure des \u00e9v\u00e9nements. <\/p>\n\n\n\n<p>Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:25px\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/17\/avant-gout-pour-le-wwe-friday-night-smackdown-du-17-mars-2023\/\" target=\"_blank\">Pour voir ce Smackdown, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"BOnyuzckid\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/17\/avant-gout-pour-le-wwe-friday-night-smackdown-du-17-mars-2023\/\">Vid\u00e9os et Programme pour le WWE Friday Night Smackdown du 17 Mars 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vid\u00e9os et Programme pour le WWE Friday Night Smackdown du 17 Mars 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/17\/avant-gout-pour-le-wwe-friday-night-smackdown-du-17-mars-2023\/embed\/#?secret=fBcnt9eF2C#?secret=BOnyuzckid\" data-secret=\"BOnyuzckid\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE SmackDown Kansas City, Missouri, 17 mars 2023 Les commentateurs sont Michael Cole et Wade Barrett. &#8211; Le WWE SmackDown d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue. Cody Rhodes fait ensuite son entr\u00e9e et prend un micro. Il nous dit qu&rsquo;on peut parler de WrestleMania. Il a beaucoup de respect pour l&rsquo;actuel champion,&#8230;<\/p>\n","protected":false},"author":4,"featured_media":81607,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,87,36,23],"tags":[],"ppma_author":[292],"class_list":["post-81604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-road-to-wrestlemania","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=81604"}],"version-history":[{"count":14,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81604\/revisions"}],"predecessor-version":[{"id":81724,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81604\/revisions\/81724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/81607"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=81604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=81604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=81604"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=81604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}