{"id":81588,"date":"2023-03-17T12:35:47","date_gmt":"2023-03-17T16:35:47","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=81588"},"modified":"2023-03-17T12:35:50","modified_gmt":"2023-03-17T16:35:50","slug":"reunion-possible-du-new-day-au-complet-a-wrestlemania-plus-sur-la-chirurgie-de-kofi-kingston","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/03\/17\/reunion-possible-du-new-day-au-complet-a-wrestlemania-plus-sur-la-chirurgie-de-kofi-kingston\/","title":{"rendered":"R\u00e9union possible du New Day au complet \u00e0 WrestleMania! Plus sur la chirurgie de Kofi Kingston!"},"content":{"rendered":"\n<p>Le New Day pourrait se r\u00e9unir \u00e0 WrestleMania 39.<\/p>\n\n\n\n<p>Un nouveau rapport du Wrestling Observer note qu&rsquo;il a \u00e9t\u00e9 question que Big E fasse son retour \u00e0 la WWE TV \u00e0 WrestleMania 39.<\/p>\n\n\n\n<p>L&rsquo;id\u00e9e est que Big E, Kofi Kingston et Xavier Woods sortiraient ensemble, mais il n&rsquo;\u00e9tait pas clair si ce serait pour une sorte de segment, ou un match avec l&rsquo;un des membres du groupe.<\/p>\n\n\n\n<p>Kingston asubit une intervention chirurgicale aujourd&rsquo;hui, ce qui peut annuler l&rsquo;id\u00e9e, mais le statut de Big E est \u00e9galement un facteur. Il a \u00e9t\u00e9 indiqu\u00e9 que la WWE pourrait ne pas aller de l&rsquo;avant avec le plan si Big E n&rsquo;est pas en mesure de faire revenir sa bague bient\u00f4t.<\/p>\n\n\n\n<p>Comme nous l&rsquo;avons not\u00e9, le week-end dernier a marqu\u00e9 un an depuis que Big E s&rsquo;est cass\u00e9 le cou \u00e0 SmackDown. Il devait subir des tests vers un an, s&rsquo;il ne l&rsquo;a pas d\u00e9j\u00e0 fait, et on ne sait pas s&rsquo;il pourra revenir apr\u00e8s l&rsquo;\u00e9valuation d&rsquo;un an par les m\u00e9decins. Vous pouvez cliquer ici pour les commentaires r\u00e9cents de Big E sur son statut.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Comme nous l&rsquo;avons not\u00e9, Kingston s&rsquo;est bless\u00e9 \u00e0 la cheville droite lors du SmackDown du 3 mars apr\u00e8s un segment de bagarre sur le ring avec The New Day, LA Knight, Karrion Kross, Sheamus et Drew McIntyre. La blessure s&rsquo;est produite lorsque McIntyre a clou\u00e9 un plongeon \u00e0 la corde sup\u00e9rieure sur d&rsquo;autres au bord du ring. La blessure a \u00e9t\u00e9 d\u00e9crite comme un \u00ab\u00a0coup de chance\u00a0\u00bb et Kingston a \u00e9t\u00e9 remplac\u00e9 par Xavier Woods dans Fatal 5 Way vendredi dernier.<\/p>\n\n\n\n<p>Dans une mise \u00e0 jour, Kingston s&rsquo;est rendu sur Twitter tard hier soir et a r\u00e9v\u00e9l\u00e9 qu&rsquo;il passerait sous le couteau aujourd&rsquo;hui.<\/p>\n\n\n\n<p>Apr\u00e8s avoir racont\u00e9 une longue histoire sur sa journ\u00e9e \u00e0 Birmingham, en Alabama, il a \u00e9crit : \u00ab Demain, nous avan\u00e7ons et entre les mains des meilleurs au monde dans ce qu&rsquo;il fait ! Mettons cette cheville en ordre&nbsp;! [poing emoji]\u00a0\u00bb<\/p>\n\n\n\n<p>Kingston se fait op\u00e9rer au Andrews Sports Medicine &amp; Orthopaedic Centre \u00e0 Birmingham aujourd&rsquo;hui.<\/p>\n\n\n\n<p><br>On ne sait pas encore combien de temps Kingston sera hors de combat. On pensait \u00e0 l&rsquo;origine qu&rsquo;il pourrait \u00eatre absent pendant environ cinq semaines et qu&rsquo;il n&rsquo;aurait pas besoin d&rsquo;une intervention chirurgicale, mais cela a \u00e9videmment chang\u00e9.<\/p>\n\n\n\n<p>Vous pouvez voir le tweet complet de Kingston ci-dessous :<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">***Long post ahead. Y\u2019all that don\u2019t like to read, this ain\u2019t for you lol***<br><br>Alabama folks are so kind. Earlier today instead of waiting 15 min for an Uber to take me to the YMCA Shades Valley to workout, I opted to take one of those electric street scooters. Big mistake. Half\u2026 <a href=\"https:\/\/t.co\/KQUjlVRCyn\">https:\/\/t.co\/KQUjlVRCyn<\/a><\/p>&mdash; Kofi Kingston (@TrueKofi) <a href=\"https:\/\/twitter.com\/TrueKofi\/status\/1636561774190247936?ref_src=twsrc%5Etfw\">March 17, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le New Day pourrait se r\u00e9unir \u00e0 WrestleMania 39. Un nouveau rapport du Wrestling Observer note qu&rsquo;il a \u00e9t\u00e9 question que Big E fasse son retour \u00e0 la WWE TV \u00e0 WrestleMania 39. L&rsquo;id\u00e9e est que Big E, Kofi Kingston et Xavier Woods sortiraient ensemble, mais il n&rsquo;\u00e9tait pas clair si ce serait pour une&#8230;<\/p>\n","protected":false},"author":609,"featured_media":81589,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,87,23],"tags":[],"ppma_author":[295],"class_list":["post-81588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-road-to-wrestlemania","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=81588"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81588\/revisions"}],"predecessor-version":[{"id":81590,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81588\/revisions\/81590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/81589"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=81588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=81588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=81588"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=81588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}