{"id":81547,"date":"2023-03-15T22:14:10","date_gmt":"2023-03-16T02:14:10","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=81547"},"modified":"2023-03-15T22:15:44","modified_gmt":"2023-03-16T02:15:44","slug":"resultats-et-video-pour-le-aew-dynamite-du-15-mars-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/03\/15\/resultats-et-video-pour-le-aew-dynamite-du-15-mars-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Dynamite du 15 Mars 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/15\/avant-gout-pour-le-aew-dynamite-du-15-mars-2023\/\" target=\"_blank\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Dynamite Winnipeg au Canada, 15 mars 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Taz, Tony Schiavone et Excalibur.<\/p>\n\n\n\n<p>&#8211; Le AEW Dynamite d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue .<\/p>\n\n\n\n<p>&#8211; Justin Roberts nous pr\u00e9sente&nbsp;MJF qui arrive sur le ring pour c\u00e9l\u00e9brer son anniversaire pour ce \u00a0\u00bbRe-Bar Mitzvah Celebration\u00a0\u00bb. MJF dit qu&rsquo;il sait que les canadiens ne sont pas trop intelligents, les canadiens pensaient que Bret Hart \u00e9tait divertissement. Shawn est bien meilleur. MJF dit qu&rsquo;on est ici pour c\u00e9l\u00e9brer le plus grand anniversaire, son anniversaire. Dans sa religion, la seule qui importe, le juda\u00efsme, lorsqu&rsquo;un enfant tourne 18 ans il a son Bar&nbsp;Mitzvah. Il a d\u00e9j\u00e0 eu son Bar&nbsp;Mitzvah, mais ce soir nous aurons un Re-Bar. Pourquoi ? Car il a fait taper Bryan Danielson afin de rester le champion mondial.<\/p>\n\n\n\n<p>MJF dit qu&rsquo;il n&rsquo;est pas seulement un homme, mais bien un Iron Man. MJF demande de lancer sa musique sp\u00e9ciale&nbsp;Mitzvah. Un groupe d&rsquo;hommes arrivent sur le ring pour faire la c\u00e9l\u00e9bration juive et danser, mais la musique de Jack Perry (Jungle Boy) commence et il arrive sur le ring ! Jack Perry allait parler, mais la musique de Sammy Guevara le coupe. Guevara arrive sur le ring et la musique de Darby Allin le coupe. MJF demande le calme \u00e0 tout le monde. MJF dit qu&rsquo;ils ruinent son Re-Bar&nbsp;Mitzvah, alors ils veulent quoi ?&nbsp;<strong>Les trois catcheurs r\u00e9pondent \u00a0\u00bbun match de titre\u00a0\u00bb.<\/strong>&nbsp;<\/p>\n\n\n\n<p>MJF dit que c&rsquo;est adorable. Jack Perry dit que leur dernier match remonte \u00e0 Double or Nothing 2020, le premier PPV sans fan. Ils ont fait un match de 20 minutes jusqu&rsquo;\u00e0 temps que MJF triche et l&#8217;emporte. Ensuite leur vie ont pris des directions diff\u00e9rentes. MJF a re\u00e7u des opportunit\u00e9s et lui a pass\u00e9 son temps \u00e0 AEW Dark. Est-ce que MJF a d\u00e9j\u00e0 eu un match \u00e0 Dark ou Elevation ou Rampage comme eux ? MJF fait seulement se promener et faire ce qu&rsquo;il veut. Perry dit que c&rsquo;est fou car il y a un vestiaire qui se donne \u00e0 fond et qui auront peut-\u00eatre juste 60 secondes sur le show. Pendant ce temps MJF poursuit de faire la m\u00eame merde depuis un an. Cet endroit tourne sur MJF et la premi\u00e8re fa\u00e7on de changer \u00e7a est de lui prendre le titre.<\/p>\n\n\n\n<p>MJF dit que la compagnie tourne sur lui, car au contraire des trois ici et ceux en coulisse il est une r\u00e9elle star. Guevara dit qu&rsquo;il n&rsquo;a pas peur de tourner ce Re-Bar&nbsp;Mitzvah&nbsp;et Re-Circoncision. Guevara dit que MJF parle trop depuis toute sa vie. MJF embrasse des culs et triche pour avoir sa place. Guevara dit qu&rsquo;il a d\u00fb pass\u00e9 10 ans sur le Indy pour avoir sa place et travailler dans les fast-foods. Lorsqu&rsquo;il est enfin arriv\u00e9 ici on lui a dit qu&rsquo;il devait \u00eatre le gars du Inner Circle \u00e0 prendre les chutes pour Chris Jericho, mais il a d\u00e9pass\u00e9 chacun des obstacles afin de devenir trois fois champions. Il n&rsquo;est pas comme MJF, il n&rsquo;a jamais eu besoin de la machine pour le pousser. Il est arriv\u00e9 ici gr\u00e2ce \u00e0 lui et \u00e7a va le mener au titre. Qu&rsquo;on aime \u00e7a ou non, Guevara sera un champion mondial car il est le meilleur et MJF le sait. MJF dit que c&rsquo;\u00e9tait adorable de voler sa catch-phrase. Il f\u00e9licite Guevara pour prendre son temps occup\u00e9 \u00e0 se battre en coulisse pour venir ici. Darby Allin dit qu&rsquo;en 2013 son professeur en cin\u00e9ma lui a dit qu&rsquo;il devait tout changer son projet car l&rsquo;\u00e9cole n&rsquo;allait pas l&rsquo;accepter. Alors il a quitt\u00e9 l&rsquo;\u00e9cole pour lui donner les couilles de d\u00e9buter le catch. \u00c0 son premier jour il s&rsquo;est arr\u00eat\u00e9 devant la porte en disant qu&rsquo;il allait r\u00e9ussir ou \u00e9chouer, mais il n&rsquo;allait jamais changer. Allin dit qu&rsquo;il a \u00e9t\u00e9 voir Tony Khan en disant qu&rsquo;il n&rsquo;y aura jamais une guerre d&rsquo;ench\u00e8res sur lui. Car l&rsquo;AEW lui donne quelque chose qui vaut plus que de l&rsquo;argent, l&rsquo;AEW lui donne la chance d&rsquo;\u00eatre lui-m\u00eame. Allin dit qu&rsquo;on a des catcheurs qui vont sur Twitter se plaindre en disant qu&rsquo;ils vont quitter la compagnie, comme MJF avec sa merde de guerre des ench\u00e8res. L&rsquo;AEW repr\u00e9sente plus pour lui que MJF, alors il devrait \u00eatre le champion mondial. S&rsquo;il n&rsquo;a pas son match de titre&#8230; il va aller se plaindre sur Twitter&#8230; s\u00e9rieusement il va lui enfoncer son skateboard dans la t\u00eate.<\/p>\n\n\n\n<p>MJF est furieux et dit d&rsquo;arr\u00eater. MJF insulte les trois en soulignant Guevara qui demande une femme en mariage tous les sept mois. Guevara dit que c&rsquo;est dr\u00f4le sachant que sa fianc\u00e9e l&rsquo;a laiss\u00e9. MJF dit que Perry avait Christian, Guevara a Jericho, Allin a Sting et lui n&rsquo;a personne.&nbsp;Car il n&rsquo;a pas besoin d&rsquo;avoir son p\u00e8re pour l&rsquo;aider \u00e0 l&rsquo;AEW, il est pr\u00eat depuis le premier jour. Ils sont les piliers de l&rsquo;AEW, ils sont le pass\u00e9, le pr\u00e9sent et le futur du catch professionnel. Mais il est le seul pilier qui peut garder cette place debout. Il a battu tous les trois en match simple et ils pensent m\u00e9riter une chance au titre ? Non, ils ne m\u00e9ritent pas de s&rsquo;approcher de lui.&nbsp;Les trois vont quitter la f\u00eate, car aucun n&rsquo;\u00e9tait invit\u00e9. Et ensuite il va manger son g\u00e2teau car il le m\u00e9rite. MJF leur dit au revoir et pousse Jack Perry, mais l&rsquo;affrontement \u00e9clate entre les quatre catcheurs. MJF tombe sur son g\u00e2teau lorsqu&rsquo;il pouss\u00e9 par erreur par les trois catcheurs.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Chris Jericho qui a re\u00e7u le grand honneur de sa ville de Winnipeg : Une rue qui a \u00e9t\u00e9 nomm\u00e9e en son nom.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, le Dark Order arrive.<\/p>\n\n\n\n<p><strong>Blackpool Combat Club&nbsp;<em>(Jon Moxley, Claudio Castagnoli et Wheeler Yuta)<\/em>&nbsp;vs Dark Order&nbsp;<em>(Adam Hangman Page, Evil Uno et Stu Grayson)<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Page se pr\u00e9pare pour son finisher, mais Yuta le frappe avec la cloche en pleine t\u00eate pendant que l&rsquo;arbitre est de dos. Uno et Grayson vont sur le ring pour se battre trois contre deux. Uno arrive \u00e0 bloquer le finisher de Moxley et lui fait son Paradigm Shift. Grayson fait un 450 Splash sur Moxley et Uno son Cannoball sur Yuta. Uno couvre Moxley, mais il r\u00e9siste. Grayson et Uno font ensuite leur Fatality sur Moxley pour le couvrir, mais Yuta brise le compte. Ensuite, Grayson veut donner la tag, mais Yuta tire Uno en bas du ring. Castagnoli fait son Uppercut \u00e0 Grayson et Moxley enchaine avec son Bulldog Choke pour faire taper Grayson.<\/p>\n\n\n\n<p><strong>Gagnants : Blackpool Combat Club<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Moxley poursuit la soumission. Uno remonte sur le ring, mais il se fait attaquer trois contre un par le BCC. John Silver et Alex Reynolds arrivent sur le ring, mais le BCC prend la fuite par la foule.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Juice Robinson. Robinson dit que tout le monde veut savoir pourquoi il a attaqu\u00e9 Ricky Starks. C&rsquo;est plus de savoir qu&rsquo;est-ce que Starks va faire pour r\u00e9pondre \u00e0 l&rsquo;attaque ?<\/p>\n\n\n\n<p>&#8211; De retour, Jade Cargill arrive sur le ring pour son Open Challenge ouvert exclusivement aux canadiennes.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>TBS Championship <\/strong><\/p>\n\n\n\n<p><strong>Jade Cargill (c)<em>&nbsp;accompagn\u00e9e de Leila Grey<\/em>&nbsp;vs Nicole Matthews<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Cargill fait son Pump Kick sur Nicole et enchaine avec son Jaded pour le compte de trois en moins d&rsquo;une minute.<\/p>\n\n\n\n<p><strong>Gagnante : Jade Cargill (54-0)<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Renee Paquette arrive sur le ring pour avoir ses commentaires sur cette nouvelle victoire et la suite. Cargill demande si Paquette vient du Canada. Cargill repousse Paquette contre le coin et lui prend son micro. Cargill demande si le Canada n&rsquo;offre que \u00e7a ?&nbsp;<strong>Taya Valkyrie arrive sur le ring<\/strong>&nbsp;! Valkyrie et Cargill font un face \u00e0 face sur le ring. Cargill quitte le ring, Leila Grey veut l&rsquo;attaquer, mais Valkyrie lui fait un Jaded.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, Tony Schiavone est avec Ricky Starks pour avoir sa r\u00e9ponse \u00e0 Juice Robinson. Starks dit que c&rsquo;est facile de frapper dans le dos. Robinson est jaloux car il a l&rsquo;attention. Robinson a fait quoi ? Il est dans le Bullet Club, c&rsquo;\u00e9tait cool en 2015. Alors si Robinson a un probl\u00e8me avec lui, il peut se ramener. Il peut aussi ramener le Bullet Club.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente&nbsp;<strong>une vid\u00e9o sur le QTV.<\/strong>&nbsp;QT Marshall est avec Powerhouse Hobbs et son \u00e9quipe du talk-show. Son \u00e9quipe d\u00e9voile que c&rsquo;est&nbsp;Aaron Solo qui est le responsable du vol dans la voiture de Wardlow juste avant AEW Revolution. Marshall dit que c&rsquo;est hilarant, mais Wardlow a vol\u00e9 son \u00e9lan l&rsquo;an dernier, il ne devrait pas \u00eatre surpris. Qu&rsquo;est-ce qui attend Wardlow apr\u00e8s ? Solo r\u00e9pond la m\u00eame chose que Batista, rien de bon. Hobbs souhaite la bienvenue \u00e0 Wardlow dans son univers.<\/p>\n\n\n\n<p>&#8211; Les commentateurs annoncent pour Rampage : Un Open Challenge pour le titre TNT de Hobbs \u00e0 Rampage.<\/p>\n\n\n\n<p><strong>AEW International Championship <\/strong><\/p>\n\n\n\n<p><strong>Jeff Jarrett&nbsp;<em>accompagn\u00e9 de son clan<\/em>&nbsp;vs Orange Cassidy (c)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, l&rsquo;arbitre se retrouve frapp\u00e9 par erreur. Sonjay Dutt lance la guitare sur le ring, mais un arbitre arrive pour lui enlever sa guitare ! Cassidy en profite pour faire un Roll Up \u00e0 Jarrett, mais il r\u00e9siste \u00e0 deux. Jarrett frappe Cassidy sur la jambe et il argumente avec l&rsquo;arbitre. Cassidy prend la guitare, mais Satnam Singh lui enl\u00e8ve. Cassidy joue le faux coup, l&rsquo;arbitre expulse Singh et Dutt en coulisse ! Cassidy profite de la distraction pour faire un DDT \u00e0 Jarrett. Cassidy se pr\u00e9pare pour son finisher, mais Jarrett parle avec l&rsquo;arbitre. Jay Lethal frappe Cassidy avec le Golden Globe ! Jarrett couvre Cassidy, mais il r\u00e9siste \u00e0 deux ! Trent Beretta arrive et attaque Lethal pour le repousser. Cassidy veut faire son Punch, mais il a trop mal au genou. Jarrett veut en profiter avec son Stroke, mais Cassidy le repousse et lui fait un Orange Punch pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Orange Cassidy<\/strong><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o promo sur le Trios Championship.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o rap sur The Acclaimed qui insulte le JAS.<\/p>\n\n\n\n<p>&#8211; Le clan&nbsp;<strong>The Outcasts<\/strong>&nbsp;arrive sur le ring. Ruby Soho dit qu&rsquo;elle a une histoire pour nous. Il y a une \u00e9poque o\u00f9 l&rsquo;herbe \u00e9tait plus verte \u00e0 l&rsquo;AEW. Jusqu&rsquo;au moment o\u00f9 quelques chiennes arrivent pour uriner sur cette pelouse. Qu&rsquo;est-ce qu&rsquo;on fait avec ces chiennes ? Saraya dit qu&rsquo;il faut leur montrer que c&rsquo;est leur maison ici. Sans elles il n&rsquo;y aurait pas une division f\u00e9minine ici. Saraya demande aux fans de montrer du respect, elle est un miracle. Toni Storm dit que lorsqu&rsquo;elle est devenue une championne par int\u00e9rim, elle l&rsquo;a fait avec un sourire et personne ne l&rsquo;a appr\u00e9ci\u00e9. Mais notre championne actuelle l&rsquo;a battu et on adore \u00e7a. Storm dit qu&rsquo;on ne sait pas ce qu&rsquo;on veut. Alors elles sont ici pour nous donner ce qu&rsquo;on a de besoin et c&rsquo;est du changement dans la division. Elles sont les Outcasts et elles sont ici pour rester. Elles vont passer toutes les rookies. \u00c7a commence avec Sky Blue, Riho, Britt Baker et Jamie Hayter. Baker et Hayter arrivent sur le ring et l&rsquo;affrontement \u00e9clate ! Baker et Hayter ne peuvent pas rivaliser trois contre deux. Soho fait son Destination Unknown sur Baker et Storm son Storm Zero sur Hayter. Willow, Riho et Blue arrivent sur le ring et les Outcasts prennent la fuite.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, en coulisse, on retrouve Matt Menard et Angelo Parker. Menard dit qu&rsquo;ils adorent le rap chez le JAS, c&rsquo;\u00e9tait divertissant comme vid\u00e9o du Acclaimed. Ils ont lanc\u00e9 deux invitations, mais ils ont crach\u00e9 \u00e0 leur visage. Parker dit que The Acclaimed devrait regarder Rampage afin de voir ce qu&rsquo;ils peuvent faire.<\/p>\n\n\n\n<p>&#8211; Les commentateurs annoncent pour Rampage (qui sera diffus\u00e9 apr\u00e8s le tournoi NCAA) : Menard et Parker vs Bollywood Boyz, Taya Valkyrie fera son premier match, et Rey Fenix va affronter Hobbs.<\/p>\n\n\n\n<p>&#8211; En coulisse, Rey Fenix annonce qu&rsquo;il va accepter l&rsquo;Open Challenge de Powerhouse Hobbs \u00e0 Rampage.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Trios Championship &#8211; 3-Way Trios Match<\/strong><\/p>\n\n\n\n<p><strong>House of Black&nbsp;<em>(Malakai Black, Brody King et Buddy Matthews)<\/em>&nbsp;(c)&nbsp;<em>accompagn\u00e9 de Julia Hart<\/em>&nbsp;vs The Elite<em>&nbsp;(Kenny Omega, Matt et Nick Jackson) accompagn\u00e9 de Don Callis et Michael Nakazawa<\/em>&nbsp;vs Jericho Appreciation Society<em>&nbsp;(Chris Jericho, Daniel Garcia et Sammy Guevara)<\/em><\/strong><\/p>\n\n\n\n<p>Pendant le combat, on voit que le Dark Order se bat contre le Blackpool Combat Club en coulisse.<\/p>\n\n\n\n<p>Guevara fait son Shooting Star Press sur Matt et le couvre, mais King brise le compte. King tire Matt pour prendre la tag. King charge Guevara contre le coin et fait son Cannonball sur Guevara et un autre sur Garcia. King termine avec son Back Senton sur Guevara et le lance vers Jericho pour qu&rsquo;il puisse prend la tag. Jericho entre sur le ring, encercl\u00e9 par la House of Black, et il se fait rouer de coups. King fait son Pile Driver sur Jericho et le couvre, mais Omega brise le compte. Garcia donne le b\u00e2ton de baseball \u00e0 Jericho et il frappe King au visage ! Guevara se lance en Shooting Star Press sur The Elite en bas du ring. Jericho couvre King, mais il r\u00e9siste \u00e0 deux ! Jericho se pr\u00e9pare pour son finisher, mais Black lui fait son Black Mass. Jericho chute en bas du ring et Garcia prend la tag. Black lui fait son Black Mass et King enchaine avec son Pile Driver pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnants : House of Black<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Jake Hager arrive sur le ring et commence \u00e0 se battre avec la House of Black. L&rsquo;affrontement entre le Dark Order et le BCC se transporte sur le ring. Le show se termine avec le BCC qui d\u00e9cide de partir lorsque The Elite se tient debout derri\u00e8re Page.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/15\/avant-gout-pour-le-aew-dynamite-du-15-mars-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir Dynamite, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"L4l3rr3C61\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/15\/avant-gout-pour-le-aew-dynamite-du-15-mars-2023\/\">Vid\u00e9os et Programme pour le AEW Dynamite du 15 Mars 2023!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vid\u00e9os et Programme pour le AEW Dynamite du 15 Mars 2023!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/15\/avant-gout-pour-le-aew-dynamite-du-15-mars-2023\/embed\/#?secret=1GOWiAP7WD#?secret=L4l3rr3C61\" data-secret=\"L4l3rr3C61\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Dynamite Winnipeg au Canada, 15 mars 2023 Les commentateurs sont Taz, Tony Schiavone et Excalibur. &#8211; Le AEW Dynamite d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue . &#8211; Justin Roberts nous pr\u00e9sente&nbsp;MJF qui arrive sur le ring pour c\u00e9l\u00e9brer son anniversaire pour ce \u00a0\u00bbRe-Bar Mitzvah Celebration\u00a0\u00bb. MJF dit qu&rsquo;il sait que les&#8230;<\/p>\n","protected":false},"author":4,"featured_media":81558,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,30,4,21,49],"tags":[],"ppma_author":[292],"class_list":["post-81547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-ex-wwe","category-news","category-resultats","category-roh"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=81547"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81547\/revisions"}],"predecessor-version":[{"id":81559,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81547\/revisions\/81559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/81558"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=81547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=81547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=81547"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=81547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}