{"id":81439,"date":"2023-03-14T13:57:44","date_gmt":"2023-03-14T17:57:44","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=81439"},"modified":"2023-03-14T13:57:46","modified_gmt":"2023-03-14T17:57:46","slug":"the-undertaker-a-la-wwe-sans-vince-mcmahon-ce-dernier-lui-envoyait-des-textos-avant-de-prendre-sa-retraite-lannee-derniere-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/03\/14\/the-undertaker-a-la-wwe-sans-vince-mcmahon-ce-dernier-lui-envoyait-des-textos-avant-de-prendre-sa-retraite-lannee-derniere-et-plus\/","title":{"rendered":"The Undertaker \u00e0 la WWE sans Vince McMahon! Ce dernier lui envoyait des textos avant de prendre sa retraite l\u2019ann\u00e9e derni\u00e8re, et plus!"},"content":{"rendered":"\n<p>The Undertaker dit qu\u2019une WWE sans le pr\u00e9sident ex\u00e9cutif Vince McMahon est difficile \u00e0 imaginer.<\/p>\n\n\n\n<p>Taker a r\u00e9cemment parl\u00e9 avec Ariel Helwani et s\u2019est souvenu que McMahon lui avait envoy\u00e9 un SMS la veille de son annonce de sa retraite en juillet 2022. Taker a dit qu\u2019il savait que Vince ne resterait pas \u00e0 l\u2019\u00e9cart.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab Il m\u2019a appel\u00e9 la veille de l\u2019annonce [de sa retraite] et nous nous sommes disput\u00e9s parce que je pensais qu\u2019il me harcelait,\u00a0J\u2019ai dit:\u00a0\u00ab\u00a0<em> Il n\u2019y a aucun moyen, il n\u2019y a absolument aucun moyen que vous vous \u00e9loigniez.<\/em>&lsquo; Nous avons fini par nous y attaquer un peu. Finalement, je me suis dit &lsquo;<em>d\u2019accord, d\u2019accord<\/em>&lsquo;. Effectivement, le lendemain, Vince a d\u00e9missionn\u00e9, mais je savais qu\u2019il n\u2019y avait aucun moyen qu\u2019il reste \u00e0 l\u2019\u00e9cart. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<p>McMahon est revenu en tant que pr\u00e9sident ex\u00e9cutif en janvier et il a \u00e9t\u00e9 rapport\u00e9 qu\u2019il n\u2019est l\u00e0 que pour diriger une vente potentielle de la soci\u00e9t\u00e9 et peut-\u00eatre les nouveaux accords RAW et SmackDown TV. Taker ne pense pas que ce sera si facile parce que Vince a fait de la WWE ce qu\u2019elle est aujourd\u2019hui.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab&nbsp;M\u00eame dans ce r\u00f4le, je pense que ce sera difficile pour lui&nbsp;\u00bb, a d\u00e9clar\u00e9 Taker. \u00ab&nbsp;Je veux dire, c\u2019est son b\u00e9b\u00e9, mec, c\u2019est lui qui a cr\u00e9\u00e9 tout \u00e7a. Je sais qu\u2019il veut s\u2019assurer que ces contrats t\u00e9l\u00e9vis\u00e9s et tout sont faits de la bonne fa\u00e7on et pour le moment, c\u2019est sa seule motivation, mais c\u2019est Vince McMahon, je ne sais pas, nous verrons o\u00f9 cela nous m\u00e8nera. Une WWE sans Vince est difficile \u00e0 imaginer.&nbsp;\u00bb<\/p>\n\n\n\n<p><\/p>\n<\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>The Undertaker dit qu\u2019une WWE sans le pr\u00e9sident ex\u00e9cutif Vince McMahon est difficile \u00e0 imaginer. Taker a r\u00e9cemment parl\u00e9 avec Ariel Helwani et s\u2019est souvenu que McMahon lui avait envoy\u00e9 un SMS la veille de son annonce de sa retraite en juillet 2022. Taker a dit qu\u2019il savait que Vince ne resterait pas \u00e0 l\u2019\u00e9cart&#8230;.<\/p>\n","protected":false},"author":665,"featured_media":81504,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-81439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=81439"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81439\/revisions"}],"predecessor-version":[{"id":81505,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81439\/revisions\/81505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/81504"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=81439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=81439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=81439"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=81439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}