{"id":81180,"date":"2023-03-03T21:57:47","date_gmt":"2023-03-04T02:57:47","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=81180"},"modified":"2023-03-07T15:42:34","modified_gmt":"2023-03-07T20:42:34","slug":"resultats-et-video-pour-le-wwe-friday-night-smackdown-du-3-mars-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/03\/03\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-3-mars-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 3 Mars 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/03\/avant-gout-pour-le-wwe-friday-night-smackdown-du-3-mars-2023\/\">Pour voir ce Smackdown, cliquez ici<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE SmackDown Washington, DC, 3 mars 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Michael Cole et Wade Barrett.<\/p>\n\n\n\n<p>&#8211; Le  WWE Friday Night SmackDown, d\u00e9bute avec Roman Reigns qui arrive sur le ring avec Jimmy Uso, Solo Sikoa ainsi que Paul Heyman. Reigns demande \u00e0 Washington DC de le reconnaitre&#8230; puis la musique de Cody Rhodes retentit ! Le vainqueur du Royal Rumble 2023 fait son entr\u00e9e puis se met face \u00e0 la Bloodline, c&rsquo;est sa premi\u00e8re apparition \u00e0 SmackDown depuis 7 ans, note Michael Cole.<\/p>\n\n\n\n<p>Cody Rhodes dit \u00eatre l\u00e0 pour parler d&rsquo;homme \u00e0 homme avec son adversaire de WrestleMania, le reste de la Bloodline n&rsquo;a pas besoin d&rsquo;\u00eatre sur le ring. Roman Reigns demande \u00e0 la Bloodline de quitter le ring puis demande \u00e0 Cody Rhodes ce dont il veut parler, apr\u00e8s avoir l\u00e2ch\u00e9 ses deux ceintures. Cody Rhodes affirme que Roman Reigns est une montagne impossible \u00e0 gravir, mais les gens lui ont dit qu&rsquo;il restera la doublure de Randy Orton, qu&rsquo;il restera toujours Stardust, ou que ses amis et lui ne pouvaient pas accueillir 10 000 fans pour un petit show ind\u00e9pendant. Roman Reigns parait impossible&#8230; mais pas pour lui !<\/p>\n\n\n\n<p>Roman Reigns lui demande s&rsquo;il a d\u00e9j\u00e0 catch\u00e9 pour l&rsquo;un de ces titres ? Il a d\u00e9j\u00e0 catch\u00e9 dans le Main Event d&rsquo;un WrestleMania ? Lui, il a d\u00e9j\u00e0 fait tout \u00e7a. Le champion parle ensuite du p\u00e8re de Cody Rhodes et dit n&rsquo;avoir rien de mal \u00e0 dire sur Dusty qui lui a donn\u00e9 beaucoup de conseils. Cody veut savoir ce que son p\u00e8re disait sur lui ? Il ne disait rien sur lui ! Et s&rsquo;il y a quelque chose que son p\u00e8re ne lui a pas apprise, Reigns le fera. Roman Reigns tend sa main mais Cody Rhodes pr\u00e9f\u00e8re r\u00e9pondre : Roman Reigns est peut-\u00eatre le fils que Dusty a toujours voulu, alors Cody doit le battre dans le Main Event de WrestleMania&#8230; que le meilleur gagne.<\/p>\n\n\n\n<p>Les deux catcheurs se serrent la main puis Roman Reigns quitte le ring avec ses deux ceintures.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Liv Morgan vs Rhea Ripley (accompagn\u00e9e par Dominik Mysterio)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Rhea Ripley fait son RipTide sur Liv Morgan suivi de sa soumission Inverted Cloverleaf pour faire taper son adversaire.<\/p>\n\n\n\n<p><strong>Gagnante : Rhea Ripley<\/strong><\/p>\n\n\n\n<p>&#8211; Dans le vestiaire de la Bloodline, Roman Reigns demande \u00e0 Jimmy Uso s&rsquo;il a parl\u00e9 avec son fr\u00e8re. Jimmy r\u00e9pond affirmativement, mais Jey a besoin d&rsquo;un peu de temps. Roman Reigns lui dit qu&rsquo;il n&rsquo;est pas patient. Jimmy r\u00e9pond qu&rsquo;il va le dire \u00e0 Jey.<\/p>\n\n\n\n<p>&#8211; On revoit ce qu&rsquo;il s&rsquo;est pass\u00e9 la semaine derni\u00e8re avec Rey Mysterio et Karrion Kross.<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Santos Escobar croise Dominik Mysterio et Rhea Ripley. Il leur dit que Rey Mysterio aurait d\u00fb le frapper la semaine derni\u00e8re ! Lui, il peut le faire, alors Dominik peut aller sur le ring avec lui tout de suite.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Santos Escobar vs Dominik Mysterio<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Rhea Ripley fait sa RipTide sur Santos Escobar \u00e0 l&rsquo;ext\u00e9rieur du ring, dans le dos de l&rsquo;arbitre, puis Dominik Mysterio monte sur la troisi\u00e8me corde et fait un Frog Splash sur Santos Escobar pour la victoire par tomb\u00e9.<\/p>\n\n\n\n<p><strong>Gagnant : Dominik Mysterio<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Dominik d\u00e9chire le masque de Rey Mysterio que Santos Escobar avait ramen\u00e9 avec lui. La musique de Rey Mysterio retentit et il vient pour r\u00e9cup\u00e9rer son masque. Dominik fait tomber le masque puis frappe son p\u00e8re !<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"font-size:25px\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=81179\">Pour la suite de Smackdown, cliquez ici<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"cOsCL3YJLo\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/03\/deuxieme-heure-de-smackdown-62\/\">Deuxi\u00e8me heure de Smackdown!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Deuxi\u00e8me heure de Smackdown!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/03\/03\/deuxieme-heure-de-smackdown-62\/embed\/#?secret=1KwuOPhNf3#?secret=cOsCL3YJLo\" data-secret=\"cOsCL3YJLo\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE SmackDown Washington, DC, 3 mars 2023 Les commentateurs sont Michael Cole et Wade Barrett. &#8211; Le WWE Friday Night SmackDown, d\u00e9bute avec Roman Reigns qui arrive sur le ring avec Jimmy Uso, Solo Sikoa ainsi que Paul Heyman. Reigns demande \u00e0 Washington DC de le reconnaitre&#8230; puis la musique de Cody Rhodes retentit !&#8230;<\/p>\n","protected":false},"author":609,"featured_media":81186,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,87,36,23],"tags":[],"ppma_author":[295],"class_list":["post-81180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-road-to-wrestlemania","category-smackdown","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=81180"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81180\/revisions"}],"predecessor-version":[{"id":81194,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81180\/revisions\/81194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/81186"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=81180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=81180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=81180"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=81180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}