{"id":81007,"date":"2023-02-27T05:54:00","date_gmt":"2023-02-27T10:54:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=81007"},"modified":"2023-02-27T16:32:48","modified_gmt":"2023-02-27T21:32:48","slug":"brutus-beefcake-raconte-comment-il-a-obtenu-son-nom-de-catcheur","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/02\/27\/brutus-beefcake-raconte-comment-il-a-obtenu-son-nom-de-catcheur\/","title":{"rendered":"Brutus Beefcake raconte comment il a obtenu son nom de catcheur!"},"content":{"rendered":"\n<p>Dans une interview avec\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/podcasts.apple.com\/us\/podcast\/hacksaw-beefcake-the-four-leaf-clover\/id767016946?i=1000601052171\" target=\"_blank\">Talk is Jericho<\/a>, Ed Leslie, mieux connu sous le nom de Brutus Beefcake, a parl\u00e9 de la fa\u00e7on dont il a obtenu son nom de catcheur, Brutus &lsquo;The Barber&rsquo; Beefcake.<\/p>\n\n\n\n<p>Bien qu\u2019il ait utilis\u00e9 de nombreux autres noms au fil des ans, c\u2019est celui pour lequel il est le plus connu. Linda McMahon, la femme de Vince McMahon, lui a donn\u00e9 le nom.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0La femme de Vince a imagin\u00e9 le nom &lsquo;Beefcake&rsquo;. C\u2019est comme \u00e7a que \u00e7a s\u2019est pass\u00e9. Hulk et Vince \u00e9taient assis dans le bureau &#8230; [et] Hulk dit : \u00ab Et Brutus ? Qu\u2019en est-il de Brutus Beefcake? Je devais faire preuve d\u2019une vraie cr\u00e9ativit\u00e9. Personne n\u2019a jamais \u00e9t\u00e9 barbier dans notre entreprise, vous savez? Donc, c\u2019est comme, d\u2019accord, qu\u2019est-ce que je peux faire? D\u2019accord, chaque fois que je lutte contre un gars, je l\u2019endors. Je vais lui couper les cheveux. Cela ne s\u2019est certainement jamais produit dans notre entreprise auparavant, et ne s\u2019est pas vraiment produit depuis. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans une interview avec\u00a0Talk is Jericho, Ed Leslie, mieux connu sous le nom de Brutus Beefcake, a parl\u00e9 de la fa\u00e7on dont il a obtenu son nom de catcheur, Brutus &lsquo;The Barber&rsquo; Beefcake. Bien qu\u2019il ait utilis\u00e9 de nombreux autres noms au fil des ans, c\u2019est celui pour lequel il est le plus connu. Linda&#8230;<\/p>\n","protected":false},"author":665,"featured_media":81022,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,30,77,4],"tags":[],"ppma_author":[289],"class_list":["post-81007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-ex-wwe","category-hall-of-fame","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=81007"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81007\/revisions"}],"predecessor-version":[{"id":81023,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/81007\/revisions\/81023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/81022"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=81007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=81007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=81007"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=81007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}