{"id":80559,"date":"2023-02-14T15:22:00","date_gmt":"2023-02-14T20:22:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=80559"},"modified":"2023-02-14T16:25:46","modified_gmt":"2023-02-14T21:25:46","slug":"tony-khan-partage-ce-quil-ferait-sil-possedait-une-autre-federation-de-lutte","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/02\/14\/tony-khan-partage-ce-quil-ferait-sil-possedait-une-autre-federation-de-lutte\/","title":{"rendered":"Tony Khan partage ce qu&rsquo;il ferait s&rsquo;il poss\u00e9dait une autre f\u00e9d\u00e9ration de lutte!"},"content":{"rendered":"\n<p>Le pr\u00e9sident de la All Elite Wrestling et \u00e9galement de la   Ring Of Honnor, Tony Khan, a expliqu\u00e9 comment il travail avec deux promotions diff\u00e9rentes et ce qu&rsquo;il ferait s&rsquo;il poss\u00e9dait une troisi\u00e8me promotion tout en apparaissant sur Bex &amp; Buster.<\/p>\n\n\n\n<p>Il pense qu&rsquo;avoir une autre promotion serait difficile. Cependant, s&rsquo;il le faisait, il s\u00e9parerait les listes.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00abSi je poss\u00e9dais une autre soci\u00e9t\u00e9 de lutte en plus des deux que je poss\u00e8de d\u00e9j\u00e0, ce serait tr\u00e8s difficile, mais je pense que nous voudrions maintenir des listes s\u00e9par\u00e9es, tout comme j&rsquo;ai essay\u00e9 de garder AEW et Ring of Honor l\u00e0 o\u00f9 il y a un croisement entre le entreprises, mais les deux ont une solide activit\u00e9 de t\u00e9l\u00e9vision \u00e0 la carte et AEW a une excellente t\u00e9l\u00e9vision.<\/p>\n<\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00ab\u00a0Bient\u00f4t, j&rsquo;aurai plus \u00e0 dire sur quand et o\u00f9 la t\u00e9l\u00e9vision hebdomadaire de Ring of Honor sera sur HonorClub et, \u00e0 l&rsquo;avenir, quand et o\u00f9 nous allons enregistrer ces \u00e9missions.<\/p>\n\n\n\n<p>\u00ab\u00a0Il y a un exemple de ce que nous ferions pour garder le secteur de la t\u00e9l\u00e9vision \u00e0 la carte s\u00e9par\u00e9, mais en ayant un certain croisement. Ce serait certainement diff\u00e9rent s&rsquo;il s&rsquo;agissait d&rsquo;une autre entreprise.<\/p>\n\n\n\n<p>\u00ab\u00a0Avec AEW et Ring of Honor, je suis tr\u00e8s content de ce que nous faisons. Certes, s&rsquo;il y avait d&rsquo;autres opportunit\u00e9s qui se pr\u00e9sentaient en termes d&rsquo;acquisitions, alors je serais certainement int\u00e9ress\u00e9 par (elles).<\/p>\n<\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la All Elite Wrestling et \u00e9galement de la Ring Of Honnor, Tony Khan, a expliqu\u00e9 comment il travail avec deux promotions diff\u00e9rentes et ce qu&rsquo;il ferait s&rsquo;il poss\u00e9dait une troisi\u00e8me promotion tout en apparaissant sur Bex &amp; Buster. Il pense qu&rsquo;avoir une autre promotion serait difficile. Cependant, s&rsquo;il le faisait, il s\u00e9parerait&#8230;<\/p>\n","protected":false},"author":609,"featured_media":80560,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,22,4,49],"tags":[],"ppma_author":[295],"class_list":["post-80559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-indy","category-news","category-roh"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/80559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=80559"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/80559\/revisions"}],"predecessor-version":[{"id":80561,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/80559\/revisions\/80561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/80560"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=80559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=80559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=80559"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=80559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}