{"id":80314,"date":"2023-02-09T04:19:00","date_gmt":"2023-02-09T09:19:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=80314"},"modified":"2023-02-09T15:16:10","modified_gmt":"2023-02-09T20:16:10","slug":"dossier-tres-complet-sur-jerry-lawler-avec-les-mises-a-jour-sur-la-sante-comment-le-tout-est-arrive-et-des-details-medicaux-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/02\/09\/dossier-tres-complet-sur-jerry-lawler-avec-les-mises-a-jour-sur-la-sante-comment-le-tout-est-arrive-et-des-details-medicaux-et-plus\/","title":{"rendered":"Dossier tr\u00e8s complet sur Jerry Lawler avec les mises \u00e0 jour sur la sant\u00e9, comment le tout est arriv\u00e9 et des d\u00e9tails m\u00e9dicaux et plus!"},"content":{"rendered":"\n<p>Il y a des rapports contradictoires sur \u00ab&nbsp;l\u2019\u00e9pisode m\u00e9dical grave&nbsp;\u00bb que le Hall of Famer de la WWE, Jerry Lawler, a subi lundi soir, mais le mot est que son \u00e9tat s\u2019am\u00e9liore.<\/p>\n\n\n\n<p>Comme indiqu\u00e9, il a \u00e9t\u00e9 rapport\u00e9 mardi que Lawler avait subi \u00ab\u00a0un \u00e9pisode m\u00e9dical grave\u00a0\u00bb,  \u00e0 son condo \u00e0 Fort Myers, en Floride, lundi et qu\u2019il avait d\u00fb \u00eatre hospitalis\u00e9. <\/p>\n\n\n\n<p>Lawler \u00e9tait sorti avec des amis pour le d\u00e9jeuner plus t\u00f4t dans la journ\u00e9e, et quelque temps apr\u00e8s, il est tomb\u00e9 malade et a \u00e9t\u00e9 transport\u00e9 d\u2019urgence \u00e0 l\u2019h\u00f4pital. Il a ensuite \u00e9t\u00e9 rapport\u00e9 par Action News 5 \u00e0 Memphis que Lawler avait subi un accident vasculaire c\u00e9r\u00e9bral et qu\u2019il avait subi une intervention chirurgicale r\u00e9ussie, mais qu\u2019il \u00e9tait d\u00e9j\u00e0 en convalescence.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Dans une mise \u00e0 jour,\u00a0Dutch Mantell\u00a0a fourni plus de d\u00e9tails sur l\u2019\u00e9tat du roi apr\u00e8s avoir parl\u00e9 avec le fils de Lawler, Kevin, qui avait parl\u00e9 avec les m\u00e9decins de son p\u00e8re. Mantell a d\u00e9clar\u00e9 qu\u2019il avait \u00e9t\u00e9 confirm\u00e9 que Lawler avait subi un accident vasculaire c\u00e9r\u00e9bral et qu\u2019il avait perdu la sensation du c\u00f4t\u00e9 droit, mais que la sensation \u00e9tait revenue et s\u2019am\u00e9liorait.<\/p>\n\n\n\n<p>Il a \u00e9galement \u00e9t\u00e9 dit que Lawler souffrait d\u2019une paralysie du c\u00f4t\u00e9 gauche lorsque l\u2019accident vasculaire c\u00e9r\u00e9bral s\u2019est produit, qu\u2019il reprenait en charge. Mantell a ajout\u00e9 que Lawler avait \u00e9galement souffert de paralysie du c\u00f4t\u00e9 droit imm\u00e9diatement apr\u00e8s l\u2019AVC, mais vers la fin de l\u2019apr\u00e8s-midi, il avait retrouv\u00e9 l\u2019usage de son bras. <\/p>\n\n\n\n<p>Selon Mantell, le discours de Lawler \u00e9tait toujours affect\u00e9 vers ce soir, mais les m\u00e9decins s\u2019attendaient \u00e0 ce que cela revienne et qu\u2019il faille plus de temps pour s\u2019am\u00e9liorer. L\u2019\u00e9tat de Lawler a \u00e9t\u00e9 d\u00e9crit comme bon, et il devrait se remettre de l\u2019\u00e9pisode.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Dave Meltzer a rapport\u00e9 plus tard que Lawler avait souffert d\u2019un blocage sanguin du c\u00f4t\u00e9 droit de son cerveau et non d\u2019un accident vasculaire c\u00e9r\u00e9bral. Le rapport indique \u00e9galement que Lawler a \u00e9t\u00e9 retrouv\u00e9 face contre terre \u00e0 l\u2019ext\u00e9rieur de sa maison lundi, puis il a \u00e9t\u00e9 imm\u00e9diatement transport\u00e9 d\u2019urgence dans un h\u00f4pital local.<\/p>\n\n\n\n<p>Lawler se serait r\u00e9veill\u00e9 de l\u2019op\u00e9ration et aurait essay\u00e9 de parler, mais n\u2019a pas pu. Il est toujours hospitalis\u00e9 \u00e0 Fort Myers.<\/p>\n\n\n\n<p>Il a \u00e9galement \u00e9t\u00e9 not\u00e9 par Meltzer que le fils de Lawler, Kevin, se rendait en Floride pour \u00eatre avec son p\u00e8re, et il \u00e9tait en contact avec la WWE.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Lawler, \u00e2g\u00e9 de 73 ans, vient de travailler sur le pr\u00e9-show du WWE Royal Rumble Kickoff et a fait une signature publique en Floride ce week-end.<\/p>\n\n\n\n<p>Lawler avait d\u00e9j\u00e0 subi un accident vasculaire c\u00e9r\u00e9bral fin mars 2018 et il avait \u00e9galement subi une crise cardiaque massive alors qu\u2019il commentait RAW en septembre 2012 \u00e0 Montr\u00e9al au Centre Bell, l\u00e0 ou la WWE sera pour Elimination Chamber. <\/p>\n\n\n\n<p>La bonne nouvelle, il serait compl\u00e8tement r\u00e9tabli.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il y a des rapports contradictoires sur \u00ab&nbsp;l\u2019\u00e9pisode m\u00e9dical grave&nbsp;\u00bb que le Hall of Famer de la WWE, Jerry Lawler, a subi lundi soir, mais le mot est que son \u00e9tat s\u2019am\u00e9liore. Comme indiqu\u00e9, il a \u00e9t\u00e9 rapport\u00e9 mardi que Lawler avait subi \u00ab\u00a0un \u00e9pisode m\u00e9dical grave\u00a0\u00bb, \u00e0 son condo \u00e0 Fort Myers, en Floride,&#8230;<\/p>\n","protected":false},"author":665,"featured_media":80340,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77,4,23],"tags":[],"ppma_author":[289],"class_list":["post-80314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hall-of-fame","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/80314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=80314"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/80314\/revisions"}],"predecessor-version":[{"id":80341,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/80314\/revisions\/80341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/80340"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=80314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=80314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=80314"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=80314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}