{"id":79897,"date":"2023-01-28T20:47:00","date_gmt":"2023-01-29T01:47:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=79897"},"modified":"2023-02-01T22:54:22","modified_gmt":"2023-02-02T03:54:22","slug":"resultats-et-video-pour-le-wwe-royal-rumble-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/01\/28\/resultats-et-video-pour-le-wwe-royal-rumble-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Royal Rumble 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/01\/28\/carte-et-infos-pour-voir-le-wwe-royal-rumble-2023\/\">Pour voir le Royal Rumble, cliquez ici.<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE Royal Rumble San Antonio, Texas, 28 janvier 2023!<\/strong><\/p>\n\n\n\n<p>&#8211; Le Kickoff du Royal Rumble 2023 commence avec le panel compos\u00e9 de Kayla Braxton, Booker T, Jerry Lawler, Kevin Patrick et Peter Rosenberg qui nous souhaitent la bienvenue.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente&nbsp;l&rsquo;interview de Roman Reigns \u00e0 Jimmy Fallon&nbsp;hier soir sur le Royal Rumble.<\/p>\n\n\n\n<p>&#8211; En coulisse, on voit&nbsp;<strong>le Bloodline qui est en silence<\/strong>. Reigns dit que lorsqu&rsquo;il donne un ordre, le Bloodline doit suivre. C&rsquo;est une recette qui fonctionne, c&rsquo;est simple. Il donne une instruction et Zayn ne peut pas suivre. Pourquoi il n&rsquo;arrive pas \u00e0 le faire ? Sami allait r\u00e9pondre, mais Jey Uso le coupe et dit que c&rsquo;est lui. Jey dit que Adam Pearce a sorti les deux du match. Reigns \u00e9tait occup\u00e9 avec son interview, il ne pouvait pas lui parler, alors il a appel\u00e9 Sami Zayn pour avoir son aide pour la famille. Zayn \u00e9tait l\u00e0 pour la famille. Reigns demande si c&rsquo;est s\u00e9rieux. Jey approuve. Reigns dit qu&rsquo;il faut penser \u00e0 ce soir, c&rsquo;est le moment de se battre. Plan de match, les Usos doivent surveiller leur arri\u00e8re, c&rsquo;est une grosse soir\u00e9e.&nbsp;Pour Zayn, il doit le suivre pendant toute la soir\u00e9e. Il va montrer \u00e0 Zayn comment faire et les Usos restent en backstage&nbsp;car ce soir c&rsquo;est la soir\u00e9e de Zayn. Zayn dit qu&rsquo;il est pr\u00eat.<\/p>\n\n\n\n<p>&#8211; En coulisse, Greg Miller du show This is Awesome sur le WWE Network retrouve JBL. JBL commence \u00e0 critiquer sa valeur en disant qu&rsquo;il brancherait son t\u00e9l\u00e9phone sur sa machine pour le garder en vie. JBL change de sujet en disant qu&rsquo;il veut \u00eatre son ami, mais lui lance une tarte au visage.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur le retour de Cody Rhodes.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Kevin Owens et le Bloodline.<\/p>\n\n\n\n<p>&#8211; Le Kickoff se termine avec les derniers commentaires du panel.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>La carte principale du Royal Rumble d\u00e9bute  avec la vid\u00e9o d&rsquo;ouverture avec le chanteur Hardy pour la narration. Les commentateurs nous souhaitent la bienvenue et la musique de Pat McAfee commence. McAfee retrouve sa place comme commentateur.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Royal Rumble Masculin<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quelques Faits saillants :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gunther est le premier participant. Sheamus arrive en second.<\/li>\n\n\n\n<li>Johnny Gargano fait son retour de blessure en #5.<\/li>\n\n\n\n<li>Brock Lesnar arrive en #12 et commence \u00e0 sortir Santos Escobar, Angelo Dawkins, Chad Gable.<\/li>\n\n\n\n<li>Bobby Lashley arrive en #13 et arrive \u00e0 sortir Lesnar du ring ! Lesnar est furieux et lance une marche d&rsquo;acier. Baron Corbin arrive en #14, mais Lesnar le booque en ringside pour lui faire un F5. Les officiels arrivent et Lesnar accepte de partir.<\/li>\n\n\n\n<li>#17, la musique de Rey Mysterio commence, mais personne n&rsquo;arrive. En #18, Dominik Mysterio arrive avec le masque de Rey sur la t\u00eate.<\/li>\n\n\n\n<li>Booker T arrive en #21, mais Booker T fait sa Spin-A-Roonie et Gunther en profite pour le sortir.<\/li>\n\n\n\n<li>Edge fait son retour en #24 et \u00e9limine Finn Balor et Damian Priest. Edge veut sortir Dominik, mais Priest et Balor tirent Edge en bas du ring pour le sortir. Edge est furieux et va se battre avec Priest et Balor sur la rampe. Rhea Ripley arrive pour cogner Edge ! Beth Phoenix arrive et fait un Spear \u00e0 Ripley. Les officiels arrivent pour les s\u00e9parer.<\/li>\n\n\n\n<li>Logan Paul arrive en #29 et finalement Cody Rhodes en #30.<\/li>\n<\/ul>\n\n\n\n<p>En fin de match, Cody \u00e9limine Theory avec une Clothesline. Il reste Rollins, Gunther et Rhodes sur le ring. Rollins et Rhodes \u00e9changent les coups. Logan Paul remonte sur le ring et lance Rollins en bas du ring pour surprendre tout le monde ! Rhodes bloque un coup de Paul et lui fait un Cross Rhodes et le lance en bas du ring. Il reste Rhodes et Gunther. Les deux \u00e9changent les coups. Ensuite, Gunther le claque sur la poitrine et le fait passer sur le tablier. Cody le repousse et monte sur le coin, mais Gunther le frappe et monte sur le coin avec lui pour faire une Superplex. Rhodes retrouve de l&rsquo;\u00e9nergie et commence \u00e0 frapper Gunther et lui fait un Springboard Cutter. Ensuite, Rhodes fait son Cross Rhodes et le sort du ring avec une Clothesline.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Gagnant : Cody Rhodes<\/strong><\/p>\n\n\n\n<p><em>Cody Rhodes aura une chance au titre de son choix lors de WrestleMania 39.<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Cody c\u00e9l\u00e8bre sa victoire sous les pyros.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p class=\"has-large-font-size\"><strong>Pitch Black Match<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>LA Knight vs Bray Wyatt<\/strong><\/p>\n\n\n\n<p>En fin de match, Knight veut frapper Waytt avec un Kendo Stick, mais Wyatt le bloque avec un Sister Abigail pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Bray Wyatt<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Wyatt se met un masque sur la t\u00eate. Knight prend la fuite dans la foule, mais Wyatt le pourchasse. Knight veut le repousser avec un Kendo Stick, mais Wyatt reste debout. Wyatt lui applique sa soumission Mandible Claw. Uncle Howdy sort d&rsquo;un podium et se lance \u00e0 plus de 10m en Splash sur Knight \u00e0 travers le plancher.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente la vid\u00e9o promo de WrestleMania 39 qui aura lieu dans 63 jours.<\/p>\n\n\n\n<p>&#8211; La WWE annonce 51 338 fans dans la salle pour ce soir.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat F\u00e9minin de RAW<\/strong><\/p>\n\n\n\n<p><strong>Alexa Bliss vs Bianca Belair <\/strong>\u00a9<\/p>\n\n\n\n<p>En fin de match, Bliss veut faire un Sister Abigail, mais Belair la renverse en KOD pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Bianca Belair<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Belair c\u00e9l\u00e8bre sur la rampe. Une vid\u00e9o sur Bray Wyatt commence et Bliss reste sans mot. On entend Uncle Howdy lui demander si elle est en contr\u00f4le maintenant. <\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente la vid\u00e9o de Elimination Chamber 2023 \u00e0 Montr\u00e9al avec Brock Lesnar.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p class=\"has-large-font-size\"><strong>Royal Rumble F\u00e9minin<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Quelques Faits saillants :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rhea Ripley arrive en premier et Liv Morgan en second.<\/li>\n\n\n\n<li>B-Fab arrive en #7 pour faire son premier match t\u00e9l\u00e9vis\u00e9 en roster principal, mais Ripley la sort directement du ring.<\/li>\n\n\n\n<li>En #17 Asuka fait son retour sous une nouvelle musique et style.<\/li>\n\n\n\n<li>Doudrop revient en Piper Niven pour le #18.<\/li>\n\n\n\n<li>Chelsea Green fait son retour en #20, mais elle se fait \u00e9liminer directement par Ripley.<\/li>\n\n\n\n<li>Becky sort Kai et Sky du ring, mais Bayley en profite pour la pousser en bas du ring. Liv Morgan en profite \u00e0 son tour pour pousser Bayley en bas du ring ! Damage CTRL et Lynch \u00e9changent les coups en ringside.<\/li>\n\n\n\n<li>Nia Jax fait son retour en 30e, mais les catcheuses font \u00e9quipe pour la sortir.<\/li>\n<\/ul>\n\n\n\n<p>En fin de match, il reste Asuka, Ripley, Nikki Cross et Liv Morgan. Nikki s&rsquo;attaque \u00e0 Asuka, mais Morgan en profite pour porter un coup de pied \u00e0 Nikki et la sortir du ring. Ensuite, Ripley et Morgan s&rsquo;affrontent sur le tablier. Asuka veut en profiter, mais Ripley la bloque et l&rsquo;am\u00e8ne sur le tablier. Asuka veut faire son Mist, Ripley l&rsquo;\u00e9vite, Morgan le re\u00e7oit au visage, Ripley repousse Asuka en bas du ring. Riplety rel\u00e8ve Morgan, mais Morgan lui&nbsp; fait un Code Breaker. Riplet attrape un c\u00e2ble et la sort du ring avec un Head Scissors.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Rhea Ripley<\/em><\/p>\n\n\n\n<p><em>Ripley aura un match de championnat de son choix \u00e0 WrestleMania 39<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Ripley c\u00e9l\u00e8bre sa victoire sous les pyros.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Ripley c\u00e9l\u00e8bre sa victoire sous les pyros.<\/p>\n\n\n\n<p>&#8211; Hardy et son groupe arrivent sur le ring pour chanter \u00a0\u00bbSold Out\u00a0\u00bb.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Owens et Reigns.<\/p>\n\n\n\n<p><strong>WWE Universal Championship &#8211; Singles Match<\/strong><\/p>\n\n\n\n<p><strong>Kevin Owens vs Roman Reigns (c<em>) accompagn\u00e9 de Sami Zayn et Paul Heyman<\/em><\/strong><\/p>\n\n\n\n<p>Vers la fin, Owens se lance en Cannonball, mais Reigns le bloque en Superman Punch et le couvre, mais Owens r\u00e9siste \u00e0 deux. Reigns se lance en Spear, mais Owens le repousse contre le poteau. Owens lui fait un Superkick et monte sur le coin pour un Swenton et le couvrir, mais Reigns r\u00e9siste \u00e0 deux. Owens monte sur le coin, Reigns se rel\u00e8ve et les deux \u00e9changent les coups sur le coin. Owens le repousse et se lance en Moonsault, mais Reigns l&rsquo;\u00e9vite et lui fait un Spear pour le couvrir, mais Owens r\u00e9siste. Reigns se lance en Spear, mais Owens le bloque. Owens le prend en Stunner, mais Reigns le repousse sur l&rsquo;arbitre. Owens fait sa Pop Up Powerbomb sur Reigns et le couvre, mais l&rsquo;arbitre est K.O. Reigns en profite pour faire un Low Blow \u00e0 Owens. <\/p>\n\n\n\n<p>En fin de match, Reigns demande \u00e0 Sami Zayn de lui donner une chaise. Sami trouve une chaise et la donne \u00e0 Reigns avec un peu de retard. Owens en profite pour faire son Stunner et le couvre, mais Reigns r\u00e9siste. Owens le lance pour son finisher, mais Reigns le boque en Superman Punch et un Spear pour le couvrir, mais il r\u00e9siste encore. Owens roule en bas du ring, Sami dit \u00e0 Owens de rester au sol. Reigns lui fait un Spear \u00e0 travers la barricade. Reigns le pousse dos premier sur la marche d&rsquo;acier \u00e0 deux reprises. Reigns le ram\u00e8ne sur le ring et lui fait un Spear pour le compte de trois.<\/p>\n\n\n\n<p style=\"font-size:25px\"><em>Gagnant : Roman Reigns<\/em><\/p>\n\n\n\n<p>&nbsp; Le show se termine avec une c\u00e9l\u00e9bration de Roman Reigns et le Bloodline. Jey Uso veut donner un collier de fleurs \u00e0 Sami, mais Reigns l&rsquo;arr\u00eate. Le Bloodline s&rsquo;amuse \u00e0 rouer de coups Owens qui est d\u00e9j\u00e0 au sol. Solo Sikoa termine avec un Hip Attack sur la t\u00eate d&rsquo;Owens avec une chaise. Reigns sort les menottes pour attacher Owens \u00e0 un c\u00e2ble. Les Usos lui font une s\u00e9rie de Superkicks. <\/p>\n\n\n\n<p>Reigns veut frapper KO avec une chaise, mais Sami lui fait signe d&rsquo;arr\u00eater. Sami lui dit qu&rsquo;il n&rsquo;a pas besoin de faire \u00e7a puisqu&rsquo;il domine d\u00e9j\u00e0. Reigns donne la chaise \u00e0 Sami. Reigns dit qu&rsquo;il a tout donn\u00e9 \u00e0 Sami, Sami doit le faire s&rsquo;il veut \u00eatre dans la famille. Sami ne sait pas quoi aire. Reigns lui hurle dessus.&nbsp;<\/p>\n\n\n\n<p>Sami d\u00e9cide de frapper Reigns sur le dos&nbsp;! Jimmy Uso fait un Superkick sur Sami. Sikoa fait son Samoan Spike sur Sami.&nbsp;Jey d\u00e9cide de quitter le ring et ne pas participer \u00e0 l&rsquo;attaque sur Sami. Reigns commence une s\u00e9rie de coups de chaise sur Sami. Le show se termine avec le Bloodline qui quitte le ring.<\/p>\n\n\n\n<p><strong>Pour voir ce Royal Rumble, cliquez ici.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"693CqBt357\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/01\/28\/carte-et-infos-pour-voir-le-wwe-royal-rumble-2023\/\">Vid\u00e9os et Carte et pour voir le WWE Royal Rumble 2023 COMPLET!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vid\u00e9os et Carte et pour voir le WWE Royal Rumble 2023 COMPLET!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/01\/28\/carte-et-infos-pour-voir-le-wwe-royal-rumble-2023\/embed\/#?secret=i4uMppMnC8#?secret=693CqBt357\" data-secret=\"693CqBt357\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE Royal Rumble San Antonio, Texas, 28 janvier 2023! &#8211; Le Kickoff du Royal Rumble 2023 commence avec le panel compos\u00e9 de Kayla Braxton, Booker T, Jerry Lawler, Kevin Patrick et Peter Rosenberg qui nous souhaitent la bienvenue. &#8211; On pr\u00e9sente&nbsp;l&rsquo;interview de Roman Reigns \u00e0 Jimmy Fallon&nbsp;hier soir sur le Royal Rumble. &#8211; En coulisse,&#8230;<\/p>\n","protected":false},"author":4,"featured_media":79899,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45,21,71,23],"tags":[],"ppma_author":[292],"class_list":["post-79897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ppv-wwe","category-resultats","category-royal-rumble","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/79897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=79897"}],"version-history":[{"count":6,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/79897\/revisions"}],"predecessor-version":[{"id":80060,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/79897\/revisions\/80060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/79899"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=79897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=79897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=79897"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=79897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}