{"id":79820,"date":"2023-01-30T18:58:00","date_gmt":"2023-01-30T23:58:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=79820"},"modified":"2023-02-05T16:38:25","modified_gmt":"2023-02-05T21:38:25","slug":"vince-mcmahon-de-retour-au-siege-de-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/01\/30\/vince-mcmahon-de-retour-au-siege-de-la-wwe\/","title":{"rendered":"Vince McMahon de retour au si\u00e8ge de la WWE"},"content":{"rendered":"\n<p>Le pr\u00e9sident de la WWE, Vince McMahon, est de retour au si\u00e8ge de l\u2019entreprise.<\/p>\n\n\n\n<p>Un nouveau rapport de PWInsider note que McMahon a \u00e9t\u00e9 aper\u00e7u cette semaine au QG de la WWE \u00e0 Stamford, CT, indiquant qu\u2019il est de retour dans son ancien bureau.<\/p>\n\n\n\n<p>Il y a eu des rumeurs selon lesquelles Vince s\u2019entra\u00eenerait dans le gymnase de la Titan Tower pour retourner \u00e0 sa retraite cet \u00e9t\u00e9, mais c\u2019est la premi\u00e8re observation confirm\u00e9e de McMahon de retour au travail.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Il a \u00e9t\u00e9 rapport\u00e9 plus t\u00f4t ce mois-ci, juste apr\u00e8s le retour de McMahon dans l\u2019entreprise, comment des rumeurs non confirm\u00e9es l\u2019avaient \u00ab&nbsp;d\u00e9j\u00e0 envoy\u00e9 \u00e0 certains d\u00e9partements pour dire&nbsp;\u00bb qu\u2019ils faisaient mal les choses. Celles-ci semblent n\u2019\u00eatre que des rumeurs car elles n\u2019ont pas \u00e9t\u00e9 confirm\u00e9es par de multiples sources depuis lors.<\/p>\n\n\n\n<p>Il n\u2019y a pas eu de mise \u00e0 jour sur le retour possible de Vince dans la cr\u00e9ation de la WWE, qui est toujours dirig\u00e9e par le Chief Content Officer de la WWE, Triple H. Au dernier mot, Vince n\u2019avait assist\u00e9 \u00e0 aucun enregistrement de la WWE TV depuis son retour, y compris l\u2019enregistrement de RAW 30. Le dernier mot au sein de la soci\u00e9t\u00e9 a \u00e9galement d\u00e9clar\u00e9 que le PDG de la WWE, Nick Khan, \u00e9tait l\u2019homme qui dirigeait la soci\u00e9t\u00e9 et qu\u2019il prenait toutes les d\u00e9cisions finales. Vince, en tant que pr\u00e9sident \u00e0 titre officiel, ne travaille que sur la vente de la soci\u00e9t\u00e9 et des contrats de droits m\u00e9diatiques, les contrats actuels de RAW et de SmackDown TV expirant \u00e0 la fin du mois de septembre 2024.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la WWE, Vince McMahon, est de retour au si\u00e8ge de l\u2019entreprise. Un nouveau rapport de PWInsider note que McMahon a \u00e9t\u00e9 aper\u00e7u cette semaine au QG de la WWE \u00e0 Stamford, CT, indiquant qu\u2019il est de retour dans son ancien bureau. Il y a eu des rumeurs selon lesquelles Vince s\u2019entra\u00eenerait dans&#8230;<\/p>\n","protected":false},"author":665,"featured_media":80180,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-79820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/79820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=79820"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/79820\/revisions"}],"predecessor-version":[{"id":80181,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/79820\/revisions\/80181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/80180"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=79820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=79820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=79820"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=79820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}