{"id":79606,"date":"2023-01-21T01:22:00","date_gmt":"2023-01-21T06:22:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=79606"},"modified":"2023-01-22T18:22:07","modified_gmt":"2023-01-22T23:22:07","slug":"mick-foley-commente-le-retour-de-vince-mcmahon-et-dit-que-la-wwe-a-ete-vraiment-amusante-sous-triple-h","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/01\/21\/mick-foley-commente-le-retour-de-vince-mcmahon-et-dit-que-la-wwe-a-ete-vraiment-amusante-sous-triple-h\/","title":{"rendered":"Mick Foley commente le retour de Vince McMahon et dit que la WWE a \u00e9t\u00e9 vraiment amusante sous Triple H!"},"content":{"rendered":"\n<p>Mick Foley a quelques r\u00e9flexions sur le retour de Vince McMahon au sein du conseil d\u2019administration de la WWE.<\/p>\n\n\n\n<p>Le Hall of Famer a abord\u00e9 ce sujet lors de la derni\u00e8re \u00e9dition de son\u00a0<a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/abdullah-the-butcher\/id1610936969?i=1000595565224\" target=\"_blank\" rel=\"noreferrer noopener\">spectacle Foley Is Pod<\/a>, o\u00f9 il a lou\u00e9 le travail de Triple H pour avoir amen\u00e9 la compagnie dans une direction amusante et excitante apr\u00e8s la retraite de Vince en juillet dernier. D\u00e9couvrez ses r\u00e9flexions compl\u00e8tes sur le sujet dans les faits saillants ci-dessous.<\/p>\n\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><strong>Le retour de Vince est la deuxi\u00e8me retraite la plus courte de l\u2019histoire de la WWE apr\u00e8s la sienne :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>C\u2019est la deuxi\u00e8me retraite la plus courte de l\u2019histoire de la WWE [rires], apr\u00e8s la mienne, qui a dur\u00e9 six semaines. H\u00e9, regarde, je sais que JR m\u2019avait dit il y a des ann\u00e9es qu\u2019il \u00e9tait inquiet pour Vince \u00e0 la retraite parce qu\u2019il est prudent de dire que JR est un bourreau de travail. Il y a une connotation n\u00e9gative parce que vous appliquez tellement de vous-m\u00eame au travail. Mais m\u00eame JR, il a le football de l\u2019Oklahoma, il a des choses qu\u2019il aime dans sa vie. Je ne pense pas que Vince, Vince aime sa famille inconditionnellement, mais je parle de passe-temps. Il n\u2019y a pas de golf, rien de ce que vous associez habituellement aux hommes de son \u00e2ge. Pas de scrap-booking pour Vince. Pas d\u2019observation des oiseaux. Les affaires \u00e9taient tr\u00e8s, tr\u00e8s personnelles, comme sa vie tournait et sa famille tournait autour de l\u2019entreprise. C\u2019\u00e9tait donc l\u2019une de mes pr\u00e9occupations. Que fait-il pour faire? Il adore travailler. Je ne l\u2019imagine pas ne pas \u00eatre l\u00e0 dans cette position de gorille. Il semblerait que quelque chose n\u2019allait pas s\u2019il n\u2019\u00e9tait pas l\u00e0.<\/p><\/blockquote>\n\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><strong>Pense que la WWE a pris une direction vraiment amusante sous Triple H:<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>L\u2019entreprise a \u00e9t\u00e9 dans une tr\u00e8s bonne direction. Il y a une raison pour laquelle Jerry Lawler et Jerry Jarrett ont chang\u00e9 le livre tous les six mois. Que ce soit n\u00e9cessaire ou non, c\u2019\u00e9tait une paire d\u2019oreilles et d\u2019yeux frais sur le produit et ils ont tous mis leurs propres empreintes dessus. Je pense que Hunter a eu l\u2019occasion de le faire et c\u2019est une s\u00e9rie vraiment amusante, avec beaucoup d\u2019am\u00e9liorations. Je ne sais pas. Je ne serais pas l\u00e0 parce que c\u2019est la famille, et maintenant c\u2019est devenu une comp\u00e9tition. Je ne sais pas. On dirait qu\u2019il a la possibilit\u00e9 de devenir laid. J\u2019ai de la compassion pour Vince et je me soucie beaucoup de Vince en tant que personne. J\u2019ai eu des hauts et des bas avec lui au fil des ans, mais c\u2019\u00e9tait en grande partie du business. Je l\u2019ai toujours respect\u00e9, je l\u2019ai toujours vraiment aim\u00e9 et je veux m\u2019assurer que ce gars qui a tant compt\u00e9 pour ma vie est heureux. Voyons ce qui se passe. Il y a quelques mois, on m\u2019a dit que quelque chose pourrait se passer et maintenant c\u2019est en train de se produire. \u00c7a va \u00eatre int\u00e9ressant, c\u2019est s\u00fbr. Mais Vince arrive, vous parlez d\u2019un gars qui a litt\u00e9ralement vol\u00e9 la Mania de l\u2019ann\u00e9e derni\u00e8re avec le Stunner pour les \u00e2ges. D\u00e9sol\u00e9 Steve [rires].<\/p><\/blockquote>\n\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><strong>Si Vince apportera des changements maintenant qu\u2019il est de retour :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Je ne sais pas. C\u2019est Vince. C\u2019est dans sa nature de faire bouger les choses, non? Ce n\u2019\u00e9tait peut-\u00eatre pas le moyen le plus efficace d\u2019\u00e9crire un spectacle et de pr\u00e9senter un spectacle o\u00f9 un gentleman emm\u00e8ne un sharpie pendant six jours de dur labeur. Mais je crois que c\u2019est comme \u00e7a que Vince pense qu\u2019il travaille le mieux, sous pression. C\u2019est sa fa\u00e7on de faire. Je pense qu\u2019il aime l\u2019id\u00e9e de faire bouger les choses pour pouvoir s\u2019\u00e9panouir. Je ne sais pas si cela veut dire qu\u2019il va faire bouger les choses apr\u00e8s le Rumble, avant Mania, ou attendre sans titre apr\u00e8s, mais \u00e7a va \u00eatre int\u00e9ressant \u00e0 coup s\u00fbr.<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Mick Foley a quelques r\u00e9flexions sur le retour de Vince McMahon au sein du conseil d\u2019administration de la WWE. Le Hall of Famer a abord\u00e9 ce sujet lors de la derni\u00e8re \u00e9dition de son\u00a0spectacle Foley Is Pod, o\u00f9 il a lou\u00e9 le travail de Triple H pour avoir amen\u00e9 la compagnie dans une direction amusante&#8230;<\/p>\n","protected":false},"author":665,"featured_media":79657,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84,30,77,4,83,23],"tags":[],"ppma_author":[289],"class_list":["post-79606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecw","category-ex-wwe","category-hall-of-fame","category-news","category-wcw","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/79606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=79606"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/79606\/revisions"}],"predecessor-version":[{"id":79658,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/79606\/revisions\/79658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/79657"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=79606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=79606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=79606"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=79606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}