{"id":78885,"date":"2023-01-02T19:55:00","date_gmt":"2023-01-03T00:55:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=78885"},"modified":"2023-01-05T14:21:13","modified_gmt":"2023-01-05T19:21:13","slug":"resultats-et-video-pour-le-wwe-monday-night-raw-du-2-janvier-2023","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2023\/01\/02\/resultats-et-video-pour-le-wwe-monday-night-raw-du-2-janvier-2023\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 2 Janvier 2023!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/01\/02\/deux-matchs-de-championnata-ce-soir-pour-le-premier-wwe-monday-night-raw-de-2023\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce RAW, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p><strong>WWE RAW Nashville, Tennessee, 2 janvier 2023<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Corey Graves et Kevin Patrick.<\/p>\n\n\n\n<p>&#8211; Le WWE Monday Night  RAW d\u00e9bute avec&nbsp;le Bloodline qui arrive par la foule et qui balance un agent de s\u00e9curit\u00e9 au sol et prend le contr\u00f4le de RAW.  Jimmy Uso prend le casque du commentateur et dit que le Bloodline va prendre le contr\u00f4le de RAW. 2023 sera comme 2022 avec le Bloodline qui domine. <\/p>\n\n\n\n<p>Sami Zayn dit que c&rsquo;est un message pour tout le monde en coulisse. La musique de Kevin Owens commence et il arrive sur la sc\u00e8ne. Zayn dit qu&rsquo;il voit bien le micro de Owens, Owens ferait mieux de rester en silence car ils ne sont pas de bonne humeur ce soir. Ce soir c&rsquo;est une prise d&rsquo;otage hostile par le Bloodline. Zayn dit que tout ce qui arrive sera \u00e0 cause de Owens. Owens dit qu&rsquo;il avait quelque chose \u00e0 dire, mais apr\u00e8s avoir entendu Zayn il veut seulement aller le cogner au visage. Owens s&rsquo;approche du ring, mais Adam Pearce arrive avec des agents de s\u00e9curit\u00e9 pour l&rsquo;arr\u00eater.<\/p>\n\n\n\n<p>Pearce dit que le Bloodline n&rsquo;est pas l&rsquo;autorit\u00e9. La strat\u00e9gie du Bloodline a dur\u00e9e trop longtemps. Le Bloodline n&rsquo;a pas le droit d&rsquo;\u00eatre sur son ring. Pearce demande \u00e0 la s\u00e9curit\u00e9 de sortir la Bloodline du ring, mais Solo Sikoa cogne tous les agents un apr\u00e8s l&rsquo;autre. Owens d\u00e9cide d&rsquo;aller sur le ring, mais il ne peut rien faire quatre contre un. Pearce demande de l&rsquo;aide. Des catcheurs du roster de RAW d\u00e9barquent pour chasser le Bloodline du ring.&nbsp;Pearce dit que le Bloodline ne pourra pas partir si facilement. le Bloodline veut venir au boulot, alors il va les faire travailler&nbsp;car ils auront tous un match ce soir et c&rsquo;est officiel !<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, Byron Saxton dit que nous aurons le RAW Women&rsquo;s Championship juste apr\u00e8s. Il demande \u00e0 Bianca Belair comment sa relation avec Alexa a chang\u00e9. Belair dit qu&rsquo;elle n&rsquo;est pas la victime de l&rsquo;histoire. Alexa peut bl\u00e2mer Bray Wyatt comme elle veut, mais Alexa est sa propre personne. Elle va prouver pourquoi le titre f\u00e9minin revient \u00e0 l&rsquo;EST de la WWE.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, en coulisse, les catcheurs argumentent avec Adam Pearce pour affronter le Bloodline. Montez Ford dit que \u00e7a doit inclure les Street Profits. Owens dit que le Bloodline est ici pour lui. Elias dit que lui veut seulement affronter Solo, Solo a cass\u00e9 sa guitare, il veut un combat contre Solo. Pearce dit que Solo et Elias vont s&rsquo;affronter dans un Street Fight musical ce soir. Pour le reste, un Six-Man Tag, les Usos et Zayn contre les Street Profits et Owens. Pearce dit que pour les autres leur chance viendra une autre fois.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Championnat F\u00e9minin de RAW<\/strong><\/p>\n\n\n\n<p><strong>Alexa Bliss vs Bianca Belair <\/strong>\u00a9<\/p>\n\n\n\n<p>En fin dem atch, Bliss se fait distraire par un homme sous le masque du nouveau Fiend en ringside. Bliss monte sur le coin, mais un autre homme masqu\u00e9 la distrait. Le logo de Bray Wyatt apparait sur le TitanTron. <\/p>\n\n\n\n<p>Bliss p\u00e8te un plomb et commence \u00e0 rouer de coups l&rsquo;arbitre ! Belair veut intervenir, mais m\u00eame r\u00e9sultat, Belair se fait rouer de coups. Bliss commence \u00e0 d\u00e9truire Belair et l&rsquo;am\u00e8ne en bas du ring pour lui faire un DDT sur la marche d&rsquo;acier. Bliss allait partir, mais elle revient pour faire un autre DDT \u00e0 Belair sur la marche d&rsquo;acier.<\/p>\n\n\n\n<p><em>Pas de Gagnant malgr\u00e9 que Bliss devrait \u00eatre DQ<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, les ambulanciers et le m\u00e9decin arrivent pour s&rsquo;occuper de Belair.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, on voit que Belair a re\u00e7u de l&rsquo;aide de Montez Ford pour marcher pendant la pause.<ins><\/ins><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Theory et Rollins. En coulisse, Cathy est avec Austin Theory pour savoir \u00e0 quel point il est confiant pour ce soir. Theory dit que c&rsquo;est au top, car c&rsquo;est la nouvelle ann\u00e9e. 2023 sera son ann\u00e9e. Il y a deux semaines il est entr\u00e9 dans la t\u00eate de Seth Rollins et il a attaqu\u00e9 lorsqu&rsquo;il \u00e9tait occup\u00e9 avec le Bloodline. \u00c7a montre que Rollins est le pass\u00e9 et lui le pr\u00e9sent. Son r\u00e8gne pour toujours ne fait que commencer.<\/p>\n\n\n\n<p>&#8211; Elias est sur le ring et dit qu&rsquo;il a pour intention de frapper sa guitare sur la t\u00eate de Solo pour qu&rsquo;il d\u00e9couvre que la WWE signifie Marcher Avec Elias. Elias dit qu&rsquo;il est venu avec une chanson pour ce soir. La musique de Solo coupe la chanson.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Music City Street Fight<\/strong><\/p>\n\n\n\n<p><strong>Elias vs Solo Sikoa<\/strong><\/p>\n\n\n\n<p>En fin de match, le chanteur Hardy ( aucune parent\u00e9 avec Matt et Jeff ) de Nashville entre sur le ring pour frapper Sikoa avec une guitare, mais il ne tombe pas ! Hardy prend rapidement la fuite. Elias porte un coup de genou \u00e0 Sikoa et se lance du coin, mais Sikoa le bloque avec un Samoan Spike. Sikoa enchaine avec son Spinning Solo sur un piano en bas du ring pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Solo Sikoa<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur le retour de John Cena&nbsp;\u00e0 SmackDown vendredi dernier.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/01\/02\/deuxieme-partie-de-raw-24\/\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"llgZ2OZFkP\"><a href=\"https:\/\/www.jdx.info\/lutte\/2023\/01\/02\/deuxieme-partie-de-raw-24\/\">Deuxi\u00e8me Partie de RAW!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Deuxi\u00e8me Partie de RAW!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2023\/01\/02\/deuxieme-partie-de-raw-24\/embed\/#?secret=OyHK5UhaKp#?secret=llgZ2OZFkP\" data-secret=\"llgZ2OZFkP\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce RAW, cliquez ici. WWE RAW Nashville, Tennessee, 2 janvier 2023 Les commentateurs sont Corey Graves et Kevin Patrick. &#8211; Le WWE Monday Night RAW d\u00e9bute avec&nbsp;le Bloodline qui arrive par la foule et qui balance un agent de s\u00e9curit\u00e9 au sol et prend le contr\u00f4le de RAW. Jimmy Uso prend le casque&#8230;<\/p>\n","protected":false},"author":4,"featured_media":78889,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,21,23],"tags":[],"ppma_author":[292],"class_list":["post-78885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=78885"}],"version-history":[{"count":8,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78885\/revisions"}],"predecessor-version":[{"id":79025,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78885\/revisions\/79025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/78889"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=78885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=78885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=78885"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=78885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}