{"id":78817,"date":"2022-12-31T00:34:00","date_gmt":"2022-12-31T05:34:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=78817"},"modified":"2023-01-01T14:54:43","modified_gmt":"2023-01-01T19:54:43","slug":"le-dernier-smackdown-de-lannee-et-john-cena-font-la-meilleure-cote-decoute-de-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/12\/31\/le-dernier-smackdown-de-lannee-et-john-cena-font-la-meilleure-cote-decoute-de-2022\/","title":{"rendered":"Le dernier Smackdown de l&rsquo;ann\u00e9e et John Cena font la meilleure c\u00f4te d&rsquo;\u00e9coute de 2022!"},"content":{"rendered":"\n<p>Comme vous le savez surement, la WWE diffusait lundi soir dernier un best of de RAW, et l\u2019\u00e9pisode de NXT \u00e9tait enregistr\u00e9 \u00e0 l\u2019avance et donc les r\u00e9sultats \u00e9tant connus les c\u00f4tes d&rsquo;\u00e9coute n&rsquo;ont rien fracass\u00e9es mais il en est autrement pour le dernier show bleu de l&rsquo;ann\u00e9e qui \u00e9tait en direct avec le seul match 2022 de John Cena. <\/p>\n\n\n\n<p>En effet Smackdown \u00e9tait bel et bien en direct vendredi soir dernier qui s\u2019est termin\u00e9e avec John Cena faisant \u00e9quipe avec le Kevin Ownes contre la Bloodline, Sami Zay et le Tribal Chief pour l&rsquo;occasion. <\/p>\n\n\n\n<p>The Champ a ainsi fait son retour sur le ring et sa Streak \u00e0 la WWE continue avec au moins un match par ann\u00e9e depuis son arriv\u00e9 dans la compagnie il y a 20 ans. Maintenant \u00e2g\u00e9 de 45 ans, le Marine Original a en effet pris part \u00e0 au moins un match au sein de la WWE depuis l\u2019ann\u00e9e 2002. Pour 2023, son nom est d\u2019ailleurs \u00e9voqu\u00e9 pour Wrestlemania 39, bien que rien n&rsquo;est confirm\u00e9 pour le moment.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>La fin d\u2019ann\u00e9e est en effet rarement propice aux bonnes audiences car tout le monde est en famille pour les party de fin d&rsquo;ann\u00e9e. John Cena a cependant fait mentir les statistiques. Le m\u00e9dia qui se concentre sur les ratings des shows est venu \u00e9voqu\u00e9 la pertinence d&rsquo;avoir Cena sur le show. <\/p>\n\n\n\n<p>L\u2019\u00e9pisode de Smackdown de vendredi a ainsi attir\u00e9 2.441 millions de t\u00e9l\u00e9spectateurs. Il s\u2019agit de la meilleure audience de l\u2019ann\u00e9e du show bleu. C\u2019est \u00e9galement la premi\u00e8re fois que Smackdown d\u00e9passe les 2.4 millions. <\/p>\n\n\n\n<p>Friday Night Smackdown a d\u2019ailleurs  fait un tr\u00e8s beau mois de d\u00e9cembre. Deux autres \u00e9pisodes avaient en effet d\u00e9pass\u00e9 les 2.3 millions de t\u00e9l\u00e9spectateurs, dont la semaine pr\u00e9c\u00e9dente, bien qu&rsquo;il \u00e9tait d\u00e9j\u00e0 enregistr\u00e9. <\/p>\n\n\n\n<p>Il faut aussi rappeler par contre que la WWE a mit le paquet pour ce show avec un match de championnat f\u00e9minin, et bien que le retour de Charlotte n&rsquo;\u00e9tait pas annonc\u00e9, la tendance sur les r\u00e9seaux sociaux a carr\u00e9ment fait exploser les chiffres en ligne juste avant cette finale. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"ZOPUVvEyYz\"><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/30\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-30-decembre-2022\/\">R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 30 D\u00e9cembre 2022!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0R\u00e9sultats et Vid\u00e9o pour le WWE Friday Night Smackdown du 30 D\u00e9cembre 2022!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/30\/resultats-et-video-pour-le-wwe-friday-night-smackdown-du-30-decembre-2022\/embed\/#?secret=rg17g3pZuU#?secret=ZOPUVvEyYz\" data-secret=\"ZOPUVvEyYz\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez surement, la WWE diffusait lundi soir dernier un best of de RAW, et l\u2019\u00e9pisode de NXT \u00e9tait enregistr\u00e9 \u00e0 l\u2019avance et donc les r\u00e9sultats \u00e9tant connus les c\u00f4tes d&rsquo;\u00e9coute n&rsquo;ont rien fracass\u00e9es mais il en est autrement pour le dernier show bleu de l&rsquo;ann\u00e9e qui \u00e9tait en direct avec le seul&#8230;<\/p>\n","protected":false},"author":4,"featured_media":78818,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,36,23],"tags":[],"ppma_author":[292],"class_list":["post-78817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=78817"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78817\/revisions"}],"predecessor-version":[{"id":78819,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78817\/revisions\/78819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/78818"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=78817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=78817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=78817"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=78817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}