{"id":78523,"date":"2022-12-20T20:51:00","date_gmt":"2022-12-21T01:51:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=78523"},"modified":"2022-12-23T23:06:55","modified_gmt":"2022-12-24T04:06:55","slug":"resultats-et-video-pour-le-wwe-nxt-du-20-decembre-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/12\/20\/resultats-et-video-pour-le-wwe-nxt-du-20-decembre-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE NXT du 20 D\u00e9cembre 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/20\/avant-gout-pour-le-wwe-nxt-du-20-janvier-2022\/\" target=\"_blank\">Pour voir ce NXT, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE NXT, Orlando, Floride, 20 d\u00e9cembre 2022<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Booker T.<\/p>\n\n\n\n<p>&#8211; Le WWE NXT d\u00e9bute avec une vid\u00e9o sur Roxanne Perez qui a battu Mandy Rose la&nbsp;semaine derni\u00e8re pour le championnat de NXT. Carmelo Hayes arrive ensuite sur le ring.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Carmelo Hayes&nbsp;acc de Trick Williams&nbsp;vs Axiom<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, les deux s&rsquo;affrontenr sur le coin, Axiom arrive \u00e0 lui faire un Super Rana du coin. L&rsquo;arbitre regarde comment va Hayes, Williams en profite pour frapper Aximon. Hayes surprend Axiom avec un Code Breaker et enchaine avec son Leg Drop du coin pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Carmelo Hayes<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Axiom se rel\u00e8ve rapidement et se lance en Moonsault sur Williams en bas du ring pendant leur c\u00e9l\u00e9bration.<\/p>\n\n\n\n<p>&#8211; En coulisse, Grayson Waller demande \u00e0 McKenzie un moment pour parler. Waller dit que si Roxanne ne devait pas attendre pour New Year&rsquo;s Evil, pourquoi lui doit attendre ? Il veut son match de titre ce soir ! McKenzie dit que Bron Breakker est en tourn\u00e9e avec les m\u00e9dias pour faire la promotion de Vengeance Day.&nbsp;<\/p>\n\n\n\n<p>Waller dit que ce n&rsquo;est pas important, le challenge est lanc\u00e9, on verra si Breakker a peur ou non.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, Tony D&rsquo;Angelo parle au t\u00e9l\u00e9phone et il est heureux. Channing Lorenzo demande c&rsquo;\u00e9tait qui. D&rsquo;Angelo dit qu&rsquo;il vient d&rsquo;avoir un match pour le titre Nord-Am\u00e9ricain la semaine prochaine. Lorenzo demande ce qu&rsquo;ils vont faire. D&rsquo;Angelo dit \u00e0 Lorenzo d&rsquo;aller aviser Dijak de rester loin de son business. Grayson Waller arrive et dit \u00e0 D&rsquo;Angelo que s&rsquo;il voit Bron Breakker de l&rsquo;aviser qu&rsquo;il le cherche.<\/p>\n\n\n\n<p>&#8211; Zoey Stark arrive pour son match, mais Lyons vient l&rsquo;attaquer sur la sc\u00e8ne ! L&rsquo;arbitre retrouve le calme et le match se lance.<\/p>\n\n\n\n<p><strong>Zoey Stark vs Nikkita Lyons<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Lyons repousse Stark contre le coin et veut lui faire un Roll Up, mais Stark renverse le compte de trois en sa faveur en attrapant un c\u00e2ble pour compl\u00e9ter le trois.<\/p>\n\n\n\n<p><em>Gagnante : Zoey Stark&nbsp;<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie demande \u00e0 Cora Jade sa r\u00e9action sur Perez qui est la nouvelle championne apr\u00e8s l&rsquo;avoir vaincu \u00e0 Deadline. Jade dit que ce devait \u00eatre son moment. Perez ne m\u00e9rite pas le titre, elle connait beaucoup de gens qui pensent m\u00e9riter des choses. Wendy Choo arrive pour se battre avec Jade, mais elles se font s\u00e9parer.<\/p>\n\n\n\n<p>&#8211; Au bar de Fallon Henley, Kiana James arrive avec son assistante et lui demande de faire la liste de tout le mat\u00e9riel. Fallon demande ce qu&rsquo;elle fait ici, elle va la sortir. James dit qu&rsquo;elle a \u00e9t\u00e9 inform\u00e9e de leur probl\u00e8me financier, alors elle peut les aider. Le bar doit des milliers en taxes pour la ville. Fallon dit que James est une chienne. La semaine prochaine elles vont s&rsquo;affronter et James devra ne plus jamais revenir au bar. Si James gagne, elle va lui donner le bar. James accepte.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Triple Menace Championnat F\u00e9minin par \u00c9quipe NXT<\/strong><\/p>\n\n\n\n<p><strong>Toxic Attraction<em>&nbsp;(Gigi Dolin et Jacy Jayne)<\/em>&nbsp;vs Ivy Nile et Tatum Paxley vs Katana Chance et Kayden Carter (c)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Carter sort Jaynes du ring. Chance monte sur le coin, mais Paxley la pousse sur Toxic Attraction en bas du ring. Nile veut en profiter avec son Dragon Sleeper, mais Carter la renverse avec un compte rapide pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnantes : Katana Chance et Kayden Carter<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Oro Mensah qui explique adorer faire la f\u00eate. Il est ici pour s&rsquo;amuser.<\/p>\n\n\n\n<p>&#8211; En coulisse,&nbsp;<strong>Booker T <\/strong>est avec <strong>Roxanne Perez <\/strong>pour une interview. Booker T lui demande comment elle se sentait. Perez dit que c&rsquo;est un m\u00e9lange d&rsquo;\u00e9motions. Elle ne pensait pas pouvoir le faire, mais elle l&rsquo;a fait. Elle est all\u00e9e \u00e0 l&rsquo;\u00e9cole de Booker T \u00e0 16 ans pour faire sa place et 5 ans plus tard la voici championne. <\/p>\n\n\n\n<p>Perez dit qu&rsquo;elle n&rsquo;a pas \u00e9t\u00e9 la championne la plus jeune, mais elle est la premi\u00e8re gagnante Breakout et la premi\u00e8re Iron Survivor et maintenant championne. Booker T demande pourquoi elle n&rsquo;a pas attendu \u00e0 New Year&rsquo;s Evil. Perez dit que Booker T lui a toujours dit de parier sur elle. Elle ne voulait pas attendre et miser sur elle d\u00e8s maintenant. Booker T dit que Perez \u00e9tait pr\u00e9par\u00e9e depuis le premier jour, bravo. Perez demande s&rsquo;il a un conseil pour lui. Booker T dit qu&rsquo;elle doit vivre avec les papillons, sinon elle doit se retirer. C&rsquo;est le moment pour Perez de faire l&rsquo;histoire.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211;&nbsp;<strong>Apollo Crews<\/strong>&nbsp;arrive sur le ring et prend le micro. Crews dit qu&rsquo;il doit f\u00e9liciter la nouvelle championne Roxanne Perez, c&rsquo;\u00e9tait bien m\u00e9rit\u00e9. Il pensait quitter Deadline comme le nouveau champion, il le savait dans son coeur, c&rsquo;\u00e9tait sa soir\u00e9e, la vision \u00e9tait claire. Il avait sa chance de capturer le titre qui \u00e9tait la raison de son retour \u00e0 NXT. On a tous vu ce qui est arriv\u00e9, \u00e7a n&rsquo;a pas \u00e9t\u00e9 comme pr\u00e9vu. Mais il n&rsquo;est pas \u00e0 l&rsquo;\u00e9cart d&rsquo;une nouvelle chance pour le titre. Waller et Bron Breakker vont se battre \u00e0 New Year&rsquo;s Evil. Et dans trois semaines NXT sera de retour sur la route pour Vengeance Day et ce sera son moment. <\/p>\n\n\n\n<p>La musique de Carmelo Hayes le coupe. Hayes dit que Crews devrait voir ses visions derri\u00e8re tout le monde Hayes dit que c&rsquo;est lui le prochain pour une chance au titre. Hayes dit que Crews a beaucoup, mais Crews n&rsquo;a pas sa position. Les deux n&rsquo;ont jamais eu de match, mais il n&rsquo;a pas de probl\u00e8me de le vaincre. Crews dit que Hayes a le style, le swag, mais il lui manque une chose. <\/p>\n\n\n\n<p>Hayes dit qu&rsquo;il lui manque le titre de NXT, comme Crews. Crews dit que peu importe \u00e0 quel point Hayes se pense bon, il y aura toujours quelqu&rsquo;un de meilleur quelque part. Il n&rsquo;a pas besoin de dire qui il est, Hayes doit seulement nommer l&rsquo;endroit et il va lui montrer.<\/p>\n\n\n\n<p>&#8211; En coulisse, Pretty Deadly retrouve le New Day. Kofi Kingston dit que c&rsquo;est les aspirants, s&rsquo;ils ont tous les cadeaux. New Day \u00e9num\u00e8re la liste de leurs cadeaux. Kit Wilson dit qu&rsquo;ils n&rsquo;ont pas exactement tout. Kingston dit qu&rsquo;ils ne peuvent pas donner le rematch. Elton Prince demande s&rsquo;ils peuvent se reprendre sur le serment d&rsquo;all\u00e9geance, mais le New Day refuse en disant que \u00e7a prendra plus.<\/p>\n\n\n\n<p>&#8211; En coulisse, Alba Fyre marche, mais Isla Dawn l&rsquo;asperge d&rsquo;un Mist.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de la semaine derni\u00e8re avec Blade, Enofe et Jones qui invitent Ava Raine pour une soir\u00e9e. Raine dit que les trois veulent remplir leur vide dans leur vie. Blade dit qu&rsquo;ils veulent seulement avoir du plaisir, c&rsquo;est cool si Raine ne veut pas les suivre, mais ils ne croient pas \u00e0 la merde su Schism. Le clan de Joe Gacy arrive. Jagger dit qu&rsquo;ils regardent \u00e0 trois personnes qui veulent se cacher derri\u00e8re le plaisir. Alors qu&rsquo;ils s&rsquo;amusent tous ce soir.<\/p>\n\n\n\n<p>&#8211; En coulisse, Alba Fyre re\u00e7oit des soins du m\u00e9decin pour ses yeux.<\/p>\n\n\n\n<p><strong>Indi Hartwell vs Elektra Lopez<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Lopez monte sur le coin, mais Hartwell la frappe. Hartwell soul\u00e8ve Lopez, mais Lopez la frappe avec un poing am\u00e9ricain et la couvre pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Elektra Lopez<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Fyre apprend qu&rsquo;elle peut faire son match.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie demande \u00e0 Wes Lee sa r\u00e9action sur le match contre Tony D&rsquo;Angelo. Lee dit qu&rsquo;il n&rsquo;a pas peur de rivaliser, il se bat pour d\u00e9fendre le titre. Il va affronter chacun des challengers et \u00e7a commence avec D&rsquo;Angelo, et ensuite Dijak qui attend. Le titre ne va pas le quitter pour bient\u00f4t.<\/p>\n\n\n\n<p>&#8211; Les catcheuses arrivent pour le match, mais Alba Fyre se fait tirer par la jambe pendant son entr\u00e9e ! Dawn commence \u00e0 rouer de coups Fyre en ringside. Dawn lui bloque la main dans la marche d&rsquo;acier et cogne dessus.<\/p>\n\n\n\n<p>&#8211; On retrouve l&rsquo;Universit\u00e9 d&rsquo;Andre Chase \u00e0 leur f\u00eate de No\u00ebl. Andre Chase se fait remettre plein de cadeaux par ses \u00e9tudiants. Chase est furieux d&rsquo;un \u00e9tudiant qui lui donne un g\u00e2teau aux fruits, il est allergique. Duke Hudson arrive et avait oubli\u00e9 un cadeau. Hudson vole le cadeau \u00e0 un \u00e9tudiant en lui disant qu&rsquo;il est convoqu\u00e9 dans le bureau. Hudson lui remet une plaque de professeur num\u00e9ro un. Chase le remercie.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie est avec Fallon, Briggs et Jensen pour avoir leur r\u00e9action. Jensen dit qu&rsquo;ils vont s&rsquo;occuper du bar plus tard, mais ce soir c&rsquo;est pour les titres par \u00e9quipe. Briggs dit que c&rsquo;est le plus gros match de leur vie. 2023 sera leur ann\u00e9e, quoi de meilleur que d&rsquo;\u00eatre les champions ? Kiana James arrive et dit qu&rsquo;elle vient pour Briggs, bonne chance pour ce soir.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de Drew Gulak qui fait un entrainement et Hank Walker arrive. Walker dit qu&rsquo;il a vu Gulak pendant son match, il sait qu&rsquo;il peut s&rsquo;am\u00e9liorer, alors est-ce que Gulak a des conseils ? Il est pr\u00eat \u00e0 travailler fort. Gulak dit que la semaine prochaine il va faire une formation et il veut que Walker vient pour observer. Walker accepte.<\/p>\n\n\n\n<p style=\"font-size:25px\"><strong>Championnat par \u00c9quipe NXT<\/strong><\/p>\n\n\n\n<p><strong>Josh Briggs et Brooks Jensen&nbsp;<em>accompagn\u00e9 de Fallon Henley<\/em>&nbsp;vs New Day \u00a9&nbsp;(Kofi Kingston et Xavier Woods)<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Kingston r\u00e9siste apr\u00e8s un Moonsault de Jensen du coin. Briggs se pr\u00e9pare pour une prise \u00e0 deux, mais Woods le repousse en bas du ring. Kingston fait un Rana \u00e0 Jensen et enchaine avec un Trouble in Paradise. Woods prend la tag pour sa Springboard Elbow pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : New Day<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, les \u00e9quipes se serrent la main.<\/p>\n\n\n\n<p>&#8211; En coulisse, Channing Lorenzo se pr\u00e9pare \u00e0 parler avec Dijak pour le match de D&rsquo;Angelo. Lorenzo entre dans la loge de Dijak.<\/p>\n\n\n\n<p>&#8211; En coulisse, Grayson Waller dit qu&rsquo;il n&rsquo;arrive pas \u00e0 trouver Breakker. Il ira l&rsquo;attendre sur le ring.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o d&rsquo;une nouvelle catcheuse pour le show du 10 janvier.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Sur le parking, Tatum Paxley dit que malgr\u00e9 la d\u00e9faite, elle et Ivy Nile vont rester solide. Indus Sher arrive et demande s&rsquo;ils ont \u00e9t\u00e9 lib\u00e9r\u00e9s par le m\u00e9decin. Julius approuve et dit que le match peut avoir lieu n&rsquo;importe quand. Veer dit qu&rsquo;il faut leur prouver. Julius dit qu&rsquo;il va affronter JD McDonagh la semaine prochaine et ensuite Indus Sher n&rsquo;aura aucune excuse.<\/p>\n\n\n\n<p>&#8211; Grayson Waller arrive sur le ring. Waller demande o\u00f9 Bron Breakker se cache, il n&rsquo;attend plus. Il veut son match pour le championnat de NXT ici et maintenant. Waller dit qu&rsquo;il a oubli\u00e9&#8230; Breakker est un l\u00e2che. Il a transport\u00e9 NXT sur son dos pendant toute l&rsquo;ann\u00e9e 2022. Il est la plus grande star, il est intouchable. Il n&rsquo;y a personne \u00e0 la WWE qui peut faire ce qu&rsquo;il fait. Waller insulte Breakker, mais il est coup\u00e9 par Bron Breakker qui arrive en voiture sur le parking.<\/p>\n\n\n\n<p>Waller dit qu&rsquo;il n&rsquo;a pas peur, ils vont le faire maintenant ! Waller attend sur le ring. Breakker arrive sur le ring, \u00e9vite un coup et lui fait un Spear, mais Breakker ne bouge plus. Waller se rel\u00e8ve et d\u00e9voile une plaque d&rsquo;acier sous sa veste. Waller dit qu&rsquo;il a \u00e9t\u00e9 plus intelligent ce soir, il a \u00e9t\u00e9 plus intelligent \u00e0 Deadline et \u00e0 New Year&rsquo;s Evil il le fera une autre fois en devenant champion de NXT. C&rsquo;est l&rsquo;effet Grayson Waller. Le show se termine avec une c\u00e9l\u00e9bration de Waller.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/20\/avant-gout-pour-le-wwe-nxt-du-20-janvier-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce NXT, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"OnVDPazYpo\"><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/20\/avant-gout-pour-le-wwe-nxt-du-20-janvier-2022\/\">Vid\u00e9os et Programme pour le WWE NXT du 20 Janvier 2022!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vid\u00e9os et Programme pour le WWE NXT du 20 Janvier 2022!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/20\/avant-gout-pour-le-wwe-nxt-du-20-janvier-2022\/embed\/#?secret=Ye6zNgEeUC#?secret=OnVDPazYpo\" data-secret=\"OnVDPazYpo\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce NXT, cliquez ici. WWE NXT, Orlando, Floride, 20 d\u00e9cembre 2022 Les commentateurs sont Vic Joseph et Booker T. &#8211; Le WWE NXT d\u00e9bute avec une vid\u00e9o sur Roxanne Perez qui a battu Mandy Rose la&nbsp;semaine derni\u00e8re pour le championnat de NXT. Carmelo Hayes arrive ensuite sur le ring. Carmelo Hayes&nbsp;acc de Trick&#8230;<\/p>\n","protected":false},"author":4,"featured_media":78526,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,23],"tags":[],"ppma_author":[292],"class_list":["post-78523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=78523"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78523\/revisions"}],"predecessor-version":[{"id":78527,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78523\/revisions\/78527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/78526"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=78523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=78523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=78523"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=78523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}