{"id":78468,"date":"2022-12-19T20:02:00","date_gmt":"2022-12-20T01:02:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=78468"},"modified":"2022-12-19T22:49:54","modified_gmt":"2022-12-20T03:49:54","slug":"resultats-et-video-pour-le-wwe-monday-night-raw-du-19-decembre-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/12\/19\/resultats-et-video-pour-le-wwe-monday-night-raw-du-19-decembre-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le WWE Monday Night RAW du 19 D\u00e9cembre 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/19\/avant-gout-express-pour-le-wwe-monday-night-raw-du-19-decembre-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce RAW, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>WWE RAW Des Moines, Iowa<\/p>\n\n\n\n<p>Les commentateurs sont Corey Graves et Kevin Patrick.<\/p>\n\n\n\n<p>&#8211; Le WWE Monday Night RAW d\u00e9bute avec Paul Heyman en coulisse qui nous souhaite la bienvenue \u00e0 Monday Night RAW et se pr\u00e9sente puis <strong>Roman Reigns<\/strong>. Reigns dit que c&rsquo;est Monday Night RAW, la maison de Kevin Owens, la maison que Kevin Owens quitte toujours pour essayer de sortir de l&rsquo;\u00eele de la non-pertinence. Et Owens veut le faire avec John Cena en prime. Reigns dit que Owens aura besoin de tout le roster de RAW pour le prot\u00e9ger.\u00a0Owens est intervenu trop souvent dans son business, c&rsquo;est le moment de retourner la faveur.\u00a0Owens devra r\u00e9aliser qu&rsquo;il doit reconnaitre le Bloodline.<\/p>\n\n\n\n<p>&#8211; En coulisse, les Usos, Sami Zayn et Solo Sikoa s&rsquo;amusent \u00e0 attaquer Mustafa Ali. Le Bloodline d\u00e9clare qu&rsquo;ils vont s&rsquo;imposer ce soir.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><strong>Street Profits\u00a0(Montez Ford et Angelo Dawkins) acc de Akira Tozawa\u00a0vs Finn Balor et Damian Priest\u00a0acc de Rhea Ripley et Dominik Mysterio<\/strong><\/p>\n\n\n\n<p>Pendant le match, on voit le Bloodline qui attaque Andre Chase de NXT en coulisse.<\/p>\n\n\n\n<p>En fin de match, Tozawa et Dominik se disputent en ringside. Tozawa lui lance un verre au visage. Ford profite de la distraction pour faire un Roll Up sur Balor pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : Street Profits<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Ripley est furieuse et va cogner Tozawa sur la sc\u00e8ne ! Ripley le challenge pour un match et il accepte !<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, le match mixte se lance.<\/p>\n\n\n\n<p><strong>Akira Tozawa\u00a0acc des Street Profits\u00a0vs Rhea Ripley\u00a0acc de Judgment Day<\/strong><\/p>\n\n\n\n<p>En fin de match, Tozawa fait un Rana \u00e0 Ripley pour la sortir du ring. Tozawa veut se lancer en saut suicide, mais Balor lui tire la jambe pour le faire chuter. Les Street Profits se lancent en Flip sur Priest et Balor en bas du ring ! Ripley retourne sur le ring pour son finisher, mais Tozawa la repousse. Ripley veut le charger, mais Tozawa l&rsquo;\u00e9vite et elle se cogne contre le coin. Tozawa enchaine avec son Senton, mais Ripley l&rsquo;\u00e9vite. Ripley lui fait son Riptide pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Rhea Ripley<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, Adam Pearce veut prendre contact au t\u00e9l\u00e9phone avec Paul Heyman, mais il tombe sur la boite vocale. Cathy lui demande une update sur son histoire avec Bobby Lashley. Pearce dit que c&rsquo;est une histoire priv\u00e9e. Ils ont discut\u00e9 ensemble cette semaine et Lashley va revenir rapidement. MVP arrive et dit qu&rsquo;il veut parler au sujet de Lashley avec Pearce. Pearce accepte, mais un arbitre arrive et demande \u00e0 Pearce de l&rsquo;accompagner pour une urgence.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, ou retrouve Dolph Ziggler et Cedric Alexander au sol. Ziggler d\u00e9clare qu&rsquo;il a \u00e9t\u00e9 attaqu\u00e9 par le Bloodline.<\/p>\n\n\n\n<p><strong>Luke Gallows et Karl Anderson\u00a0acc de AJ Styles et Mia Yim\u00a0vs Alpha Academy\u00a0(Otis et Chad Gable)<\/strong><\/p>\n\n\n\n<p>En fin de match, Gallows \u00e9vite le Moonsault de Gable et lui porte un coup de pied. Anderson prend la tag et ils font leur Magic Killer sur Anderson pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants : The OC<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, The OC c\u00e9l\u00e8bre leur victoire, mais le Bloodline arrive pour rouer de coups The OC.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour, Adam Pearce est en ringside avec des agents de la s\u00e9curit\u00e9. Pearce leur demande de quitter le ring. Jimmy Uso dit que le Bloodline est \u00e0 Des Moines. Jimmy dit qu&rsquo;ils dirigent le business. Sami Zayn demande c&rsquo;est quoi le probl\u00e8me de Pearce, Pearce est le seul qui est f\u00e2ch\u00e9, les fans adorent les voir. Ce qu&rsquo;on voit ce soir est un petit exemple de ce qui va arriver \u00e0 John Cena et Kevin Owens lorsqu&rsquo;ils vont les affronter \u00e0 SmackDown. Le Bloodline accepte finalement de quitter le ring. AJ Styles arrive et saute sur le Bloodline. La s\u00e9curit\u00e9 s\u00e9pare tout le monde.<\/p>\n\n\n\n<p>&#8211; En coulisse, AJ Styles parle avec Adam Pearce et dit qu&rsquo;il veut n&rsquo;importe qui, m\u00eame Sami Uso. Pearce confirme le match AJ contre Sami Uso.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/?p=78469\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce RAW, cliquez ici. WWE RAW Des Moines, Iowa Les commentateurs sont Corey Graves et Kevin Patrick. &#8211; Le WWE Monday Night RAW d\u00e9bute avec Paul Heyman en coulisse qui nous souhaite la bienvenue \u00e0 Monday Night RAW et se pr\u00e9sente puis Roman Reigns. Reigns dit que c&rsquo;est Monday Night RAW, la maison&#8230;<\/p>\n","protected":false},"author":4,"featured_media":78491,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,21,23],"tags":[],"ppma_author":[292],"class_list":["post-78468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=78468"}],"version-history":[{"count":5,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78468\/revisions"}],"predecessor-version":[{"id":78485,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78468\/revisions\/78485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/78491"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=78468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=78468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=78468"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=78468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}