{"id":78155,"date":"2022-12-11T15:48:10","date_gmt":"2022-12-11T20:48:10","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=78155"},"modified":"2022-12-13T15:13:43","modified_gmt":"2022-12-13T20:13:43","slug":"resultats-et-video-du-wwe-nxt-deadl1ne-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/12\/11\/resultats-et-video-du-wwe-nxt-deadl1ne-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du WWE NXT Deadl1ne 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/10\/carte-du-wwe-nxt-deadline-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce NXT, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p><strong>WWE NXT Deadline Orlando, Floride, 10 d\u00e9cembre 2022<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph et Booker T.<\/p>\n\n\n\n<p>&#8211; Le premium live event, WWE NXT Deadline d\u00e9marre avec une vid\u00e9o preview sur le show et les commentateurs nous souhaitent la bienvenue. <\/p>\n\n\n\n<p>Les r\u00e8glements du Iron Survivor Challenge sont pr\u00e9sent\u00e9es et les catcheuses arrivent sur le ring.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Iron Survivor Challenge <\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Aspirante championnat f\u00e9minin de NXT<\/strong><\/p>\n\n\n\n<p><strong>Zoey Stark vs Cora Jade vs Roxanne Perez vs Kiana James vs Indi Hartwell<\/strong><\/p>\n\n\n\n<p>En fin de match, les catcheuses veulent se d\u00e9p\u00eacher \u00e0 faire des comptes, mais tout le monde r\u00e9siste. Il reste moins d&rsquo;une minute, James arrive \u00e0 faire un Spanish Fly sur Stark. Jade repousse James et couvre Stark, mais elle r\u00e9siste. Jade fait un DDT sur Perez et le temps se termine.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Roxanne Perez<\/em><\/p>\n\n\n\n<p>Score : Cora 1 &#8211; Indi 1 &#8211; Kiana 0 &#8211; Roxanne 2 &#8211; Zoey 1<ins><\/ins><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur le match pour les titres par \u00e9quipe.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie demande \u00e0 Ivy Nile ses commentaires sur la blessure de Julius Creed qui emp\u00eache le match contre Indus Sher. Nile dit que c&rsquo;est dommage, elle sait que tout le monde veut voir le match, mais la priorit\u00e9 est leur sant\u00e9. Elle veut seulement les voir \u00e0 100% pour leur match, elle doit les prot\u00e9ger. Katana Chance et Kayden Carter arrivent. Chance dit qu&rsquo;elle a fait ce qu&rsquo;il fallait. Nile dit que sa gentillesse n&rsquo;est pas une faiblesse. Tatum Paxley dit qu&rsquo;elles vont arriver pour ces titres par \u00e9quipe. Carter dit qu&rsquo;elles vont les attendre.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Fyre et Dawn.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Isla Dawn vs Alba Fyre<\/strong><\/p>\n\n\n\n<p>En fin de match, Fyre fait une Slam \u00e0 Dawn. Fyre monte sur le coin et fait son Swenton, mais l&rsquo;arbitre est poss\u00e9d\u00e9 apr\u00e8s que Dawn l&rsquo;a touch\u00e9. L&rsquo;arbitre crache du noir. Fyre fait un Superkick \u00e0 Dawn qui se rel\u00e8ve, mais il n&rsquo;y a aucun arbitre. Un nouvel arbitre arrive et elle couvre Dawn, mais elle r\u00e9siste. Dawn repousse Fyre t\u00eate premi\u00e8re contre le poteau lorsque le nouvel arbitre aide l&rsquo;ancien. Dawn enchaine avec un Reverse DDT sur Fyre pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Isla Dawn<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie demande au New Day leur commentaire avant le match. Xavier Woods dit que tout le monde demande pourquoi ils sont ici. Ils vont affronter Pretty Deadly car ils veulent affronter les meilleurs et ils sont des champions. Rien ne peut les arr\u00eater des Triple Crown Tag Team Match. Kingston dit que Pretty Deadly a quitt\u00e9 leur pays pour devenir champion, ce n&rsquo;est pas facile. \u00catre Triple Crown les motive ce soir ! Woods dit qu&rsquo;il promet de quitter la salle comme les champions.<\/p>\n\n\n\n<p style=\"font-size:28px\"><strong>Championnat par \u00c9quipe NXT<\/strong><\/p>\n\n\n\n<p><strong>Pretty Deadly<em>&nbsp;(Kit Wilson et Elton Prince)<\/em>&nbsp;\u00a9 vs New Day<em>&nbsp;(Kofi Kingston et Xavier Woods)<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Pretty Deadly veut tricher avec les titres. Prince lance un titre vers Woods pour jouer la fausse blessure, mais ils se lancent tous le titre pour jouer \u00e0 la patate chaude pendant que l&rsquo;arbitre est de dos. Ils se couchent tous au sol pour jouer le coup de ceinture, l&rsquo;arbitre ne comprend rien et remet l&rsquo;ordre. Wilson frappe Woods avec un titre et le couvre, mais il r\u00e9siste ! Prince prend la tag pour leur finisher, mais Kingston sort Wilson du ring et lui fait un Trouble in Paradise ! Woods repousse Prince contre le coin, Kingston prend la tag, ils font leur Up Up Down Down pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnants et nouveaux champions: New Day <\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, le New Day c\u00e9l\u00e8bre cette victoire dans la foule, ils sont maintenant des champions Triple Crown.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur une nouvelle catcheuse qui va d\u00e9buter le 10 janvier 2023.<\/p>\n\n\n\n<p>&#8211; En coulisse, Kayden et Chance arr\u00eatent le clan de Odyssey Jones qui se pr\u00e9parent pour la f\u00eate. Gigi Dolin et Jacy Jayne arrivent. Dolin demande si c&rsquo;est s\u00e9rieux de donner un match pour les titres par \u00e9quipe. Jayne dit que Kayden et Chance veulent juste affronter des \u00e9quipes qu&rsquo;elles peuvent battre. Ivy Nile et Paxley arrivent pour se battre, elles se font s\u00e9parer.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p class=\"has-large-font-size\"><strong>Iron Survivor Challenge <\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Aspirant championnat NXT<\/strong><\/p>\n\n\n\n<p><strong>Carmelo Hayes vs Grayson Waller vs Joe Gacy vs JD McDonagh vs Axiom<\/strong><\/p>\n\n\n\n<p>En fin de match, Gacy se lance en soumission sur Aximon et il veut tout faire pour le faire taper, mais Hayes et McDonagh arr\u00eatent la soumission. Ensuite, Hayes arrive \u00e0 faire son Leg Drop sur Aximon pour le couvrir, mais Waller sort Hayes du ring et le frappe. Waller couvre Axiom pour le compte de trois ! Waller tire McDonagh pour \u00e9tirer le temps alors qu&rsquo;il reste moins de 30 secondes. Hayes pourchasse Waller, mais il s&rsquo;\u00e9chapper et le 25 minutes se termine.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Grayson Waller<\/em><\/p>\n\n\n\n<p>Score : Axiom 2 &#8211; Gacy 2 &#8211; Hayes 2 &#8211; McDonagh 0 &#8211; Waller 3<\/p>\n\n\n\n<p>&#8211; On annonce que NXT New Year&rsquo;s Evil aura lieu le 10 janvier.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie demande \u00e0 Drew Gulak pourquoi il \u00e9tait \u00e0 NXT la semaine derni\u00e8re. Gulak dit qu&rsquo;il sait o\u00f9 aller, il est venu ici pour se battre sur le ring. S&rsquo;il voit quelqu&rsquo;un de sp\u00e9cial en coulisse ou sur le ring, quelqu&rsquo;un qui peut aider, il va se pr\u00e9senter. Damon Kemp arrive et se pr\u00e9sente. Gulak dit qu&rsquo;il le connait bien, un bon catcheur. Kemp dit que mardi il sera de retour \u00e0 NXT, et il devrait bien surveiller son match. Gulak approuve.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Championnat NXT<\/strong><\/p>\n\n\n\n<p><strong>Bron Breakker \u00a9 vs Apollo Crews<\/strong><\/p>\n\n\n\n<p>En fin de match, les deux pugilistes \u00e9changent les coups. Crews veut le repousser, mais Breakker tombe sur ses pieds et lui fait un Spear pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Bron Breakker<\/em><\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration de Breakker, mais Grayson Waller arrive et le surprend avec son Cutter ! Waller pose avec le titre de NXT.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/10\/carte-du-wwe-nxt-deadline-2022\/\" target=\"_blank\">Pour voir ce NXT, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"tQlqbwID0u\"><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/10\/carte-du-wwe-nxt-deadline-2022\/\">Vid\u00e9os et Carte du Premium Live Event WWE NXT Deadline 2022!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vid\u00e9os et Carte du Premium Live Event WWE NXT Deadline 2022!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2022\/12\/10\/carte-du-wwe-nxt-deadline-2022\/embed\/#?secret=ocaxYYkGyK#?secret=tQlqbwID0u\" data-secret=\"tQlqbwID0u\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce NXT, cliquez ici. WWE NXT Deadline Orlando, Floride, 10 d\u00e9cembre 2022 Les commentateurs sont Vic Joseph et Booker T. &#8211; Le premium live event, WWE NXT Deadline d\u00e9marre avec une vid\u00e9o preview sur le show et les commentateurs nous souhaitent la bienvenue. Les r\u00e8glements du Iron Survivor Challenge sont pr\u00e9sent\u00e9es et les&#8230;<\/p>\n","protected":false},"author":4,"featured_media":78198,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,23],"tags":[],"ppma_author":[292],"class_list":["post-78155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=78155"}],"version-history":[{"count":6,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78155\/revisions"}],"predecessor-version":[{"id":78199,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/78155\/revisions\/78199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/78198"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=78155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=78155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=78155"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=78155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}