{"id":77714,"date":"2022-11-28T23:08:13","date_gmt":"2022-11-29T04:08:13","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=77714"},"modified":"2022-11-28T23:17:09","modified_gmt":"2022-11-29T04:17:09","slug":"troisieme-heure-de-raw-53","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/11\/28\/troisieme-heure-de-raw-53\/","title":{"rendered":"Troisi\u00e8me Heure de RAW"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/11\/28\/deuxieme-heure-de-raw-57\/\">Pour revenir \u00e0 la deuxi\u00e8me heure, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>&#8211; De retour, le nouveau champion des \u00c9tats-Unis,<strong>\u00a0Austin Theory<\/strong>, arrive sur le ring. Theory demande qui est l&rsquo;enfant maintenant ? Tout le monde voulait le retenir, tout le monde voulait \u00eatre le clou pour fermer son cercueil. On a tous dit que l&rsquo;encaissement MITB de cet enfant \u00e9tait le pire, qui \u00e9tait stupide. Qui est stupide maintenant ? Apr\u00e8s Survivor Series il ne veut plus jamais \u00eatre nomm\u00e9 l&rsquo;enfant. Il a battu Seth Rollins et Bobby Lashley en m\u00eame temps et \u00e7a fait de lui un deux fois champion des USA. Il est le pr\u00e9sent et le futur de la WWE, il est l&rsquo;image de Monday Night RAW. Depuis son arriv\u00e9 \u00e0 la WWE tout le monde a un probl\u00e8me avec lui et pourquoi ? Un mot simple : jalousie. Tout le monde veut \u00eatre Austin Theory. Il est plus jeune, plus fort et meilleur. L&rsquo;\u00e8re de Austin Theory commence maintenant. <\/p>\n\n\n\n<p>La musique de Seth Rollins commence et il arrive sur le ring. Rollins dit \u00e0 Theory de rester en silence et laisser les fans chanter son th\u00e8me. Theory demande ce qui arrive lorsque quelqu&rsquo;un de si jeune et si talentueux fait paraitre le suppos\u00e9 futur comme le pass\u00e9 ? Rollins dit que Theory a eu de la chance samedi, mais \u00e7a ne change rien.\u00a0<\/p>\n\n\n\n<p>Rollins dit que Theory sait que les Monday Night reviennent \u00e0 lui. Il a une chose \u00e0 dire avant de partir, f\u00e9licitations l&rsquo;enfant. Si Theory veut se battre, ils peuvent le faire ici et maintenant.\u00a0Theory dit qu&rsquo;il va l&rsquo;affronter, mais sous les termes du champion.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o de Byron Saxton qui pr\u00e9sente la rivalit\u00e9 entre le Miz et Dexter Lumis.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Byron Saxton arr\u00eate le Miz pour avoir ses commentaires, mais Miz lui dit de garder ses questions. Miz dit qu&rsquo;il a son sac d&rsquo;argent, mais le match n&rsquo;aura pas lieu, car il est une nouvelle fois bless\u00e9 \u00e0 la main. Adam Pearce arrive et dit que tout le monde sait que Miz n&rsquo;est pas bless\u00e9. Miz dit qu&rsquo;il est trop bless\u00e9 pour combattre, encore moins pour un Anything Goes. Pearce dit que le match aura lieu, peu importe ce que le Miz dit. Miz dit que Pearce va entendre de son avocat.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Anything Goes Match<\/strong><\/p>\n\n\n\n<p><strong>Dexter Lumis vs The Miz<\/strong><br><em>Si Lumis gagne, il aura un contrat \u00e0 la WWE et Miz devra le payer.<\/em><\/p>\n\n\n\n<p>En fin de match, Lumis fait une Slam \u00e0 Miz et lui applique son Silence pour le faire taper.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Dexter Lumix<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Adam Pearce fait signer le contrat de WWE Superstar \u00e0 Dexter Lumis et lui remet l&rsquo;argent du Miz. Lumis donne de l&rsquo;argent aux fans en ringside. Miz se rel\u00e8ve et frappe Lumis dans le dos ! Miz enl\u00e8ve l&rsquo;argent \u00e0 un enfant en ringside et prend le sac qui contient le reste. Johnny Gargano arrive et lui fait un Superkick ! Gargano redonne le sac d&rsquo;argent \u00e0 Lumis.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Candice LeRae vs Dakota Kai<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Kai frappe LeRae contre le coin et la monte sur le coin. LeRae bloque Kai sur le coin et lui fait un Neck Breaker de la troisi\u00e8me corde pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnante : Candice LeRae<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Jey se r\u00e9chauffe pour son match avec le Bloodline.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Cathy est avec Asuka, Alexa Bliss et Bianca Belair pour avoir leur r\u00e9action apr\u00e8s Survivor Series. Belair dit que physiquement elles vont bien depuis. Mentalement c&rsquo;est bien que cette histoire est termin\u00e9e. Une histoire qui avait commenc\u00e9e \u00e0 SummerSlam et qui se termine \u00e0 Survivor Series. Elle a construit la division et bloqu\u00e9 chacune des attaques de Damage CTRL. Elle est heureuse de son \u00e9quipe \u00e0 WarGames. Asuka est heureuse. Bliss reste sans r\u00e9ponse et dit finalement que Belair a raison.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-medium-font-size\"><strong>Kevin Owens vs Jey Uso\u00a0acc du Bloodline (Sami Zayn, Jimmy Uso et Solo Sikoa<\/strong>)<\/p>\n\n\n\n<p>En fin de match, Owens veut faire son Powerbomb, mais il a trop mal \u00e0 son dos. Jey lui fait un Superkick et le couvre, mais Owens r\u00e9siste encore ! Owens roule en bas du ring et bloque un saut de Jey. Owens fait un Superkick \u00e0 Jimmy qui voulait intervenir. L&rsquo;arbitre repousse Jey et Solo Sikoa en profite pour faire chuter Owens. Jey enchaine en Splash du coin, mais Owens l&rsquo;\u00e9vite et lui fait un Stunner pour le compte de trois.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Gagnant : Kevin Owens<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, Owens prend directement la fuite sur la sc\u00e8ne pour se sauver du Bloodline et le show se termine ainsi<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/11\/28\/avant-gout-pour-le-wwe-monday-night-raw-du-28-novembre-2022\/\" target=\"_blank\">Pour voir ce RAW, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-wp-embed is-provider-info-lutte wp-block-embed-info-lutte\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"hrXsrGkBmu\"><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/11\/28\/avant-gout-pour-le-wwe-monday-night-raw-du-28-novembre-2022\/\">Vid\u00e9o et Programme pour le WWE Monday Night RAW du 28 Novembre 2022!<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00ab\u00a0Vid\u00e9o et Programme pour le WWE Monday Night RAW du 28 Novembre 2022!\u00a0\u00bb &#8212; Info-Lutte\" src=\"https:\/\/www.jdx.info\/lutte\/2022\/11\/28\/avant-gout-pour-le-wwe-monday-night-raw-du-28-novembre-2022\/embed\/#?secret=MiKYUUnyzd#?secret=hrXsrGkBmu\" data-secret=\"hrXsrGkBmu\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la deuxi\u00e8me heure, cliquez ici. &#8211; De retour, le nouveau champion des \u00c9tats-Unis,\u00a0Austin Theory, arrive sur le ring. Theory demande qui est l&rsquo;enfant maintenant ? Tout le monde voulait le retenir, tout le monde voulait \u00eatre le clou pour fermer son cercueil. On a tous dit que l&rsquo;encaissement MITB de cet enfant&#8230;<\/p>\n","protected":false},"author":4,"featured_media":77722,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-77714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/77714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=77714"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/77714\/revisions"}],"predecessor-version":[{"id":77721,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/77714\/revisions\/77721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/77722"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=77714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=77714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=77714"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=77714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}