{"id":77300,"date":"2022-11-17T01:12:00","date_gmt":"2022-11-17T06:12:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=77300"},"modified":"2022-11-17T13:18:50","modified_gmt":"2022-11-17T18:18:50","slug":"andrade-est-suspendu-de-la-aew-la-situation-salariale-de-braun-strowman-selon-ric-flair","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/11\/17\/andrade-est-suspendu-de-la-aew-la-situation-salariale-de-braun-strowman-selon-ric-flair\/","title":{"rendered":"Andrade est suspendu de la AEW ! \/ La situation salariale de Braun Strowman selon Ric Flair!"},"content":{"rendered":"\n<p>Le bruit courait sur un possible suspension du lutteur mexicain et voil\u00e0 que tout cela se pr\u00e9cise. <\/p>\n\n\n\n<p>Cela fait quelque temps que nous n&rsquo;avons pas vu Andrade El Idolo \u00e0 la AEW. Le mois dernier, on apprenait que le catcheur s&rsquo;\u00e9tait bagarr\u00e9 avec Sammy Guevara dans les coulisses d&rsquo;un show de la AEW. Depuis, Andrade El Idolo n&rsquo;a plus \u00e9t\u00e9 vu sur le ring de la compagnie am\u00e9ricaine, contrairement \u00e0 Sammy Guevara qui a par exemple eut un match cette semaine lors de Dynamite.<\/p>\n\n\n\n<p>Il y a quelques jours, le mari de Charlotte Flair s&rsquo;\u00e9tait m\u00eame plaint sur Twitter de n&rsquo;avoir re\u00e7u aucun message de la AEW pour son anniversaire. \u00c0 en croire le Wrestling Observer,\u00a0Andrade El Idolo serait en fait \u00ab\u00a0actuellement suspendu de la AEW.\u00a0\u00bb\u00a0<\/p>\n\n\n\n<p>Nous n&rsquo;avons pas plus de d\u00e9tails concernant cette suspension \u00e0 l&rsquo;heure actuelle, sur celui qui tentait d&rsquo;avoir sa lib\u00e9ration de la compagnie mais qui et maintenant prit \u00e0 attendre chez lui.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Thank you for the Happy birthday Wishes <a href=\"https:\/\/twitter.com\/AEW?ref_src=twsrc%5Etfw\">@AEW<\/a> &#x1f44f;&#x1f3fc;<\/p>&mdash; \u201cEL IDOLO\u201d ANDRADE (@AndradeElIdolo) <a href=\"https:\/\/twitter.com\/AndradeElIdolo\/status\/1588638964222545920?ref_src=twsrc%5Etfw\">November 4, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Les coupes budg\u00e9taires de 2020 et 2021 de la WWE furent sanglantes. Aucune superstar n\u2019\u00e9tait d\u2019ailleurs \u00e0 l\u2019abri et le couperet semblait pouvoir tomber sur n\u2019importe qui. Le nom de Bray Wyatt avait notamment particuli\u00e8rement choqu\u00e9 lorsqu\u2019il avait \u00e9t\u00e9 appris que la compagnie se s\u00e9parait de lui. Pr\u00e8s de deux mois plus t\u00f4t, c\u2019est Braun Strowman qui s\u2019\u00e9tait vu montrer la sortie. La raison \u00e9voqu\u00e9e \u00e0 chaque fois \u00e9tait la volont\u00e9 de faire des \u00e9conomies. La WWE \u00e9tait alors en pleine pand\u00e9mie de covid et les shows avaient lieu \u00e0 huis-clos. Finalement a la prise de pouvoir de\u00a0Triple H, bon nombre de renvoy\u00e9s et partants ont fait leurs retours au sein de la compagnie.<\/p>\n\n\n\n<p>Braun Strowman fait ainsi partie de cette liste. A l\u2019occasion de son podcast\u00a0<a href=\"https:\/\/youtu.be\/B4O-f2tsv0A\" target=\"_blank\" rel=\"noreferrer noopener\">The Man<\/a>, Ric Flair a d\u2019ailleurs fait une r\u00e9v\u00e9lation \u00e0 son sujet. Si le Monstre parmi les Hommes a r\u00e9cup\u00e9r\u00e9 sa place \u00e0 la WWE, il n\u2019aurait pas r\u00e9cup\u00e9r\u00e9 son salaire. Triple H aurait r\u00e9ussi \u00e0 le faire revenir pour moins que ce qu\u2019il touchait auparavant. Pour rappel, il \u00e9tait alors rapport\u00e9 que la r\u00e9mun\u00e9ration de Strowman \u00e9tait de 1.2 millions de dollars par an. Ric Flair ajoute que Karl Anderson serait dans la m\u00eame situation que l\u2019ancien rival d\u2019Omos.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le bruit courait sur un possible suspension du lutteur mexicain et voil\u00e0 que tout cela se pr\u00e9cise. Cela fait quelque temps que nous n&rsquo;avons pas vu Andrade El Idolo \u00e0 la AEW. Le mois dernier, on apprenait que le catcheur s&rsquo;\u00e9tait bagarr\u00e9 avec Sammy Guevara dans les coulisses d&rsquo;un show de la AEW. Depuis, Andrade&#8230;<\/p>\n","protected":false},"author":609,"featured_media":77301,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,30,77,4,23],"tags":[],"ppma_author":[295],"class_list":["post-77300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-ex-wwe","category-hall-of-fame","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/77300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=77300"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/77300\/revisions"}],"predecessor-version":[{"id":77302,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/77300\/revisions\/77302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/77301"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=77300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=77300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=77300"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=77300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}