{"id":77048,"date":"2022-11-11T20:15:00","date_gmt":"2022-11-12T01:15:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=77048"},"modified":"2022-11-14T11:58:52","modified_gmt":"2022-11-14T16:58:52","slug":"video-pour-le-aew-rampage-du-11-novembre-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/11\/11\/video-pour-le-aew-rampage-du-11-novembre-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o pour le AEW Rampage du 11 novembre 2022!"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong>AEW Rampage Boston, Massachusetts, 10 novembre 2022<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Exalibur, Jim Ross et Tony Schiavone.<\/p>\n\n\n\n<p>&#8211; Le AEW Rampage d\u00e9marre avec Christian Cage et Luchasaurus qui arrivent sur le ring. Cage dit qu&rsquo;ils sont pr\u00eats pour le challenge de Jack Perry, ils attendent. Jack Perry arrive et dit que Luchasaurus et Chrisitian ont tout g\u00e2ch\u00e9. Luchasaurus a g\u00e2ch\u00e9 des ann\u00e9es qu&rsquo;il ne va jamais retrouver. Perry dit qu&rsquo;il veut se venger et tout g\u00e2cher pour Luchasaurus, alors il le challenge dans un Steel Cage Match \u00e0 Full Gear. Cage accepte le challenge, mais dit que Perry est comme son p\u00e8re, un beau look, mais il ne peut pas se battre. Perry attrape Christian par le cou, mais Luchasaurus frappe directement Perry. Christian am\u00e8ne des chaises sur le ring et Luchasaurus lui fait un ChokeSlam sur les chaises.<\/p>\n\n\n\n<p>&#8211; En coulisse, Renee Paquette faisait une interview avec Claudio Castagnoli, mais Jake Hager arrive et dit que pendant que Castagnoli est un bon catcheur, lui est un meilleur divertisseur sportif. Hager lui dit de bien r\u00e9fl\u00e9chir \u00e0 l&rsquo;offre.&nbsp;about:blank&nbsp;<\/p>\n\n\n\n<p><strong>Tournoi World Title Eliminator &#8211; Premier tour<\/strong><\/p>\n\n\n\n<p><strong>Brian Cage&nbsp;<em>accompagn\u00e9 de Prince Nana<\/em>&nbsp;vs Dante Martin<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Cage fait une Full Nelson Slam \u00e0 Martin et le couvre, mais il r\u00e9siste. Cage enchaine avec son Weapon X pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Brian Cage<\/strong><\/p>\n\n\n\n<p>&#8211; En coulisse, Lexy est avec Lee Moriarty et Stokely Hathaway pour avoir leur r\u00e9action sur le match de Jon Moxley. Moriarty dit qu&rsquo;il a perdu, mais il a montr\u00e9 qu&rsquo;il peut rivaliser contre le champion mondial. Alors c&rsquo;est le moment pour lui de gagner des titres et ce n&rsquo;est pas important qui s&rsquo;est. HOOK arrive, les deux se regardent et il quitte.<\/p>\n\n\n\n<p><strong>Tournoi World Title Eliminator &#8211; Premier tour<\/strong><\/p>\n\n\n\n<p><strong>RUSH vs Bandido<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Jos\u00e9 l&rsquo;assistant veut intervenir avec une chaise, mais John Silver arrive et le repousse. Bandido en profite pour faire un Roll Up sur RUSH pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Bandido<\/strong><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; En coulisse, on retrouve Death Triangle. Pac leur avise de continuer \u00e0 jouer de mani\u00e8re intelligente et utiliser son marteau selon la situation.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la renaissance de la House of Black.<\/p>\n\n\n\n<p><strong>Nyla Rose vs Kayla Sparks<\/strong><\/p>\n\n\n\n<p>Rose \u00e9crase Sparks en quelques minutes avec le Jaded pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnante : Nyle Rose<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Jade Cargill et les Baddies arrivent pour la confrontation. Rose repousse les Baddies sans probl\u00e8me, mais Cargill lui porte un coup de pied. Rose prend la fuite avec le championnat TBS, Cargill la pourchasse.<\/p>\n\n\n\n<p>&#8211; Pour l&rsquo;interview du main event. QT Marshall dit que Lee Johnson est revenu \u00e0 la maison et maintenant il va ramener un titre au Factory. Danhausen dit qu&rsquo;il va arracher les dents de Johnson ce soir. Cassidy dit que \u00e7a suffit de parler. Henry l&rsquo;arr\u00eate, c&rsquo;est le temps du main event !<\/p>\n\n\n\n<p><strong>AEW All-Atlantic Championship <\/strong><\/p>\n\n\n\n<p><strong>Lee Johnson&nbsp;<em>accompagn\u00e9 du Factory<\/em>&nbsp;vs Orange Cassidy (c)&nbsp;<em>accompagn\u00e9 des Best Friends<\/em><\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Lee \u00e9vite le finiser de Cassidy et lui porte une s\u00e9rie de coups. Lee le prend pour une Powerbomb, mais Cassidy tombe sur ses pieds et lui fait un Beach Break pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Orange Cassidy<\/strong><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Cole Karter veut attaquer Cassidy, mais Cassidy l&rsquo;\u00e9vite et lui fait un Orange Punch. Les Best Friends se font un c\u00e2lin au centre du ring avec Karter qui est bloqu\u00e9 et ils terminent avec leur Powerbomb \u00e0 trois pour terminer le show.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-text-align-center\">DAILYMOTION VIDEOS (HD QUALITY)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a rel=\"noreferrer noopener\" href=\"http:\/\/thechefonline.com\/cgi-bin\/megapro.php?File=y%26lister=none%26mirror=m6p1%26mainid=351428\" target=\"_blank\">Fullshow<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\">PVPHD VIDEOS (HD QUALITY)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a rel=\"noreferrer noopener\" href=\"http:\/\/thechefonline.com\/cgi-bin\/megapro.php?File=y%26lister=none%26mirror=pvp1%26mainid=351428\" target=\"_blank\">Fullshow<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\">SINGLE LINKS VIDEOS (HDTV QUALITY)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a rel=\"noreferrer noopener\" href=\"https:\/\/1.multiup.us\/f\/LrRww7niLq6k\" target=\"_blank\">Netu<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a rel=\"noreferrer noopener\" href=\"https:\/\/multiup.us\/files\/?id=11122022103441\" target=\"_blank\">Multiup<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\">DAILYMOTION VIDEOS (HD QUALITY)<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a rel=\"noreferrer noopener\" href=\"http:\/\/thechefonline.com\/cgi-bin\/megapro.php?File=y%26lister=none%26mirror=dlp1%26mainid=351428\" target=\"_blank\">Part1<\/a><a rel=\"noreferrer noopener\" href=\"http:\/\/thechefonline.com\/cgi-bin\/megapro.php?File=y%26lister=none%26mirror=dlp2%26mainid=351428\" target=\"_blank\">   <\/a><a rel=\"noreferrer noopener\" href=\"http:\/\/thechefonline.com\/cgi-bin\/megapro.php?File=y%26lister=none%26mirror=dlp2%26mainid=351428\" target=\"_blank\">Part2<\/a><a rel=\"noreferrer noopener\" href=\"http:\/\/thechefonline.com\/cgi-bin\/megapro.php?File=y%26lister=none%26mirror=dlp3%26mainid=351428\" target=\"_blank\">   <\/a><a rel=\"noreferrer noopener\" href=\"http:\/\/thechefonline.com\/cgi-bin\/megapro.php?File=y%26lister=none%26mirror=dlp3%26mainid=351428\" target=\"_blank\">Part3<\/a><a rel=\"noreferrer noopener\" href=\"http:\/\/thechefonline.com\/cgi-bin\/megapro.php?File=y%26lister=none%26mirror=dlp4%26mainid=351428\" target=\"_blank\">   <\/a><a rel=\"noreferrer noopener\" href=\"http:\/\/thechefonline.com\/cgi-bin\/megapro.php?File=y%26lister=none%26mirror=dlp4%26mainid=351428\" target=\"_blank\">Part4<\/a><\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>AEW Rampage Boston, Massachusetts, 10 novembre 2022 Les commentateurs sont Exalibur, Jim Ross et Tony Schiavone. &#8211; Le AEW Rampage d\u00e9marre avec Christian Cage et Luchasaurus qui arrivent sur le ring. Cage dit qu&rsquo;ils sont pr\u00eats pour le challenge de Jack Perry, ils attendent. Jack Perry arrive et dit que Luchasaurus et Chrisitian ont tout&#8230;<\/p>\n","protected":false},"author":4,"featured_media":77049,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,21,20],"tags":[],"ppma_author":[292],"class_list":["post-77048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-resultats","category-videos"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/77048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=77048"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/77048\/revisions"}],"predecessor-version":[{"id":77124,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/77048\/revisions\/77124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/77049"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=77048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=77048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=77048"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=77048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}