{"id":76327,"date":"2022-10-26T01:33:00","date_gmt":"2022-10-26T05:33:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=76327"},"modified":"2022-10-26T13:41:59","modified_gmt":"2022-10-26T17:41:59","slug":"pco-signe-avec-impact-wrestling-le-kingdom-est-all-elite-wrestling","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/10\/26\/pco-signe-avec-impact-wrestling-le-kingdom-est-all-elite-wrestling\/","title":{"rendered":"PCO Signe avec Impact Wrestling! \/ Le Kingdom est All Elite Wrestling!"},"content":{"rendered":"\n<p>Bonne nouvelle pour notre ancien coll\u00e8gue et lutteur Qu\u00e9b\u00e9cois trois fois champion par \u00e9quipe de la WWF, Champion Mondial ROH et Hardcore de la WCW qui nous repr\u00e9sente sur la sc\u00e8ne internationale.<\/p>\n\n\n\n<p>Nous avons eu la confirmation que PCO Pierre Carl Ouellet a sign\u00e9 une nouvelle entente avec Impact Wrestling apr\u00e8s que son clan les Honor no More se soit dissous et qu&rsquo;une partie soit pass\u00e9 \u00e0 la AEW\/ROH.<\/p>\n\n\n\n<p>L\u2019entente liera le French Frankenstein avec la compagnie canadienne jusqu\u2019au 31 octobre 2023.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Je suis tr\u00e8s content de signer une nouvelle entente avec Impact. La compagnie a vraiment mis le paquet pour me garder avec elle pour une autre ann\u00e9e\u00a0\u00bb, a mentionn\u00e9 l\u2019athl\u00e8te de 54 ans.<\/p><\/blockquote>\n\n\n\n<p>De plus, PCO aura son propre maquilleur professionnel, fourni par Impact maintenant, question de mettre davantage en valeur son personnage de monstre de Perfect Creation.<\/p>\n\n\n\n<p>Il s\u2019agit d\u2019une deuxi\u00e8me entente avec la compagnie. Jusqu\u2019\u00e0 tout r\u00e9cemment, il faisait partie du clan&nbsp;<em>Honor no More<\/em>&nbsp;clan contre lequel il s\u2019est tourn\u00e9, \u00e9tant donn\u00e9 le d\u00e9part de Mike Bennett, Matt Taven, Vincent et Maria Kanellis.<\/p>\n\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><\/p>\n\n\n\n<p>The Kingdom aurait bien sign\u00e9 avec la AEW. Mike Bennett, Matt Taven et Maria Kanellis du Kingdom ont termin\u00e9 avec Impact Wrestling le 8 octobre. Ils ont perdus lors des enregistrements post-Bound For Glory les titres par \u00e9quipe contre Heath et Rhino. Ils ont fait leurs d\u00e9buts \u00e0 la AEW le 14 octobre \u00e0 Rampage, techniquement toujours en tant que champions d\u2019Impact car le changement de titre n\u2019a \u00e9t\u00e9 diffus\u00e9 que le 20 octobre \u00e0 Impact.<\/p>\n\n\n\n<p>Notre source selecte note que Bennett, Taven et Kanellis ont tous sign\u00e9 des contrats de plusieurs ann\u00e9es \u00e0 temps plein avec la All Elite, et ils ont lanc\u00e9 un d\u00e9fi aux champions du monde par \u00e9quipe AAA, IWGP et ROH FTR pour leurs d\u00e9buts \u00e0 Rampage, pour les titres ROH.<\/p>\n\n\n\n<p>The Kingdom n\u2019avait pas sign\u00e9 de contrats \u00e0 la AEW lors de leurs d\u00e9buts \u00e0 Rampage \u00e0 Toronto, c&rsquo;\u00e9tait un \u00ab\u00a0pay day\u00a0\u00bb, comme on dit dans le milieux, mais sont maintenant avec la All Elite Wrestling.<\/p>\n\n\n\n<p>On sait que la WWE voulait signer un contrat avec Taven. La rumeur dit maintenant que Bennett et Kanellis ont \u00e9galement eu des discussions avec la WWE. Kanellis rejoint Brandi Rhodes en tant que seules femmes \u00e0 \u00eatre apparue\u00a0 pour AEW, WWE, ROH, Impact et NJPW. Elle d\u00e9clare\u00a0 vouloir aider le propri\u00e9taire de la ROH, Tony Khan, \u00e0 faire grandir la promotion et la division f\u00e9minine de la ROH. Mais pour l\u2019instant, elle n\u2019est que talent sur le ring.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Bonne nouvelle pour notre ancien coll\u00e8gue et lutteur Qu\u00e9b\u00e9cois trois fois champion par \u00e9quipe de la WWF, Champion Mondial ROH et Hardcore de la WCW qui nous repr\u00e9sente sur la sc\u00e8ne internationale. Nous avons eu la confirmation que PCO Pierre Carl Ouellet a sign\u00e9 une nouvelle entente avec Impact Wrestling apr\u00e8s que son clan les&#8230;<\/p>\n","protected":false},"author":609,"featured_media":76328,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,22,4,49,41],"tags":[],"ppma_author":[295],"class_list":["post-76327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-news","category-roh","category-tna-impact"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/76327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=76327"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/76327\/revisions"}],"predecessor-version":[{"id":76329,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/76327\/revisions\/76329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/76328"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=76327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=76327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=76327"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=76327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}