{"id":74265,"date":"2022-09-14T03:11:00","date_gmt":"2022-09-14T07:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=74265"},"modified":"2022-09-14T13:20:53","modified_gmt":"2022-09-14T17:20:53","slug":"cody-rhodes-parle-de-la-roh-pco-explique-pourquoi-il-a-choisi-la-ring-of-honnor","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/09\/14\/cody-rhodes-parle-de-la-roh-pco-explique-pourquoi-il-a-choisi-la-ring-of-honnor\/","title":{"rendered":"Cody Rhodes parle de la ROH! \/ PCO explique pourquoi il a choisi la Ring of Honnor!"},"content":{"rendered":"\n<p>En 2018, PCO \u00e9tait l\u2019un des agents libres les plus convoit\u00e9s du business apr\u00e8s avoir remport\u00e9 le titre poids lourd Canadien \u00e0 la GNW. <\/p>\n\n\n\n<p>Le v\u00e9t\u00e9ran qu\u00e9b\u00e9cois a alors re\u00e7u \u00e0 cette \u00e9poque deux propositions concr\u00e8tes, l\u2019une de la ROH et l\u2019autre de la AEW pas encore en activit\u00e9. Pour Wrestling Inc. Le 3 fois champion par \u00e9quipe de la WWF, explique ce qui l\u2019a pouss\u00e9 dans les bras de la premi\u00e8re au d\u00e9triment de la seconde:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Quand la AEW a d\u00e9marr\u00e9, je ne comprenais pas tout. Je parlais avec Marty (Scurll) d\u2019un c\u00f4t\u00e9 qui repr\u00e9sentait la ROH et de l\u2019autre avec Cody (Rhodes) et les Bucks. Ils ne se parlaient plus entre eux ce que je ne savais pas. J\u2019avais en t\u00eate qu\u2019ils \u00e9taient de vrais bons amis. Je n\u2019ai jamais cru possible que Scurll puisse ne pas les suivre dans ce qui allait devenir la AEW (\u2026)<\/p><p>J\u2019ai opt\u00e9 pour la s\u00e9curit\u00e9. Je ne connaissais pas Tony (Khan). Je ne savais pas pour combien de temps il pr\u00e9voyait d\u2019investir. Ils n\u2019avaient pas de deal TV \u00e0 l\u2019\u00e9poque aussi. Ils avaient quelques pay-per-views qui approchaient mais je devais prendre une d\u00e9cision pour moi-m\u00eame. J\u2019ai pr\u00e9f\u00e9r\u00e9 aller \u00e0 la ROH parce que (le r\u00e9seau TV) Sinclair \u00e9tait derri\u00e8re.<\/p><\/blockquote>\n\n\n\n<p>Alors voici le choix qu&rsquo;a fait PCO apr\u00e8s avoir \u00e9t\u00e9 notre collaborateur en 2017, puis a rejoint Impact Wrestling apr\u00e8s son run \u00e0 la Ring of Honnor!<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Rhodes a fait ses d\u00e9buts au Ring of Honor Final Battle 2016, quelques mois seulement apr\u00e8s avoir quitt\u00e9 la WWE. Il est rapidement devenu l&rsquo;une des meilleures stars de la promotion et \u00e0 remporter le championnat du monde ROH au \u00ab Best in the World 2017 \u00bb. Cette m\u00eame ann\u00e9e, il a remport\u00e9 le prix ROH du lutteur de l&rsquo;ann\u00e9e. Rhodes a ensuite quitt\u00e9 l&rsquo;entreprise apr\u00e8s Final Battle 2018 et a fond\u00e9 la \u00ab All Elite Wrestling \u00bb.<\/p>\n\n\n\n<p>Dans un tweet du 13 ao\u00fbt, Rhodes a r\u00e9pondu \u00e0 un fan qui a d\u00e9clar\u00e9 que sa course ROH \u00e9tait un moment amusant. \u00ab\u00a0The American Nightmare\u00a0\u00bb a d\u00e9clar\u00e9 que la soci\u00e9t\u00e9 \u00e9tait \u00ab\u00a0si bonne avec lui\u00a0\u00bb, et il a repens\u00e9 \u00e0 son travail avec un certain nombre de lutteurs de renom, dont The Young Bucks et Jay Lethal. Il a \u00e9galement f\u00e9licit\u00e9 l&rsquo;\u00e9quipe de production et a not\u00e9 que son temps avec ROH l&rsquo;avait fa\u00e7onn\u00e9. Dans l&rsquo;ensemble, il a soulign\u00e9 qu&rsquo;ils avaient chang\u00e9 le monde de la lutte.<\/p>\n\n\n\n<p>Cody Rhodes est toujours sur la touche \u00e0 la WWE apr\u00e8s une impressionnante blessure au muscle pectoral. Esp\u00e9rons le revoir tr\u00e8s bient\u00f4t.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Happy Anniversary <a href=\"https:\/\/twitter.com\/TheBrandiRhodes?ref_src=twsrc%5Etfw\">@TheBrandiRhodes<\/a> &#8211; today is the best day. Thank you for the endless unspoken sacrifices you\u2019ve made for me, for being the best mom, and being the ultimate confidant (oldie but a goodie pic) <a href=\"https:\/\/t.co\/AKCHiq9yss\">pic.twitter.com\/AKCHiq9yss<\/a><\/p>\u2014 Cody Rhodes (@CodyRhodes) <a href=\"https:\/\/twitter.com\/CodyRhodes\/status\/1569329285319491591?ref_src=twsrc%5Etfw\">September 12, 2022<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>En 2018, PCO \u00e9tait l\u2019un des agents libres les plus convoit\u00e9s du business apr\u00e8s avoir remport\u00e9 le titre poids lourd Canadien \u00e0 la GNW. Le v\u00e9t\u00e9ran qu\u00e9b\u00e9cois a alors re\u00e7u \u00e0 cette \u00e9poque deux propositions concr\u00e8tes, l\u2019une de la ROH et l\u2019autre de la AEW pas encore en activit\u00e9. Pour Wrestling Inc. Le 3 fois&#8230;<\/p>\n","protected":false},"author":609,"featured_media":74266,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,4,49,41],"tags":[],"ppma_author":[295],"class_list":["post-74265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-news","category-roh","category-tna-impact"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/74265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=74265"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/74265\/revisions"}],"predecessor-version":[{"id":74268,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/74265\/revisions\/74268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/74266"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=74265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=74265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=74265"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=74265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}