{"id":73773,"date":"2022-09-02T22:34:24","date_gmt":"2022-09-03T02:34:24","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=73773"},"modified":"2022-09-05T12:26:53","modified_gmt":"2022-09-05T16:26:53","slug":"resultats-et-video-du-wwe-friday-night-smackdown-du-2-septembre-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/09\/02\/resultats-et-video-du-wwe-friday-night-smackdown-du-2-septembre-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du WWE Friday Night Smackdown du 2 septembre 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/09\/02\/deux-ans-de-regne-ca-se-fete-lavenir-wwe-de-rousey-dernier-smackdown-avant-clash-at-the-castle-et-plus-ce-soir\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce Smackdown, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p><strong>WWE SmackDown D\u00e9troit, Michigan, 2 septembre 2022<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Michael Cole et Pat McAfee.<\/p>\n\n\n\n<p>&#8211; Le WWE SmackDown, d\u00e9marre&nbsp;avec l\u2019arriv\u00e9e des Viking Raiders suivi du New Day pour le premier combat de la soir\u00e9e.&nbsp;<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Viking Rules Match<\/strong><\/p>\n\n\n\n<p><strong>Viking Raider (Ivar &amp; Erik) vs The New Day (Kofi Kingston &amp; Xavier Woods)<\/strong><\/p>\n\n\n\n<p>Durant le match, Kofi Kingston porte un coup de marteau de la troisi\u00e8me corde directement sur le cr\u00e2ne d\u2019Erik puis il effectue le tomb\u00e9, mais \u00e7a ne suffit pas.<\/p>\n\n\n\n<p>\u00c0 la fin du match, Kofi Kingston saute de la troisi\u00e8me corde, mais Ivar lui envoie un bouclier en pleine face pour le mettre hors d&rsquo;\u00e9tat de nuire. Erik et Ivar prennent Xavier Woods et le font passer \u00e0 travers 2 tables \u00e0 l&rsquo;ext\u00e9rieur du ring pour la victoire.<\/p>\n\n\n\n<p><em>Gagnants : Viking Raider (Ivar &amp; Erik)<\/em><\/p>\n\n\n\n<p>&#8211; La premi\u00e8re partie d&rsquo;une vid\u00e9o sur l&rsquo;ascension de Roman Reigns en tant que Tribal Chief est diffus\u00e9e, avec Paul Heyman \u00e0 la narration.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Apr\u00e8s la coupure publicitaire, nous avons un r\u00e9capitulatif de ce qu\u2019il s\u2019est pass\u00e9 la semaine derni\u00e8re avec l\u2019attaque de la Bloodline sur Drew McIntyre.<\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Sami Zayn qui sera le ma\u00eetre de c\u00e9r\u00e9monie de la c\u00e9l\u00e9bration des deux ans de r\u00e8gne de Roman Reigns ce soir, avec les Usos. Sami Zayn leur dit que la c\u00e9l\u00e9bration de ce soir sera unique, car c\u2019est tr\u00e8s rare de d\u00e9tenir un titre aussi longtemps. Il dit qu\u2019il a pr\u00e9par\u00e9 des photos pour l&rsquo;occasion. Jey Uso l&rsquo;interrompt et dit que c\u2019est Paul Heyman qui aurait d\u00fb \u00eatre l\u00e0 ce soir et il demande \u00e0 Sami Zayn pourquoi il ne l\u2019a pas aid\u00e9 \u00e0 RAW face \u00e0 Kevin Owens. Jey se calme et dit que Sami semble avoir la situation en main pour ce soir et s\u2019en va.<\/p>\n\n\n\n<p>&#8211; On retrouve ensuite Kayla Braxton avec Shayna Baszler qui lui dit qu\u2019elle va s\u2019occuper et d\u00e9truire Liv Morgan pour lui prendre ce titre de championne du monde, mais elle ne continue pas car la championne d\u00e9barque. Elle dit \u00e0 Shayna Baszler qu\u2019elle va d\u00e9truire son bras et qu\u2019elle ne pourra que contempler \u00e7a.<\/p>\n\n\n\n<p>&#8211; Nous avons une promo de Karrion accompagn\u00e9 de Scarlett Bordeaux. Karrion Kross nous dit que ce soir Drew McIntyre va r\u00e9fl\u00e9chir longuement \u00e0 ce qui lui est arriv\u00e9 la semaine derni\u00e8re. Roman Reigns va c\u00e9l\u00e9brer ses deux ans de r\u00e8gne et lui, va faire regretter certaines choses \u00e0 Drew Gulak.<\/p>\n\n\n\n<p>&#8211; La deuxi\u00e8me partie de la vid\u00e9o sur Roman Reigns est diffus\u00e9e.<\/p>\n\n\n\n<p>&#8211; C\u2019est l&rsquo;heure du premier match \u00e0 Smackdown pour Karrion Kross qui d\u00e9barque sur le ring aux c\u00f4t\u00e9s de Scarlett Bordeaux.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Karrion Kross acc de Scarlett Bordeaux vs Drew Gulak<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Karrion Kross balance Drew Gulak directement sur la t\u00eate avec une Saito Suplex puis il encha\u00eene avec un Rear Naked Choke (\u00e9tranglement arri\u00e8re) et termine avec le tomb\u00e9 pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Karrion Kross<\/em><\/p>\n\n\n\n<p>&#8211; Nous avons un r\u00e9capitulatif de ce qu\u2019il s&rsquo;est pass\u00e9 avec Ronda Rousey lors de son arrestation et ce soir, nous aurons la d\u00e9cision finale concernant son sort.<\/p>\n\n\n\n<p>&#8211; Apr\u00e8s la coupure publicitaire, nous avons la 3e partie de la vid\u00e9o sur Roman Reigns.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; C\u2019est maintenant l\u2019heure d&rsquo;accueillir Ronda Rousey qui arrive sur le ring avec des documents. Ronda dit qu\u2019elle a une d\u00e9claration officielle du quartier g\u00e9n\u00e9ral de la WWE et elle demande \u00e0 Adam Pierce de venir sur le ring. Adam Pearce vient sur le ring et dit que toutes les d\u00e9cisions prises de sa part contre Ronda Rousey n\u2019ont jamais \u00e9t\u00e9 personnelles. Ronda Rousey lui r\u00e9pond qu\u2019il ment et lui demande de lire la lettre qu\u2019elle a re\u00e7ue. La lettre dit que malgr\u00e9 le comportement de Ronda Rousey, elle ne m\u00e9ritait pas d&rsquo;\u00eatre trait\u00e9e comme une criminelle et donc que son arrestation est totalement injustifi\u00e9e. Ronda Rousey est donc en probation et est donc r\u00e9int\u00e9gr\u00e9e. Ronda Rousey est heureuse et demande \u00e0 Adam Pearce pourquoi il fait cette t\u00eate. Adam Pearce lui r\u00e9pond qu\u2019il en a marre de ne pas \u00eatre trait\u00e9 \u00e0 sa juste valeur et que son travail ne soit pas reconnu. Il dit qu\u2019il en a marre des gens comme Ronda Rousey pour qui il fait \u00e9norm\u00e9ment, mais qui sont ingrats. Il termine en disant que Ronda Rousey est la plus grande salope qu\u2019il n\u2019ait jamais rencontr\u00e9 de sa vie. Ronda s\u2019approche vers Adam Pearce qui dit qu\u2019il a parl\u00e9 un peu trop vite et que c\u2019est d\u00fb au stress. Ronda l\u2019attaque et lui applique un Jujigatame.<\/p>\n\n\n\n<p>&#8211; On retrouve Sami Zayn dans les vestiaires qui re\u00e7oit un bouquet de fleurs. Sami Zayn est encore \u00e0 cause de l\u2019odeur naus\u00e9abonde de ces fleurs puis sur la carte, on voit \u00e9crit \u201c Tick Tock\u201d. Sami Zayn pose le bouquet et fait comme si de rien \u00e9tait.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Hit Row (Ashante Thee Adonis &amp; Top Dolla acc de B-Fab vs MMM Mace &amp; Mansoor ac de Max &amp; Maxxine Dupri<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Ashante Thee Adonis porte un Dropkick sur Mace et Top Dolla encha\u00eene avec un Belly to Back Suplex pour la victoire.<\/p>\n\n\n\n<p><em>Gagnants : Hit Row <\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, Angel Garza et Humberto Carrillo viennent autour du ring, ce qui permet \u00e0 Mace et Mansoor d\u2019attaquer les deux membres de Hit Row quand soudain les Street Profits (Angelo Dawkins &amp; Montez Ford) d\u00e9barquent pour pr\u00eater main forte \u00e0 Hit Row en se d\u00e9barrassant d\u2019Angel Garza, Humberto Carillo et de MMM.<\/p>\n\n\n\n<p>&#8211; Nous avons un r\u00e9capitulatif de la victoire de Ricochet sur Happy Corbin.<\/p>\n\n\n\n<p>&#8211; En coulisse, Happy Corbin dit \u00e0 Kayla Braxton qu\u2019il ne veut pas parler de la victoire miraculeuse de Ricochet, car il ne vit pas dans le pass\u00e9. Il dit qu\u2019il a toujours su remonter la pente apr\u00e8s avoir v\u00e9cu des moments difficile et ce soir, il va faire un open challenge.<\/p>\n\n\n\n<p>&#8211; La 4e partie de la vid\u00e9o sur Roman Reigns est diffus\u00e9e.<\/p>\n\n\n\n<p>&#8211; Happy Corbin vient sur le ring et c\u2019est la musique du King of Strong Style qui retentit.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Happy Corbin vs Shinsuke Nakamura<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Happy Corbin fait sa glissade pour se retrouver \u00e0 l&rsquo;ext\u00e9rieur du ring, mais en remontant, il est accueilli par le Kinshasa de Shinsuke Nakamura pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Shinsuke Nakamura<\/em><\/p>\n\n\n\n<p>&#8211; Nous avons un r\u00e9capitulatif de la victoire de Raquel Gonzalez et Aliyah lors de la finale du tournoi feminin par \u00e9quipe face \u00e0 IYO SKY et Dakota Kai.<\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve un Happy Corbin d\u00e9pit\u00e9 quand soudain une limousine arborant des cordes \u00e0 la JBL s&rsquo;arr\u00eate \u00e0 c\u00f4t\u00e9 de lui et une voix lui demande ce qu\u2019il se passe avec lui et lui demande de monter. La limousine s\u2019en va avec JBL et Baron Corbin \u00e0 son bord.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Butch acc de Sheamus &amp; Ridge Holland vs Ludwig Kaiser acc de Gunther<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Ludwig Kaiser tente de porter un Swinging Reverse DDT, mais Butch attrape ses doigts et les craque puis il encha\u00eene avec son Bitter End pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Butch <\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, Sheamus et Gunther sont pr\u00eats \u00e0 en d\u00e9coudre, mais Ludwig Kaiser dissuade son partenaire et ils s\u2019en vont.<\/p>\n\n\n\n<p>&#8211; Nous avons la 5e et derni\u00e8re partie de la vid\u00e9o sur les exploits de Roman Reigns durant ces deux derni\u00e8res ann\u00e9es.<\/p>\n\n\n\n<p>&#8211; Dans les vestiaires, on retrouve Sami Zayn et les Usos. Jey Uso dit qu\u2019il faut aller sur le ring, mais Sami Zayn pense qu\u2019il faudrait attendre Roman Reigns pour une entr\u00e9e avec toute la Bloodline. Jey Uso s&rsquo;\u00e9nerve et dit pourquoi il se met dans le lot en disant toute la Bloodline. Jimmy calme tout le monde et dit que ce soir, c\u2019est une nuit de c\u00e9l\u00e9bration pour le Chef Tribal.<\/p>\n\n\n\n<p>&#8211; Une vid\u00e9o de Tyson Fury annon\u00e7ant sa pr\u00e9sence en ringside lors de Clash at the Castle \u00e0 Cardiff ce samedi est diffus\u00e9e.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; Sami Zayn et les Usos d\u00e9barquent sur le ring et nous accueillent pour la c\u00e9l\u00e9bration des 2 ans de r\u00e8gne de Roman Reigns. Jimmy Uso demande au membre honoraire de la Bloodline de faire ce qu\u2019il a \u00e0 faire en tant que ma\u00eetre de c\u00e9r\u00e9monie, mais Jey Uso le fait \u00e0 sa place. Jey dit que depuis 2 ans, Roman Reigns d\u00e9cime tout ceux qu&rsquo;ils le mettent sur son chemin. Il les a tous terrasses a coup de Superman Punch, Spear et Guillotine. Les trois hommes demandent ensuite \u00e0 tous les fans de se mettre debout pour accueillir le Chef Tribal et actuel champion indiscut\u00e9 de la WWE. Sur le titantron, on voit Roman Reigns qui sort de sa voiture quand soudain il se fait mettre K.O par un Big Boot de Drew McIntyre qui vient ensuite sur le ring, met Sami Zayn K.O avec un Glasgow Kiss puis un Claymore Kick&nbsp; et d\u00e9truit les Usos avec un Spear en mode Roman Reigns contre la barricade en mimant les m\u00eames gestes que le Chef Tribal.<\/p>\n\n\n\n<p>Drew McIntyre prend ensuite le micro et dit qu\u2019\u00e0 Clash at the Castle il va d\u00e9sactiver le God Mode du Chef Tribal et il va lui arracher la t\u00eate pour devenir le nouveau champion.<\/p>\n\n\n\n<p>Le show se termine avec la c\u00e9l\u00e9bration de Drew McIntyre.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/09\/02\/deux-ans-de-regne-ca-se-fete-lavenir-wwe-de-rousey-dernier-smackdown-avant-clash-at-the-castle-et-plus-ce-soir\/\" target=\"_blank\">Pour voir ce Smackdown, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce Smackdown, cliquez ici. WWE SmackDown D\u00e9troit, Michigan, 2 septembre 2022 Les commentateurs sont Michael Cole et Pat McAfee. &#8211; Le WWE SmackDown, d\u00e9marre&nbsp;avec l\u2019arriv\u00e9e des Viking Raiders suivi du New Day pour le premier combat de la soir\u00e9e.&nbsp; Viking Rules Match Viking Raider (Ivar &amp; Erik) vs The New Day (Kofi Kingston&#8230;<\/p>\n","protected":false},"author":4,"featured_media":73777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,36,23],"tags":[],"ppma_author":[292],"class_list":["post-73773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/73773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=73773"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/73773\/revisions"}],"predecessor-version":[{"id":73909,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/73773\/revisions\/73909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/73777"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=73773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=73773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=73773"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=73773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}