{"id":73493,"date":"2022-08-25T10:44:00","date_gmt":"2022-08-25T14:44:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=73493"},"modified":"2022-08-25T11:13:01","modified_gmt":"2022-08-25T15:13:01","slug":"la-aew-et-tony-khan-ne-se-laisse-pas-faire-par-le-maraudage-de-la-wwe-envers-son-roster","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/08\/25\/la-aew-et-tony-khan-ne-se-laisse-pas-faire-par-le-maraudage-de-la-wwe-envers-son-roster\/","title":{"rendered":"La AEW et Tony Khan ne se laisse pas faire par le maraudage de la WWE envers son Roster!"},"content":{"rendered":"\n<p>Nous vous en avions parl\u00e9 il y a quelque jour, une star sous contrat avec la All Elite Wrestling a \u00e9t\u00e9\u00a0approch\u00e9 par la WWE, qui a fait comprendre qu&rsquo;il \u00e9tait tr\u00e8s heureux dans la compagnie de Tony Khan et ne souhaitait pas partir. Cette rumeur est arriv\u00e9e jusqu&rsquo;aux oreilles de la AEW qui ne compte pas laisser la concurrence faire ce qu&rsquo;elle souhaite.<\/p>\n\n\n\n<p>Quelques heures avant la diffusion en live de\u00a0Dynamite, Tony Khan a organis\u00e9 une r\u00e9union avec les talents de la AEW afin de mettre au clair plusieurs sujets et il est revenu sur la rumeur selon laquelle la WWE a contact\u00e9 un des talents de de l&rsquo;organisation, selon Fightful et le PWInsider.<\/p>\n\n\n\n<p>Durant cette r\u00e9union, Tony Khan a r\u00e9v\u00e9l\u00e9 que Megha Parekh, responsable des affaires juridiques de la AEW, a envoy\u00e9\u00a0un mail \u00e0 Nick Khan et Stephanie McMahon afin de les pr\u00e9venir de \u00ab\u00a0ne pas essayer de soudoyer\u00a0\u00bb les catcheurs ainsi que catcheuses de la All Elite Wrestling. Dans tous les sports professionnel on appel cela du maraudage. <\/p>\n\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Ces deux sources am\u00e9ricaines notent \u00e9galement que Tony Khan \u00e9tait \u00ab\u00a0enflamm\u00e9\u00a0\u00bb durant cette r\u00e9union et qu&rsquo;il a affirm\u00e9 que de nouveaux dispositifs ont \u00e9t\u00e9 mis en place derni\u00e8rement au sein de la compagnie, concernant par exemple les relations avec les talents ou encore le d\u00e9veloppement, dans le but de rendre les choses meilleures pour les catcheurs.<\/p>\n\n\n\n<p>Le manque de communication, qui est beaucoup reproch\u00e9 \u00e0 Tony Khan ces derniers temps, a \u00e9t\u00e9 abord\u00e9. Kenny Omega et les Young Bucks ont aussi d\u00e9clar\u00e9 que leur porte \u00e9tait toujours ouverte et qu&rsquo;ils peuvent \u00eatre contact\u00e9s en cas de probl\u00e8me. Chris Jericho et Tony Schiavone ont \u00e9galement pu parler lors de cette r\u00e9union.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Nous vous en avions parl\u00e9 il y a quelque jour, une star sous contrat avec la All Elite Wrestling a \u00e9t\u00e9\u00a0approch\u00e9 par la WWE, qui a fait comprendre qu&rsquo;il \u00e9tait tr\u00e8s heureux dans la compagnie de Tony Khan et ne souhaitait pas partir. Cette rumeur est arriv\u00e9e jusqu&rsquo;aux oreilles de la AEW qui ne compte&#8230;<\/p>\n","protected":false},"author":4,"featured_media":73494,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,4,23],"tags":[],"ppma_author":[292],"class_list":["post-73493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/73493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=73493"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/73493\/revisions"}],"predecessor-version":[{"id":73495,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/73493\/revisions\/73495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/73494"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=73493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=73493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=73493"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=73493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}