{"id":71595,"date":"2022-07-04T21:57:44","date_gmt":"2022-07-05T01:57:44","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=71595"},"modified":"2022-07-06T21:54:18","modified_gmt":"2022-07-07T01:54:18","slug":"resultats-et-video-du-wwe-monday-night-raw-du-4-juillet-2022-lapres-money-in-the-bank-mitb","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/07\/04\/resultats-et-video-du-wwe-monday-night-raw-du-4-juillet-2022-lapres-money-in-the-bank-mitb\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du WWE Monday Night RAW du 4 Juillet 2022! L&rsquo;apr\u00e8s Money in the Bank #MitB !"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/07\/04\/regardez-le-wwe-monday-night-raw-du-4-juillet-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce RAW, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>WWE RAW San Diego, Californie, 4 juillet 2022<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Jimmy Smith, Corey Graves et Byron Saxton.<\/p>\n\n\n\n<p>&#8211; Le WWE Monday Night RAW, d\u00e9bute avec une vid\u00e9o pour honorer les c\u00e9l\u00e9brations du 4 juillet qui est le jour de l&rsquo;ind\u00e9pendance sux USA. On a la chance d&rsquo;avoir la voix de John Cena \u00e0 la naration.<\/p>\n\n\n\n<p>Les commentateurs nous souhaitent ensuite la bienvenue et pr\u00e9sentent la carte de la soir\u00e9e.<\/p>\n\n\n\n<p>&#8211; Le nouveau champion des \u00c9tats-Unis, Bobby Lashley, arrive ensuite sur le ring. Lashley dit qu&rsquo;il attendait ce moment depuis bien longtemps : bienvenue \u00e0 Monday Night RAW. Lashley dit que le Jour de l&rsquo;Ind\u00e9pendance prend une place sp\u00e9ciale dans tous nos coeurs. Il ne peut pas \u00eatre plus fier que d&rsquo;\u00eatre devant la WWE Universe comme le nouveau champion USA. Ce n&rsquo;est pas le titre qui fait l&rsquo;homme, mais bien l&rsquo;homme qui fait le titre. Il dit \u00e7a pour annoncer ceci.&nbsp;Lashley dit qu&rsquo;il n&rsquo;y a pas un autre homme dans n&rsquo;importe quelle division ou compagnie qui peut le battre pour le championnat des \u00c9tats-Unis&nbsp;! <\/p>\n\n\n\n<p>La musique de Theory commence et il arrive avec sa mallette. Theory demande pourquoi Lashley a le droit de lancer RAW ? Theory dit que tout le monde attendait sa r\u00e9action apr\u00e8s Money in the Bank. Oui Lashley a gagn\u00e9, mais le monde parle du gagnant le plus jeune de l&rsquo;histoire du Money in the Bank. Il avait les chances contre lui, un boulot difficile. Il \u00e9tait dans le match avec des v\u00e9t\u00e9rans, des anciens gagnants MITB, mais il a r\u00e9ussi. Il doit admettre que Lashley l&rsquo;a battu dans la premi\u00e8re p\u00e9riode, mais comme Michael Jordan ou Tom Brady, il est revenu pour monter sur l&rsquo;\u00e9chelle et prouver au monde qu&rsquo;il peut le faire pendant toute la journ\u00e9e. Lashley dit que Theory devient un idiot arrogant. Theory s&rsquo;est lanc\u00e9 dans le MITB car il a cass\u00e9 l&rsquo;\u00e9go de Theory en millions de morceaux. Si Theory veut une autre promenade dans le Hurt Lock, il peut lui donner. <\/p>\n\n\n\n<p>Theory dit qu&rsquo;ils vont se voir dans le Six-Man Tag ce soir. Il voit Lashley, Lashley le voit et il accomplit. Il voit qu&rsquo;il va direct au top avec la mallette.<strong>&nbsp;<\/strong> Il a aussi appris qu&rsquo;il aura un combat \u00e0 SummerSlam, un rematch pour le titre des \u00c9tats-Unis&nbsp;! Un premier plan pour SummerSlam.&nbsp;Et le second, Roman Reigns va affronter Brock Lesnar en Last Man Standing pour une derni\u00e8re fois. Celui qui sera le dernier homme debout va se faire couler par Theory. Il va sortir de Nashville comme le champion unifi\u00e9, le meilleur champion de l&rsquo;histoire. Lashley dit que Theory a oubli\u00e9 qu&rsquo;il fait partie du plan, \u00e7a d\u00e9pend si Theory sera capable d&rsquo;atteindre SummerSlam. C&rsquo;est le Jour de l&rsquo;Ind\u00e9pendance et les gens veulent des feux d&rsquo;artifice.<\/p>\n\n\n\n<p>Lashley lance son micro au sol. Theory lance sa mallette sur Lashley pour le distraire et le frappe ! Theory commece \u00e0 le rouer de coups avec sa mallette, mais Lashley le repousse et lui fait une Slam. Theory prend la fuite.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, on demande aux Mysterio leur r\u00e9ponse \u00e0 Finn Balor. Dominik Mysterio dit que c&rsquo;\u00e9tait honteux, un manque de respect. La seule personne avec qui il veut apprendre c&rsquo;est son p\u00e8re. Rey dit qu&rsquo;ils sont le premier duo p\u00e8re et fils avec les titres par \u00e9quipe, alors il doit bien former. En plus c&rsquo;est la premi\u00e8re fois que Dominik aura un match \u00e0 San Diego et lui qui fait son retour apr\u00e8s beaucoup d&rsquo;ann\u00e9es. C&rsquo;est leur maison ici, ils vont montrer comment il faut respecter les Mysterio dans le 619.<\/p>\n\n\n\n<p>&#8211; Les Mysterio arrivent sur le ring. La musique du Judgment Day commence, mais ils arrivent par derri\u00e8re pour attaquer les Mysterio.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, le match se lance.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Rey et Dominik Mysterio vs Finn Balor et Damian Priest<\/strong><\/p>\n\n\n\n<p>En fin de match,  Dominik fait un Drop Kick \u00e0 Priest pour le repousser sur la deuxi\u00e8me corde. Les Mysterio font un Double 619. Rey enchaine avec un Splash sur Balor, mais Balor le bloque avec ses genoux et un compte rapide, mais Rey r\u00e9siste. Priest lance une chaise sur le ring et distrait l&rsquo;arbitre. Rey se couche au sol pour jouer le faux coup de chaise, l&rsquo;arbitre se retourne et arr\u00eate le match.<\/p>\n\n\n\n<p><em>Gagnants : Rey et Dominik Mysterio&nbsp;par DQ<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, les Mysterio vont c\u00e9l\u00e9brer sur la sc\u00e8ne pendant que le Judgment Day est furieux.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la&nbsp;signature de Logan Paul \u00e0 la WWE.<\/p>\n\n\n\n<p>&#8211; En coulisse, Megan est avec le Miz pour avoir sa r\u00e9action sur Logan Paul qui vient l&rsquo;affronter. Miz dit qu&rsquo;il est fier. Il aime la confiance, ce qui fait parler les gens, ce qui fait de grands titres. Paul a une grande base de fans, mais il est encercl\u00e9 d&rsquo;une \u00e9quipe qui font seulement lui dire oui. \u00c0 la WWE c&rsquo;est diff\u00e9rent. Il est un gars gentil, Paul devrait changer d&rsquo;id\u00e9e et accepter son offre. Ensemble ils pourront devenir les champions par \u00e9quipe de la WWE.&nbsp;Si Paul n&rsquo;accepte pas son offre, il sera sans piti\u00e9 et il va faire tout regretter \u00e0 Paul.&nbsp;<\/p>\n\n\n\n<p>Megan lui demande pourquoi il a quitt\u00e9 son match la semaine derni\u00e8re. Miz dit qu&rsquo;il a eu deux matchs la semaine derni\u00e8re, ce n&rsquo;\u00e9tait pas le temps de faire des blagues.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o de plus t\u00f4t aujourd&rsquo;hui. Les Street Profits organisent une f\u00eate du 4 juillet avec des amis et des WWE Superstars. Angelo Dawkins invite tout le monde \u00e0 prendre de la nourriture, un verre et profiter. American Alpha arrive. Chad Gable demande le silence. Gable demande comment ils peuvent faire la f\u00eate apr\u00e8s la d\u00e9faite ? Ford avait son \u00e9paule lev\u00e9e, mais ils ont perdu au final. Au moins il est ici pour donner une le\u00e7on d&rsquo;histoire. Ford dit que la constitution explique que tout le monde a le droit de couper Gable. Ford le frappe avec une saucisse. Otis dit de faire attention au h\u00e9ros am\u00e9ricain. Dawkins dit qu&rsquo;il regarde au trois fois champion de mangeur de hot-dogs. Otis dit qu&rsquo;il peut rivaliser sans probl\u00e8me. Ford officialise le challenge.<\/p>\n\n\n\n<p>&#8211; En coulisse, les Mysterio marchent, mais ils se font attaquer par Damian Priest et Finn Balor. Ils lancent les Mysterio contre les murs. Les officiels arrivent pour stopper l&rsquo;attaque.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>AJ Styles vs The Miz<\/strong><\/p>\n\n\n\n<p>En finde match, AJ fait son Phenomenal Forearm sur le Miz pour le compte de trois.<\/p>\n\n\n\n<p>Gagnant : AJ Styles<\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, AJ c\u00e9l\u00e8bre sur le ring, mais Ciampa arrive et le frappe dans le dos ! AJ arrive \u00e0 le repousser et lui faire un Pele Kick. AJ prend Ciampa pour son finisher, mais Miz revient et surprend AJ avec son Skull Crushing Finale !<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o de la victoire de Liv Morgan face \u00e0 Ronda Rousey \u00e0&nbsp;Money in the Bank samedi dernier. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; La nouvelle championne de SmackDown,&nbsp;<strong>Liv Morgan<\/strong>, arrive ensuite sur le ring sous une ovation. Morgan dit qu&rsquo;elle est fi\u00e8re d&rsquo;\u00eatre devant nous comme la championne de SmackDown. Tous ses r\u00eaves se sont r\u00e9alis\u00e9s dans la soir\u00e9e de Money in the Bank. Vaincre six des meilleures catcheuses de la WWE dans la bataille la plus difficile de sa vie. La WWE Universe lui a permis de traverser l&rsquo;\u00e9preuve. On est rest\u00e9 avec elle dans ce parcours \u00e0 chacune des \u00e9tapes. On a cru en elle, m\u00eame aux moments o\u00f9 elle pensait ne plus rien nous donner. On lui a donn\u00e9 la confiance, la confiance qu&rsquo;elle avait besoin pour gagner la mallette MITB et l&rsquo;encaisser le m\u00eame soir pour devenir la nouvelle championne de SmackDown. \u00c7a lui coupe le souffle de le dire.&nbsp;Le titre n&rsquo;est pas seulement pour elle, c&rsquo;est pour nous tous.<\/p>\n\n\n\n<p>&nbsp;La musique de Natalya commence et elle arrive. Natalya dit que Morgan devrait remercier une personne et c&rsquo;est elle ! Natalya dit qu&rsquo;elle est la seule raison de pourquoi Morgan a eu la chance d&rsquo;encaisser sa mallette, car elle a d\u00e9truit le genou de Ronda Rousey avec le Sharpshooter. Comme elle n&rsquo;a pas de merci, elle pr\u00e9f\u00e8re prendre le titre f\u00e9minin. Morgan dit que Natalya a de la difficult\u00e9 \u00e0 accepter la d\u00e9faite contre Rousey. Comme elle est la nouvelle championne, c&rsquo;est normal que Natalya vient pour elle.&nbsp;Comme elles vont partager le vestiaire \u00e0 SmackDown, si Natalya veut une chance elle sait exactement o\u00f9 la trouver.&nbsp;<\/p>\n\n\n\n<p>La musique de Carmella commence et elle arrive. Elle demande de lui expliquer pourquoi les deux sont ici, c&rsquo;est RAW ici. Alors elles peuvent amener leur cul bleu \u00e0 SmackDown. Elle est surprise de voir que les deux peuvent partager un ring ensemble, car si c&rsquo;\u00e9tait son cas elle \u00e9craserait la championne comme Bianca Belair. Donc on peut lui laisser la lumi\u00e8re, la prochaine championne de RAW. Morgan dit que tous les yeux \u00e9taient sur Carmella lorsqu&rsquo;elle a perdu \u00e0 MITB. Si Carmella veut vraiment la voir sortir du ring, elle devrait le faire. Carmella dit qu&rsquo;elle a une id\u00e9e, elle et Natalya vont la faire sortir. Natalya et Carmella attaquent Morgan pour la rouer de coups. Bianca Belair arrive pour les chasser du ring. Adam Pearce arrive et organise un Tag Team Match comme elles veulent tous se battre.<\/p>\n\n\n\n<p><strong>Liv Morgan et Bianca Belair vs Carmella et Natalya<\/strong><\/p>\n\n\n\n<p>En fin de match, Morgan repousse Natalya qui voulait faire sa soumission et lui fait son Oblivion pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnantes : Liv Morgan et Bianca Belair<\/em><\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/07\/04\/deuxieme-heure-de-raw-47\/\">Pour la suite de RAW, cliquez ici!<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce RAW, cliquez ici. WWE RAW San Diego, Californie, 4 juillet 2022 Les commentateurs sont Jimmy Smith, Corey Graves et Byron Saxton. &#8211; Le WWE Monday Night RAW, d\u00e9bute avec une vid\u00e9o pour honorer les c\u00e9l\u00e9brations du 4 juillet qui est le jour de l&rsquo;ind\u00e9pendance sux USA. On a la chance d&rsquo;avoir la&#8230;<\/p>\n","protected":false},"author":4,"featured_media":71611,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,43,21,23],"tags":[],"ppma_author":[292],"class_list":["post-71595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-money-in-the-bank","category-raw-wwe","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=71595"}],"version-history":[{"count":7,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71595\/revisions"}],"predecessor-version":[{"id":71721,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71595\/revisions\/71721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/71611"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=71595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=71595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=71595"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=71595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}