{"id":71480,"date":"2022-07-01T23:10:00","date_gmt":"2022-07-02T03:10:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=71480"},"modified":"2022-07-04T14:00:03","modified_gmt":"2022-07-04T18:00:03","slug":"resultats-et-video-du-aew-rampage-du-1er-juillet-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/07\/01\/resultats-et-video-du-aew-rampage-du-1er-juillet-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du AEW Rampage du 1er Juillet 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/07\/01\/programme-et-liens-pour-voir-le-aew-royal-rampage-en-direct-a-22h-4h-europe\/\" target=\"_blank\">Pour voir ce Rampage, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Rampage D\u00e9troit, Michigan, 1 juillet 2022<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Excalibur, Jim Ross et Tony Schiavone.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Royal Rampage<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Aspirant tire mondial par int\u00e9rim <\/strong><\/p>\n\n\n\n<p><strong>Participants <\/strong>: Frankie Kazarian, John Silver, Orange Cassidy, RUSH, Hangman Page, Konusuke Takeshita, Penta Oscuro, Powerhouse Hobbs, Ricky Starks, Keith Lee, Swerve Strickland, Darby Allin, The Blade, Dustin Rhodes, The Butcher, Max Caster, Tony Nese, Matt Hardy, Dante Martin et Brody King.<\/p>\n\n\n\n<p>\u00c0 la fin du combat, King est le dernier homme sur le ring rouge apr\u00e8s avoir \u00e9limin\u00e9 Ethan Page avec un coup. Sur le ring bleu, Allin arrive \u00e0 sortir Blade et Butcher en \u00e9vitant une attaque. Allin rejoint King sur le ring rouge pour finir le match. Ensuite, King applique un Sleeper sur Allin et le soul\u00e8ve pour l&rsquo;amener sur le tablier et poursuivre le Sleeper. Allin n&rsquo;a plus d&rsquo;air, King le laisser tomber pour remporter le match.<\/p>\n\n\n\n<p><em>Gagnant : Brody King<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, en coulisse, Alex Marvez est avec HOOK pour savoir ce qui l&rsquo;attend apr\u00e8s sa derni\u00e8re victoire. HOOK reste sans mot. Marvez dit que HOOK semble marcher selon l&rsquo;\u00e9nergie. HOOK l&rsquo;attrape par la cravate et lui dit que tout ce qu&rsquo;il dit est invisible pour les yeux.<ins><\/ins><\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Aspirants titres par \u00e9quipe<\/strong><\/p>\n\n\n\n<p><strong>The Young Bucks (Nick et Matt Jackson) vs Hirooki Goto et Yoshi-Hashi<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Nick se lance sur Goto en bas du ring en saut suicide juste apr\u00e8s un Superkick. Les Bucks font ensuite leur Meltzer Driver sur Hashi pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : The Young Bucks<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Jonathan Greshman. Il explique que lui et Lee Moriarty vont affronter les deux clients de Tully Blanchard la semaine prochaine \u00e0 Rampage. Il est le meilleur technicien au monde et il ne peut plus entendre les autres le dire. Il va le prouver aux Claudio Castagnoli et Bryan Danielson.<\/p>\n\n\n\n<p>&#8211; De trouve, on retrouve Mark Henry pour l&rsquo;interview du main event. Nyla Rose dit qu&rsquo;elle est l&rsquo;aspirante et Storm est sur son territoire. Elle sera plus un probl\u00e8me que Shafir. Storm dit que lorsqu&rsquo;elle aura termin\u00e9 avec Rose, elle va retourner pour le titre f\u00e9minin.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Nyla Rose&nbsp;acc de Marina Shafir&nbsp;vs Toni Storm<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du combat, Storm fait une German Suplex \u00e0 Rose et Shafir monte sur le tablier pour la distraire. Storm lui porte un coup de pied. Storm enchaine avec deux Tornado DDT sur Rose pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Toni Storm<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Shafir attaque Storm pendant sa c\u00e9l\u00e9bration. Thunder Rosa arrive sur le ring pour chasser Rose et Shafir du ring. Le show se termine avec Storm et Rosa qui se serrent la main.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/07\/01\/programme-et-liens-pour-voir-le-aew-royal-rampage-en-direct-a-22h-4h-europe\/\" target=\"_blank\">Pour voir ce Rampage, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce Rampage, cliquez ici. AEW Rampage D\u00e9troit, Michigan, 1 juillet 2022 Les commentateurs sont Excalibur, Jim Ross et Tony Schiavone. Royal Rampage Aspirant tire mondial par int\u00e9rim Participants : Frankie Kazarian, John Silver, Orange Cassidy, RUSH, Hangman Page, Konusuke Takeshita, Penta Oscuro, Powerhouse Hobbs, Ricky Starks, Keith Lee, Swerve Strickland, Darby Allin, The&#8230;<\/p>\n","protected":false},"author":4,"featured_media":71482,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,21],"tags":[],"ppma_author":[292],"class_list":["post-71480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=71480"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71480\/revisions"}],"predecessor-version":[{"id":71582,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71480\/revisions\/71582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/71482"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=71480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=71480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=71480"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=71480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}