{"id":71359,"date":"2022-07-03T12:20:00","date_gmt":"2022-07-03T16:20:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=71359"},"modified":"2022-07-04T15:13:55","modified_gmt":"2022-07-04T19:13:55","slug":"la-principale-star-de-mlw-aux-prises-avec-des-problemes-de-commotion-cerebrale-affirme-que-la-sante-a-pris-des-tournures-inattendues","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/07\/03\/la-principale-star-de-mlw-aux-prises-avec-des-problemes-de-commotion-cerebrale-affirme-que-la-sante-a-pris-des-tournures-inattendues\/","title":{"rendered":"La principale star de MLW aux prises avec des probl\u00e8mes de commotion c\u00e9r\u00e9brale affirme que la sant\u00e9 a \u00ab\u00a0pris des tournures inattendues\u00a0\u00bb"},"content":{"rendered":"\n<p>La star de mlw Richard Holliday est actuellement aux prises avec des probl\u00e8mes de commotion c\u00e9r\u00e9brale.<\/p>\n\n\n\n<p>Holliday s\u2019est rendu sur Twitter et a annonc\u00e9 qu\u2019il se retirait des prochaines dates de la Texoma Pro Wrestling et de la Pal\u0113 Pro Wrestling en raison de probl\u00e8mes persistants de commotion c\u00e9r\u00e9brale. Il a not\u00e9 que sa sant\u00e9 avait \u00ab&nbsp;pris des tournures inattendues&nbsp;\u00bb au cours du dernier mois et qu\u2019il avait maintenant besoin de temps pour se r\u00e9tablir.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0En raison de probl\u00e8mes persistants de commotion c\u00e9r\u00e9brale, je ne pourrai malheureusement pas faire @TexomaPro et @PaleProWrestlin ce week-end. Ma sant\u00e9 a pris des tournures inattendues au cours du dernier mois et j\u2019ai besoin de temps libre pour r\u00e9cup\u00e9rer. Ma prochaine apparition sera le 15\/07 pour @AAWPro Rendez-vous l\u00e0-bas. [pouce lev\u00e9 emoji]\u00a0\u00bb, a-t-il \u00e9crit.<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Il a ajout\u00e9 dans un tweet de suivi: \u00ab&nbsp;Cela \u00e9tant dit, les deux promotions \u00e9taient plus que compr\u00e9hensives et je rattraperai ces dates en septembre.&nbsp;\u00bb<\/p>\n\n\n\n<p>Holliday devait d\u00e9fier le champion poids lourd de Red River, Shane Taylor, lors de l\u2019\u00e9v\u00e9nement TPW Independence Day de vendredi \u00e0 Sherman, au Texas, puis d\u00e9fier le champion Pal\u0113 Pro Chandler Hopkins lors de l\u2019\u00e9v\u00e9nement PPW Judges de samedi \u00e0 Arlington, au Texas.<\/p>\n\n\n\n<p>Holliday doit actuellement revenir sur le ring le vendredi 15 juillet lors de l\u2019\u00e9v\u00e9nement The Independents Day de l\u2019AAW Wrestling \u00e0 Merrionette Park, IL.<\/p>\n\n\n\n<p>Holliday a lutt\u00e9 pour la derni\u00e8re fois lors des enregistrements mlw Battle Riot IV le 23 juin. Il a travaill\u00e9 un Falls Count Anywhere match ce soir-l\u00e0 contre le champion MLW World Heavyweight Alexander Hammerstone.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La star de mlw Richard Holliday est actuellement aux prises avec des probl\u00e8mes de commotion c\u00e9r\u00e9brale. Holliday s\u2019est rendu sur Twitter et a annonc\u00e9 qu\u2019il se retirait des prochaines dates de la Texoma Pro Wrestling et de la Pal\u0113 Pro Wrestling en raison de probl\u00e8mes persistants de commotion c\u00e9r\u00e9brale. Il a not\u00e9 que sa sant\u00e9&#8230;<\/p>\n","protected":false},"author":665,"featured_media":71593,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,22,4],"tags":[],"ppma_author":[289],"class_list":["post-71359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-indy","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=71359"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71359\/revisions"}],"predecessor-version":[{"id":71594,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71359\/revisions\/71594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/71593"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=71359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=71359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=71359"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=71359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}