{"id":71308,"date":"2022-06-29T12:14:00","date_gmt":"2022-06-29T16:14:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=71308"},"modified":"2022-06-29T14:21:08","modified_gmt":"2022-06-29T18:21:08","slug":"accident-de-voiture-pour-une-superstar-de-la-wwe-raison-de-labsence-de-kevin-owens-a-raw-pour-affronter-ezekiel","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/06\/29\/accident-de-voiture-pour-une-superstar-de-la-wwe-raison-de-labsence-de-kevin-owens-a-raw-pour-affronter-ezekiel\/","title":{"rendered":"Accident de voiture pour une Superstar de la WWE! \/ Raison de l&rsquo;absence de Kevin Owens \u00e0 RAW, pour affronter Ezekiel!"},"content":{"rendered":"\n<p>L&rsquo;actuelle championne 24\/7 n&rsquo;a pas \u00e9t\u00e9 vue lors de\u00a0RAW\u00a0cette semaine. Dana Brooke \u00e9tait absente du show et elle a d\u00e9voil\u00e9 la raison par le biais d&rsquo;un Tweet.<\/p>\n\n\n\n<p>Dana Brooke r\u00e9v\u00e8le ainsi avoir fait un accident de voiture la semaine derni\u00e8re\u00a0et c&rsquo;est pour cette raison qu&rsquo;elle ne pouvait \u00eatre pr\u00e9sente pour le show rouge cette semaine.<\/p>\n\n\n\n<p>Heureusement, la catcheuse nous rassure en nous disant qu&rsquo;elle va bien qu&rsquo;elle sera de retour tr\u00e8s bient\u00f4t.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&lt;&lt; [&#8230;] La raison pour laquelle je n&rsquo;\u00e9tait pas \u00e0 RAW lundi soir, c&rsquo;est parce que j&rsquo;ai eu un terrible accident de voiture la semaine derni\u00e8re. Je vais bien et je serai de retour tr\u00e8s vite ! J&rsquo;appr\u00e9cie vraiment votre amour et je ne pourrais pas demander un meilleur soutien des fans. >><\/p><\/blockquote>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/06\/27\/resultats-du-wwe-monday-night-raw-du-27-juin-2022\/\" target=\"_blank\">R\u00e9sultats du WWE Monday Night RAW du 27 Juin 2022!<\/a><\/strong><\/li><\/ul>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Much &#x2764;&#xfe0f; to the <a href=\"https:\/\/twitter.com\/hashtag\/wweuniverse?src=hash&amp;ref_src=twsrc%5Etfw\">#wweuniverse<\/a> for the support &amp; love, standing up for me! The reason why I was not on RAW last night was bc I got into a bad car accident the past week, I am doing good &amp; will be back in no time! I really appreciate the love &amp; couldn\u2019t ask for better Fan support &#x2764;&#xfe0f;<\/p>&mdash; Dana Brooke WWE (@DanaBrookeWWE) <a href=\"https:\/\/twitter.com\/DanaBrookeWWE\/status\/1541807437249904647?ref_src=twsrc%5Etfw\">June 28, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Jusqu&rsquo;au tout d\u00e9but de RAW du 27 juin, la WWE annon\u00e7ait que Kevin Owens devait affronter Elias, Ezekiel ou un autre fr\u00e8re du nom d&rsquo;Elrod pendant le show, un challenge lanc\u00e9 par Owens la semaine pr\u00e9c\u00e9dente.<\/p>\n\n\n\n<p>Finalement, le match n&rsquo;a jamais eu lieu sur nos \u00e9crans et vous aurez remarqu\u00e9 que Kevin Owens \u00e9tait absent pour souligner les 20 ans de carri\u00e8re de John Cena. <\/p>\n\n\n\n<p> On apprend aujourd&rsquo;hui que Kevin Owens souffrirait d&rsquo;une blessure l\u00e9g\u00e8re et c&rsquo;est pour cette raison que les officiels ont pris la d\u00e9cision de le retirer du programme.<\/p>\n\n\n\n<p>Une d\u00e9cision qui semblerait avoir \u00e9t\u00e9 prise \u00e0 la derni\u00e8re minute puisque son match \u00e9tait toujours sur la carte m\u00eame pendant le show<\/p>\n\n\n\n<p>. Pour l&rsquo;instant, personne n&rsquo;a plus de d\u00e9tails sur le sujet, il faudra surveiller les prochaines informations. Le match entre Owens et un membre de la famille d&rsquo;Elias n&rsquo;est toujours pas de retour sur la programmation.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/06\/27\/resultats-du-wwe-monday-night-raw-du-27-juin-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00e9sultats du WWE Monday Night RAW du 27 Juin 2022!<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;actuelle championne 24\/7 n&rsquo;a pas \u00e9t\u00e9 vue lors de\u00a0RAW\u00a0cette semaine. Dana Brooke \u00e9tait absente du show et elle a d\u00e9voil\u00e9 la raison par le biais d&rsquo;un Tweet. Dana Brooke r\u00e9v\u00e8le ainsi avoir fait un accident de voiture la semaine derni\u00e8re\u00a0et c&rsquo;est pour cette raison qu&rsquo;elle ne pouvait \u00eatre pr\u00e9sente pour le show rouge cette semaine&#8230;.<\/p>\n","protected":false},"author":609,"featured_media":71310,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[295],"class_list":["post-71308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=71308"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71308\/revisions"}],"predecessor-version":[{"id":71311,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/71308\/revisions\/71311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/71310"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=71308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=71308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=71308"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=71308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}