{"id":70809,"date":"2022-06-20T02:15:00","date_gmt":"2022-06-20T06:15:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=70809"},"modified":"2022-06-20T14:27:40","modified_gmt":"2022-06-20T18:27:40","slug":"maryse-ne-dit-pas-non-a-un-petit-retour-les-superstars-se-plaignent-dattendre-avant-leur-match","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/06\/20\/maryse-ne-dit-pas-non-a-un-petit-retour-les-superstars-se-plaignent-dattendre-avant-leur-match\/","title":{"rendered":"Maryse ne dit pas non \u00e0 un petit retour! \/ Les Superstars se plaignent d&rsquo;attendre avant leur match!"},"content":{"rendered":"\n<p>C&rsquo;est devenu une habitude depuis quelques mois du c\u00f4t\u00e9 de RAW et de SmackDown. Les Superstars qui participent au Main Event de la soir\u00e9e ont tendance \u00e0 attendre plusieurs minutes, g\u00e9n\u00e9ralement aux alentours des 15 minutes, entre leur entr\u00e9e et le d\u00e9but du match pour la version en direct. <\/p>\n\n\n\n<p>Donc, 20 minutes d&rsquo;attente ont pu \u00eatre constat\u00e9es pour un r\u00e9cent match entre Rhea Ripley et Liv Morgan \u00e0 RAW. Pendant ce temps, nous pouvons voir des vid\u00e9os promotionnelles, des replays ou encore des pauses publicitaires entre 3 et 4 minute plus celles de la compagnie  qui annonce ses autres galas localement.<\/p>\n\n\n\n<p>Une source a pu contacter certaines Superstars qui ont d\u00fb attendre une dizaine de minutes sur le ring avant le Main Event.\u00a0Ces Superstars ont fait part de leur agacement et ont d\u00e9voil\u00e9 qu&rsquo;ils en ont parl\u00e9 \u00e0 leurs sup\u00e9rieurs. En revanche, on leur a r\u00e9pondu que c&rsquo;\u00e9tait le format actuel et que \u00e7a am\u00e9liorait le d\u00e9roulement du show.<\/p>\n\n\n\n<p>Mais que font les Superstars sur le ring pendant qu&rsquo;elles attendent ? L&rsquo;une d&rsquo;entre elles affirme qu&rsquo;elle \u00ab\u00a0parle \u00e0 la foule, dance ou s\u2019agace d&rsquo;attendre autant de temps.\u00a0\u00bb<\/p>\n\n\n\n<p>Note perso sur le sujet: <em>Dans les ann\u00e9e 90 \u00e0 2005, c&rsquo;\u00e9tait le blackout total dans les ar\u00e9na quand les shows t\u00e9l\u00e9s passait \u00e0 la pause. Les Superstars ne terminaient m\u00eame pas leur entr\u00e9e sur une musique et marchaient au ring sans projecteurs. Au moins maintenant m\u00eame si c&rsquo;est hors des ondes, la compagnie leur fait terminer leur entr\u00e9e et ainsi avoir quand m\u00eame leur pop. <\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Comme vous le savez, Maryse a mis fin \u00e0 sa carri\u00e8re de catcheuse \u00e0 plein temps en 2011. Depuis lors, la femme du Miz est revenue sur le ring \u00e0 seulement quatre occasions, \u00e0 commencer par WrestleMania 33 o\u00f9 le couple a perdu face \u00e0 John Cena et Nikki Bella. Son dernier match en date a eu lieu au Royal Rumble 2022, cette fois-ci contre Edge et Beth Phoenix.<\/p>\n\n\n\n<p>L&rsquo;ancienne championne des Divas \u00e9tait r\u00e9cemment en interview pour KOIN 6 et elle s&rsquo;est exprim\u00e9e concernant un \u00e9ventuel retour en tant que catcheuse. Elle d\u00e9voile avoir tendance \u00e0 vouloir ne pas remonter sur le ring \u00e0 cause des risques du m\u00e9tier et du fait qu&rsquo;elle ait des enfants, mais elle finit toujours par revenir pour un match de temps en temps.<\/p>\n\n\n\n<p>Elle nous dit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&lt;&lt; Je dis toujours \u00ab\u00a0jamais\u00a0\u00bb, \u00ab\u00a0Je ne reviendrai plus jamais sur le ring.\u00a0\u00bb C&rsquo;est ce que j&rsquo;avais dit apr\u00e8s WrestleMania avec le Miz en 2016 (c&rsquo;\u00e9tait en 2017, ndlr). Puis j&rsquo;ai eu un b\u00e9b\u00e9 et je me disais : \u00ab\u00a0Plus jamais, je pense en avoir fini.\u00a0\u00bb Quatre mois plus tard, j&rsquo;\u00e9tais de retour sur le ring puis j&rsquo;ai eu un nouveau b\u00e9b\u00e9. Je me disais : \u00ab\u00a0J&rsquo;en ai fini pour de bon.\u00a0\u00bb Non, je suis revenue sur le ring. Je pense que je reviendrai une nouvelle fois.<\/p><p>Je dis toujours que je ne reviendrai pas car je ne veux pas me blesser, j&rsquo;ai des enfants et c&rsquo;est difficile de s&rsquo;investir dans \u00e7a. C&rsquo;est un sport extr\u00eame. >><\/p><\/blockquote>\n\n\n\n<p>En conclusion, Maryse ne reviendra pas \u00e0 temps plein mais pourrait faire quelques matchs comme elle le fait depuis 2017.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est devenu une habitude depuis quelques mois du c\u00f4t\u00e9 de RAW et de SmackDown. Les Superstars qui participent au Main Event de la soir\u00e9e ont tendance \u00e0 attendre plusieurs minutes, g\u00e9n\u00e9ralement aux alentours des 15 minutes, entre leur entr\u00e9e et le d\u00e9but du match pour la version en direct. Donc, 20 minutes d&rsquo;attente ont pu&#8230;<\/p>\n","protected":false},"author":609,"featured_media":70815,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[295],"class_list":["post-70809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=70809"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70809\/revisions"}],"predecessor-version":[{"id":70816,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70809\/revisions\/70816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/70815"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=70809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=70809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=70809"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=70809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}