{"id":70744,"date":"2022-06-18T13:45:54","date_gmt":"2022-06-18T17:45:54","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=70744"},"modified":"2022-06-18T13:45:59","modified_gmt":"2022-06-18T17:45:59","slug":"les-details-sur-le-retour-surprise-de-brock-lesnar","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/06\/18\/les-details-sur-le-retour-surprise-de-brock-lesnar\/","title":{"rendered":"Les d\u00e9tails sur le retour surprise de Brock Lesnar!"},"content":{"rendered":"\n<p>Le Smackdown de vendredi soir (en vf aujourd&rsquo;hui samedi) \u00e9tait fortement attendu afin de connaitre ce que\u00a0Vince McMahon dirait publiquement\u00a0suite au scandale qu\u2019il a d\u00e9clench\u00e9, la WWE a tout de m\u00eame fait en sorte qu\u2019un \u00e9v\u00e9nement marquant ait lieu lors de ce show. <\/p>\n\n\n\n<p>Apr\u00e8s le main event qui a vu Roman Reigns faire sa premi\u00e8re d\u00e9fense de titre depuis qu&rsquo;il les a unifi\u00e9s \u00e0 WrestleMania, match qui \u00e9tait hier soir contre Riddle; Brock Lesnar a alors fait son retour \u00e0 la WWE, et s\u2019en est pris au champion. Dans la foul\u00e9e, il a \u00e9t\u00e9 annonc\u00e9 un rematch entre les deux pour Summerslam le 39 juillet prochain dans un Last Man Standing Match. <\/p>\n\n\n\n<p>Cela sera le 6\u00e8me match entre les deux lutteurs. Leur dernier remontait \u00e0 Wrestlemania 38 et avait tourn\u00e9 \u00e0 l\u2019avantage de Reigns. Le Tribal Chief m\u00e8ne d\u2019ailleurs 3 victoires \u00e0 2 sur son rival et est sur une streak de trois victoires de suite. <\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p> Un retour du Beast qui est rest\u00e9 un secret jusqu&rsquo;\u00e0 la derni\u00e8re minute.<\/p>\n\n\n\n<p>Notre source nous apprend ce matin que les personnes dans les coulisses ont commenc\u00e9 \u00e0 \u00eatre inform\u00e9es de la pr\u00e9sence de Brock Lesnar environ trois heures avant le show et que son nom est rest\u00e9 absent de la liste des Superstars pr\u00e9sente surle show afin de garder la surprise au maximum. Le plan initial pour SummerSlam \u00e9tait de faire un Roman Reigns contre Randy Orton, mais la r\u00e9elle blessure au dos d&rsquo;Orton et le fait qu&rsquo;il aura probablement besoin d&rsquo;une op\u00e9ration ont chang\u00e9 le plan.<\/p>\n\n\n\n<p>La WWE a pris contact avec Brock Lesnar il y a trois semaines afin de discuter avec lui et voir si le retour \u00e9tait possible pour SummerSlam. Ce qui indique que ce n&rsquo;est pas un retour de derni\u00e8re minute afin de cacher l&rsquo;affaire Vince McMahon et que Lesnar est toujours le plan de secours de Vince. \u00c0 l&rsquo;heure actuelle, on ne sait toujours pas pour combien de temps ce nouveau retour de Brock Lesnar est pr\u00e9vu.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/06\/17\/resultats-du-wwe-friday-night-smackdown-du-17-juin-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00e9sultats du WWE Friday Night Smackdown du 17 Juin 2022!<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Le Smackdown de vendredi soir (en vf aujourd&rsquo;hui samedi) \u00e9tait fortement attendu afin de connaitre ce que\u00a0Vince McMahon dirait publiquement\u00a0suite au scandale qu\u2019il a d\u00e9clench\u00e9, la WWE a tout de m\u00eame fait en sorte qu\u2019un \u00e9v\u00e9nement marquant ait lieu lors de ce show. Apr\u00e8s le main event qui a vu Roman Reigns faire sa premi\u00e8re&#8230;<\/p>\n","protected":false},"author":4,"featured_media":70746,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,36,23],"tags":[],"ppma_author":[292],"class_list":["post-70744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=70744"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70744\/revisions"}],"predecessor-version":[{"id":70747,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70744\/revisions\/70747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/70746"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=70744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=70744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=70744"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=70744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}