{"id":70687,"date":"2022-06-17T20:12:40","date_gmt":"2022-06-18T00:12:40","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=70687"},"modified":"2022-06-19T13:59:44","modified_gmt":"2022-06-19T17:59:44","slug":"programme-et-liens-du-aew-ramapage-du-17-juin-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/06\/17\/programme-et-liens-du-aew-ramapage-du-17-juin-2022\/","title":{"rendered":"Programme et Liens du AEW Ramapage du 17 Juin 2022!"},"content":{"rendered":"\n<p><strong>Avant Gout du AEW RAMPAGE du 10 juin 2022<\/strong><\/p>\n\n\n\n<p>La AEW pr\u00e9sente Rampage ce soir \u00e0 22h, de suite apr\u00e8s Smackdown et donc \u00e0 4h du matin pour l\u2019Europe; et ce en direct de la ville de St-Louis dans l&rsquo;\u00c9tat du Missouri.<\/p>\n\n\n\n<p>Le tout sur TNT aux USA en direct \u00e0 l\u2019heure pile. Nous vous passerons bien s\u00fbre des liens ici m\u00eame juste avant le d\u00e9but du show qui durera une heure seulement chaque vendredi soir. La reprise sera en ligne \u00e9galement ici m\u00eame tout de suite apr\u00e8s la diffusion du direct.<\/p>\n\n\n\n<p><em>Les liens pour le direct seront affich\u00e9s ici sur cette m\u00eame page juste avant l\u2019heure de la diffusion \/ et ou apr\u00e8s pour la reprise.<\/em><\/p>\n\n\n\n<p>Au Canada vous pouvez suivre en direct sur l\u2019application de TSN et non \u00e0 la t\u00e9l\u00e9 ou sur Fite t\u00e9l\u00e9 partout dans le monde. TSN 2 ne semble pas passer la reprise cette semaine mais le tout sera sur leur application sauf changement du diffuseur.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p class=\"has-large-font-size\"><strong>Au Programme ce Soir:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Championnat TBS <\/strong> Jade Cargill a lanc\u00e9 un Open Challenge pour son titre TBS et Willow Nightingale l&rsquo;a accept\u00e9 pendant Dynamite, leur affrontement aura lieu ce vendredi \u00e0 Rampage pour ce sp\u00e9cial \u00a0\u00bbRoad Rager\u00a0\u00bb.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Match Solo: <\/strong>Nous aurons un rematch entre Dante Martin et Jon Moxley. Martin veut prouver qu&rsquo;il peut devenir la prochaine star de la compagnie.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>D\u00e9fi Sp\u00e9cial:<\/strong> Darby Allin veut venger Sting pour la derni\u00e8re attaque, il fera face \u00e0 Bobby Fish.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Trios Match<\/strong>: Max Caster et le Gunn Club (Austin et Colten Gunn) vont affronter Bear Country (Bear Boulder et Bear Bronson) et Leon Ruff.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Grosse Tentions: <\/strong> Keith Lee et Swerve Strickland vont s&rsquo;exprimer au sujet de leur possible tension suite \u00e0 l&rsquo;\u00e9limination de Strickland dans le Battle Royal.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Alors soyez des notre en direct ou pour la reprise.<\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/06\/10\/resultats-et-video-du-aew-rampage-du-10-juin-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour les r\u00e9sultats et vid\u00e9o de la semaine pass\u00e9, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Avant Gout du AEW RAMPAGE du 10 juin 2022 La AEW pr\u00e9sente Rampage ce soir \u00e0 22h, de suite apr\u00e8s Smackdown et donc \u00e0 4h du matin pour l\u2019Europe; et ce en direct de la ville de St-Louis dans l&rsquo;\u00c9tat du Missouri. Le tout sur TNT aux USA en direct \u00e0 l\u2019heure pile. Nous vous&#8230;<\/p>\n","protected":false},"author":4,"featured_media":70698,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,68,30,29,20],"tags":[],"ppma_author":[292],"class_list":["post-70687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-carte","category-ex-wwe","category-streaming","category-videos"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=70687"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70687\/revisions"}],"predecessor-version":[{"id":70700,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70687\/revisions\/70700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/70698"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=70687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=70687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=70687"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=70687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}