{"id":70434,"date":"2022-06-11T02:16:00","date_gmt":"2022-06-11T06:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=70434"},"modified":"2022-06-11T14:22:09","modified_gmt":"2022-06-11T18:22:09","slug":"un-match-pour-john-cena-seconde-clinique-mobile-pour-sami-zayn","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/06\/11\/un-match-pour-john-cena-seconde-clinique-mobile-pour-sami-zayn\/","title":{"rendered":"Un match pour John Cena? \/ Seconde clinique mobile pour Sami Zayn!"},"content":{"rendered":"\n<p>En fin 2021, on apprenait que la clinique mobile\u00a0\u00a0\u00bbSamiForSyria\u00a0\u00bb avait offert 7 143 services m\u00e9dicaux\u00a0pendant l&rsquo;ann\u00e9e 2021 aux gens dans le besoin en Syrie. Pour ceux et celles qui ne savent pas, Sami Zayn a lanc\u00e9 le projet d&rsquo;une clinique m\u00e9dicale mobile dans son pays d&rsquo;origine qu&rsquo;est Syrie il y a cinq ans. Une clinique financ\u00e9e par les dons et ses investissements.<\/p>\n\n\n\n<p>Ce weekend, il a annonc\u00e9 sur Twitter que sa fondation lan\u00e7ait une seconde clinique mobile en Syrie pour s&rsquo;occuper des citoyens qui sont souvent d\u00e9plac\u00e9s par la guerre :<\/p>\n\n\n\n<p><\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">5 years ago I started <a href=\"https:\/\/twitter.com\/hashtag\/SamiForSyria?src=hash&amp;ref_src=twsrc%5Etfw\">#SamiForSyria<\/a> &#8211; a mobile clinic in Syria delivering medical care to civilians displaced by war.<br><br>I am proud to tell you: thanks to your support, we now have TWO clinics currently operating!<br><br>Please donate at <a href=\"https:\/\/t.co\/t4RdChDwIW\">https:\/\/t.co\/t4RdChDwIW<\/a> to keep this going strong! <a href=\"https:\/\/t.co\/ZVvckt0Ogf\">pic.twitter.com\/ZVvckt0Ogf<\/a><\/p>&mdash; Sami Zayn (@SamiZayn) <a href=\"https:\/\/twitter.com\/SamiZayn\/status\/1535054396010143767?ref_src=twsrc%5Etfw\">June 10, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>C&rsquo;est pour le moment au stade de rumeur, mais selon la bande de Dave Meltzer, le retour de John Cena le 27 juin prochain \u00e0 RAW pour ses 20 ans, devrait mener \u00e0 un combat face \u00e0 Theory lors de SummerSlam.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cCena revient lors du show Raw du 27 juin \u00e0 Laredo, TX. Bien que cela ne nous ait pas \u00e9t\u00e9 confirm\u00e9 par la compagnie, la rumeur dans le monde du catch est que ce sera Cena contre Theory \u00e0 SummerSlam avec l&rsquo;id\u00e9e que travailler avec Cena am\u00e8nera Theory \u00e0 un niveau sup\u00e9rieur.\u201d<\/p><\/blockquote>\n\n\n\n<p>Le retour de John Cena s\u2019annonce d\u00e9j\u00e0 l\u00e9gendaire pour f\u00eater les 20 ans de ses d\u00e9buts \u00e0 la WWE. Depuis plusieurs semaines, Theory et John Cena \u00e9changent sur Twitter quelques messages hostiles, ce qui peut laisser penser \u00e0 une future rivalit\u00e9 dans le plus grand show de l&rsquo;\u00e9t\u00e9. <\/p>\n\n\n\n<p>Le Monday Night RAW du 27 juin semble \u00eatre le moment propice pour lancer cette rivalit\u00e9 qui pourrait faire exploser Theory pour qu\u2019il devienne le futur de la WWE.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>En fin 2021, on apprenait que la clinique mobile\u00a0\u00a0\u00bbSamiForSyria\u00a0\u00bb avait offert 7 143 services m\u00e9dicaux\u00a0pendant l&rsquo;ann\u00e9e 2021 aux gens dans le besoin en Syrie. Pour ceux et celles qui ne savent pas, Sami Zayn a lanc\u00e9 le projet d&rsquo;une clinique m\u00e9dicale mobile dans son pays d&rsquo;origine qu&rsquo;est Syrie il y a cinq ans. Une clinique&#8230;<\/p>\n","protected":false},"author":609,"featured_media":70435,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[295],"class_list":["post-70434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=70434"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70434\/revisions"}],"predecessor-version":[{"id":70436,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70434\/revisions\/70436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/70435"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=70434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=70434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=70434"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=70434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}