{"id":70417,"date":"2022-06-10T23:29:00","date_gmt":"2022-06-11T03:29:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=70417"},"modified":"2022-06-13T13:41:46","modified_gmt":"2022-06-13T17:41:46","slug":"resultats-et-video-du-aew-rampage-du-10-juin-2022","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/06\/10\/resultats-et-video-du-aew-rampage-du-10-juin-2022\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du AEW Rampage du 10 Juin 2022!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/06\/10\/programme-et-liens-pour-le-aew-rampage-du-10-juin-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir le show, cliquez <\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AEW Rampage Independence, Missouri. 10 juin 2022<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Eddie Kingston vs Jake Hager<\/strong><\/p>\n\n\n\n<p>en fin de match, Hager repousse Kingston contre le coin et le frappe de la deuxi\u00e8me corde, mais Kingston le bloque et lui fait une Powerbomb. Kingston enchaine avec son Spinning Back Fist pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Eddie Kingston<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Tony Schiavone est avec Britt Baker, Jamie Hayter et Rebel. Baker dit qu&rsquo;elle a toujours le titre Owen Hart, c&rsquo;\u00e9tait un manque de respect de Toni Storm de mettre les mains sur le titre f\u00e9minin de l&rsquo;AEW. Baker dit que Storm veut essayer de couper la ligne. L&rsquo;\u00e9quipe DMD va remporter le titre avec Storm.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, on pr\u00e9sente une vid\u00e9o promo sur le Hair vs Hair Match de mercredi prochain.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Satnam Singh et Jay Lethal vs Matt Fichettt et Davey Vega<\/strong><\/p>\n\n\n\n<p>Singh et Lethal attaquent directement les deux catcheurs. Lethal termine avec son Lethal Injection sur les deux adversaires pour le compte de trois en deux minutes.<\/p>\n\n\n\n<p><em>Gagnants : Satnam Singh et Jay Lethal<\/em><\/p>\n\n\n\n<p>&#8211; Dans une vid\u00e9o plus t\u00f4t, Lexy voulait faire une interview avec Danhausen et Hook. Danhausen d\u00e9barque finalement en kart de golf et passe devant. Hook suite derri\u00e8re dans un kart plus cool et laisse ses lunettes soleil sur Lexy pour ensuite partir.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Kris Statlander vs Red Velvet accompagn\u00e9e des Baddies<\/strong><\/p>\n\n\n\n<p>\u00c0 la fin du match, Velvet porte son coup de pied sur Statlander et la couvre, mais elle r\u00e9siste \u00e0 deux. Statlander bloque un autre coup de pied et lui fait son Friday Night Fever pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Kris Statlander<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Statlander se fait directement attaquer par les Baddies. Anna Jay arrive sur le ring, mais Hogan et Velvet la repousse rapidement. Athena arrive ensuite, mais les officiels arrivent pour s\u00e9parer tout le monde.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Miro qui va participer au tournoi All-Atlantic mercredi.<\/p>\n\n\n\n<p>&#8211; En coulisse, Lexy est avec American Top Team. Ethan Page dit qu&rsquo;il croit en lui pour son match contre Miro. Le drapeau canadien sera lev\u00e9 heut et fort.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, Mark Henry est en interview pour le main event. Will Ospreay dit qu&rsquo;il est venu \u00e0 l&rsquo;AEW pour s\u00e9parer les lions des moutons. Dax Harwood dit qu&rsquo;ils ont choisi les mauvais gars.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Trios Match<\/strong><\/p>\n\n\n\n<p><strong>FTR<em>&nbsp;(Dax Harwood et Cash Wheeler)<\/em>&nbsp;et Trent Beretta vs Will Ospreay et Aussie Open&nbsp;<em>(Kyle Fletcher et Mark Davis)<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Ospreay repousse FTR en bas du ring avec un Cross Body. Fletcher fait un Roll Up \u00e0 Beretta, mais il r\u00e9siste et le renverse en Roll Up, mais Fletcher r\u00e9siste aussi. Beretta enchaine avec son Stong Zero pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : FTR et Trent Beretta<\/em><\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration des gagnants.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2022\/06\/10\/programme-et-liens-pour-le-aew-rampage-du-10-juin-2022\/\" target=\"_blank\">Pour voir le show, cliquez <\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir le show, cliquez AEW Rampage Independence, Missouri. 10 juin 2022 Eddie Kingston vs Jake Hager en fin de match, Hager repousse Kingston contre le coin et le frappe de la deuxi\u00e8me corde, mais Kingston le bloque et lui fait une Powerbomb. Kingston enchaine avec son Spinning Back Fist pour le compte de trois&#8230;.<\/p>\n","protected":false},"author":4,"featured_media":70418,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,21],"tags":[],"ppma_author":[292],"class_list":["post-70417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=70417"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70417\/revisions"}],"predecessor-version":[{"id":70420,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70417\/revisions\/70420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/70418"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=70417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=70417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=70417"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=70417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}