{"id":70278,"date":"2022-06-08T12:27:00","date_gmt":"2022-06-08T16:27:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=70278"},"modified":"2022-06-08T13:38:37","modified_gmt":"2022-06-08T17:38:37","slug":"edge-cest-oppose-a-une-idee-pour-judgment-day-matt-hardy-souligne-que-lexpulsion-dedge-ressemble-a-une-storyline-de-la-all-elite-wrestling","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/06\/08\/edge-cest-oppose-a-une-idee-pour-judgment-day-matt-hardy-souligne-que-lexpulsion-dedge-ressemble-a-une-storyline-de-la-all-elite-wrestling\/","title":{"rendered":"Edge c&rsquo;est oppos\u00e9 \u00e0 une id\u00e9e pour Judgment Day! \/ Matt Hardy souligne que l&rsquo;expulsion d&rsquo;Edge ressemble \u00e0 une storyline de la All Elite Wrestling!"},"content":{"rendered":"\n<p>Les fans de la WWE et de la AEW \u2013 et m\u00eame certains lutteurs aiment bien rappeler que certaines histoires sont parfois reprises, du moins en partie d\u2019une compagnie \u00e0 l\u2019autre.<\/p>\n\n\n\n<p>C\u2019est au tour de Matt Hardy d\u2019aller dans cette direction, en comparant la r\u00e9cente expulsion de Edge du clan Judgement Day avec une histoire survenue en mars \u00e0 la AEW.<\/p>\n\n\n\n<p>Sur son compte Twitter, Hardy a fait le parall\u00e8le avec lui-m\u00eame (du moins son personnage \u00e0 la AEW), qui avait \u00e9t\u00e9 expuls\u00e9 du clan Andrade-Hardy Family Office par, entre autres, Andrade El Idolo, Private Party et The Butcher.<\/p>\n\n\n\n<p>Il faudrait tout de m\u00eame leur rappeler qu&rsquo;un push-out reste un push. <\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Young kids don\u2019t have any respect for their mentors nowadays..&#x1f937;&#x1f3fb;&#x200d;&#x2642;&#xfe0f; <a href=\"https:\/\/t.co\/KOaTPkUyT0\">pic.twitter.com\/KOaTPkUyT0<\/a><\/p>\u2014 MATT HARDY (@MATTHARDYBRAND) <a href=\"https:\/\/twitter.com\/MATTHARDYBRAND\/status\/1534270216884060161?ref_src=twsrc%5Etfw\">June 7, 2022<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><\/p>\n\n\n\n<p>Comme il avait d\u00e9j\u00e0 effectu\u00e9 son heel turn lors du Wrestlemania Weekend, Edge \u00e9tait pass\u00e9 \u00e0 la vitesse sup\u00e9rieur en fondant son propre clan Judgement Day avec Damian Priest puis Rhea Ripley. Comme vous l&rsquo;avez vu lors du dernier RAW, Finn Balor a lui aussi rejoint la faction et fait son heel turn en joignant le clan, avant que le groupe ne se retourne contre Edge et ne l\u2019exclut. <\/p>\n\n\n\n<p>M\u00eame si cela n\u2019a dur\u00e9 que deux mois, le v\u00e9t\u00e9ran canadien tenait le Judgement Day \u00e0 coeur et essayait d\u2019imposer son avis sur le booking du groupe. Notre source rapporte que la WWE voulait que le clan aille du c\u00f4t\u00e9 du surnaturel avec on imagine l\u2019\u00e9quivalent de pouvoirs, un peu comme l&rsquo;Undertaker et du Fiend et autre gimmick du genre. Edge aurait cependant exprim\u00e9 un non cat\u00e9gorique \u00e0 cette id\u00e9e.<\/p>\n\n\n\n<p>Est-ce que le tout changera avec l&rsquo;arriv\u00e9 du Demon King? Nous le saurons dans les prochaines semaines. <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/06\/06\/resultats-et-video-du-wwe-monday-night-raw-du-6-juin-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00e9sultats et Vid\u00e9o du WWE Monday Night RAW du 6 Juin 2022!<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Les fans de la WWE et de la AEW \u2013 et m\u00eame certains lutteurs aiment bien rappeler que certaines histoires sont parfois reprises, du moins en partie d\u2019une compagnie \u00e0 l\u2019autre. C\u2019est au tour de Matt Hardy d\u2019aller dans cette direction, en comparant la r\u00e9cente expulsion de Edge du clan Judgement Day avec une histoire&#8230;<\/p>\n","protected":false},"author":609,"featured_media":70279,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,30,4,43,23],"tags":[],"ppma_author":[295],"class_list":["post-70278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-ex-wwe","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=70278"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70278\/revisions"}],"predecessor-version":[{"id":70281,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70278\/revisions\/70281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/70279"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=70278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=70278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=70278"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=70278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}