{"id":70116,"date":"2022-06-05T23:25:07","date_gmt":"2022-06-06T03:25:07","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=70116"},"modified":"2022-06-05T23:27:16","modified_gmt":"2022-06-06T03:27:16","slug":"deuxieme-partie-du-hell-in-a-cell","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/06\/05\/deuxieme-partie-du-hell-in-a-cell\/","title":{"rendered":"Deuxi\u00e8me Partie du Hell in a Cell!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/06\/05\/resultats-et-video-du-wwe-hell-in-a-cell-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour revenir \u00e0 la premi\u00e8re partie, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 avec le Judgment Day.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Six-Person Mixed Tag Team Match<\/strong><\/p>\n\n\n\n<p><strong>Judgment Day&nbsp;<em>(Edge, Damian Priest et Rhea Ripley)<\/em>&nbsp;vs AJ Styles, Finn Balor et Liv Morgan<\/strong><\/p>\n\n\n\n<p>En fin de match, Priest fait une Slam \u00e0 Balor, mais AJ lui fait un Phenomenal Forearm. Edge repousse AJ en bas du ring. Edge se lance en Spear, mais Balor le renverse en Roll Up et il r\u00e9siste. Balor enchaine avec une Slingblade et un Drop Kick. Balor monte sur le coin, mais Ripley lui bloque la route. Morgan saute sur Ripley pour la sortir. Edge \u00e9vite le saut de Balor et lui fait un Spear pour le compte de trois.<\/p>\n\n\n\n<p><strong>Gagnant : Judgment Day<\/strong><\/p>\n\n\n\n<p>&#8211; En coulisse,&nbsp; Bobby Lashley arr\u00eate Cedric Alexander et lui demande c&rsquo;\u00e9tait quoi sur le ring. Alexander dit que c&rsquo;\u00e9tait pour eux deux. MVP et Omos ont eu ce qu&rsquo;ils m\u00e9ritaient. Lashley dit qu&rsquo;il est fier d&rsquo;Alexander qui prend sa place.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Moss et Corbin.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p class=\"has-large-font-size\"><strong>No Holds Barred Match<\/strong><\/p>\n\n\n\n<p><strong>Madcap Moss vs Happy Corbin<\/strong><\/p>\n\n\n\n<p>En fin de match, Moss fait un Slam \u00e0 Corbin sur la marche d&rsquo;acier. Moss bloque la t\u00eate de Corbin dans une chaise. Moss va chercher la marche d&rsquo;acier et frappe sur la chaise pour l&rsquo;\u00e9trangler ! Moss le couvre pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Madcap Moss<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, les m\u00e9decins arrivent pour embarquer Corbin sur la civi\u00e8re.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Championnat des USA<\/strong><\/p>\n\n\n\n<p><strong>Theory \u00a9 vs Mustafa Ali<\/strong><\/p>\n\n\n\n<p>En fin de match, Ali monte sur le coin, mais Theory le fait tr\u00e9bucher. Theory le prend pour son ATL, mais Ali le bloque et le pousse au sol pour lui appliquer un STF. Theory r\u00e9siste et rampe pour attraper un c\u00e2ble. Theory se d\u00e9place sur le tablier, Ali lui fait un DDT pour le ramener sur le ring. Ali monte sur le coin et lui fait un 450 Splash, mais Theory l&rsquo;\u00e9vite. Theory le frappe sur la jambe et lui fait un ATL pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Theory<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 entre Cody et Seth.<\/p>\n\n\n\n<p>&#8211; Cody arrive sur le ring malgr\u00e9 sa d\u00e9chirure au muscle pectoral, on peut voir son ecchymose au niveau de la poitrine puisque le tendon s&rsquo;est d\u00e9tach\u00e9 de l&rsquo;os.<\/p>\n\n\n\n<p class=\"has-large-font-size\"><strong>Hell in a Cell Match<\/strong><\/p>\n\n\n\n<p><strong>Seth Rollins vs Cody Rhodes<\/strong><\/p>\n\n\n\n<p>En fin de match, Rollins va chercher une masse. Rollins le charge, mais Cody le bloque. Seth veut faire un Pedigree, mais Cody le renverse avec un Pedigree pour le couvrir, mais Seth r\u00e9siste \u00e0 deux. Cody prend la masse, mais Seth roule en bas du ring. Seth retourne sur le ring et surprend Cody avec son Curb Stomp pour le couvrir, mais Cody r\u00e9siste encore. Rollins se lance pour un autre Stomp, mais Rhodes l&rsquo;\u00e9vite et Rollins revient avec un Cross Rhodes. Seth veut en faire un autre, mais Rhodes le renverse avec un Cross Rhodes. Les deux rampent vers la masse, Cody la prend le premier, mais son bras ne peut plus la tenir. Cody bloque une chare avec son Cross Rhodes, un second Cross Rhodes, mais Cody le l\u00e2che. Cody prend la masse et cogne Seth en plein visage pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Cody Rhodes<\/em><\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration de Cody Rhodes dans la douleur.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re partie, cliquez ici. &#8211; On pr\u00e9sente une vid\u00e9o sur la rivalit\u00e9 avec le Judgment Day. Six-Person Mixed Tag Team Match Judgment Day&nbsp;(Edge, Damian Priest et Rhea Ripley)&nbsp;vs AJ Styles, Finn Balor et Liv Morgan En fin de match, Priest fait une Slam \u00e0 Balor, mais AJ lui fait un Phenomenal&#8230;<\/p>\n","protected":false},"author":4,"featured_media":70117,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[73],"tags":[],"ppma_author":[292],"class_list":["post-70116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hell-in-a-cell"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=70116"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70116\/revisions"}],"predecessor-version":[{"id":70123,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/70116\/revisions\/70123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/70117"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=70116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=70116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=70116"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=70116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}