{"id":698,"date":"2019-03-19T19:05:49","date_gmt":"2019-03-19T19:05:49","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=698"},"modified":"2019-03-19T19:24:52","modified_gmt":"2019-03-19T19:24:52","slug":"batista-a-le-coeur-lourd-resultats-wwe-raw-18-mars-2019","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2019\/03\/19\/batista-a-le-coeur-lourd-resultats-wwe-raw-18-mars-2019\/","title":{"rendered":"Batista a le Coeur Lourd ! R\u00e9sultats WWE RAW 18 Mars 2019!"},"content":{"rendered":"\n<p>Bonjour \u00e0 tous, dans cet express, d\u00e9couvrez le bilan du RAW de la semaine.<\/p>\n\n\n\n<p>Quel a \u00e9t\u00e9 votre match de la soir\u00e9e? Avez-vous aim\u00e9 cet \u00e9pisode? Dites nous tout en commentaire. <\/p>\n\n\n\n<p>\n\nN&rsquo;oubliez pas de soutenir et de vous abonner \u00e0 la page Reos Catch, review de vos \u00e9v\u00e9nements catch pr\u00e9f\u00e9r\u00e9s. Il suffit juste de <a href=\"https:\/\/www.youtube.com\/channel\/UCby0EOvzMb_hwAI-oZEvxnQ?view_as=subscriber\/\">cliquer ici<\/a>.\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"BATISTA A LE COEUR LOURD ! R\u00e9sultats WWE RAW 18 Mars 2019\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/_s_o20p-IT8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Bonne vid\u00e9o ! <\/p>\n\n\n\n<p>Suivez nous sur Twitter, <a href=\"https:\/\/twitter.com\/InfoLutte\">@InfoLutte<\/a>, et Merci de d\u00e9sactiver votre <a href=\"http:\/\/lutte.jdx.info\/forum\/show.php?t=78369\">Add-Block<\/a> ce qui nous aidera et vous aidera pour voir les vid\u00e9os. Faire une petite visite vers le bas pour nous aidez, ou encore abonnez vous gratuitement \u00e0 notre page Facebook en <a href=\"https:\/\/www.facebook.com\/InfoLuttenet\">cliquant ici<\/a>.<\/p>\n\n\n\n<p>N&rsquo;oubliez pas de soutenir et de vous abonner \u00e0 la page Reos Catch, review de vos \u00e9v\u00e9nements catch pr\u00e9f\u00e9r\u00e9s. Il suffit juste de <a href=\"https:\/\/www.youtube.com\/channel\/UCby0EOvzMb_hwAI-oZEvxnQ?view_as=subscriber\/\">cliquer ici<\/a>.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Bonjour \u00e0 tous, dans cet express, d\u00e9couvrez le bilan du RAW de la semaine. Quel a \u00e9t\u00e9 votre match de la soir\u00e9e? Avez-vous aim\u00e9 cet \u00e9pisode? Dites nous tout en commentaire. N&rsquo;oubliez pas de soutenir et de vous abonner \u00e0 la page Reos Catch, review de vos \u00e9v\u00e9nements catch pr\u00e9f\u00e9r\u00e9s. Il suffit juste de cliquer&#8230;<\/p>\n","protected":false},"author":3,"featured_media":719,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,20],"tags":[],"ppma_author":[291],"class_list":["post-698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-videos"],"authors":[{"term_id":291,"user_id":3,"is_guest":0,"slug":"amine","display_name":"Amine Benhelal","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/2ac225a45c11cce8567af8f2b64e669faee748a823f5f22499aaa30f28cfa944?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=698"}],"version-history":[{"count":15,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/698\/revisions"}],"predecessor-version":[{"id":721,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/698\/revisions\/721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/719"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=698"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}