{"id":69651,"date":"2022-05-27T12:55:30","date_gmt":"2022-05-27T16:55:30","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=69651"},"modified":"2022-05-27T12:55:36","modified_gmt":"2022-05-27T16:55:36","slug":"naomi-et-sasha-banks-sont-sans-salaire-tony-khan-evoque-a-nouveau-lajout-de-nouveaux-titres-a-la-aew","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/05\/27\/naomi-et-sasha-banks-sont-sans-salaire-tony-khan-evoque-a-nouveau-lajout-de-nouveaux-titres-a-la-aew\/","title":{"rendered":"Naomi et Sasha Banks sont sans salaire! \/ Tony Khan \u00e9voque \u00e0 nouveau l\u2019ajout de nouveaux titres \u00e0 la AEW!"},"content":{"rendered":"\n<p>Avec un roster qui ne fait que prendre de l\u2019ampleur jour apr\u00e8s jour, les fans de la AEW \u00e9voque r\u00e9guli\u00e8rement l\u2019id\u00e9e d\u2019ajouter de nouveaux titres au sein de la compagnie afin d\u2019ajouter de l\u2019enjeu aux rivalit\u00e9s. <\/p>\n\n\n\n<p>Alors que Tony Khan avait d\u00e9j\u00e0 \u00e9voqu\u00e9 son int\u00e9r\u00eat pour un titre par \u00e9quipe f\u00e9minin, il a remis une pi\u00e8ce dans la machine en \u00e9voquant cette fois une probable arriv\u00e9e d\u2019un titre Trios \u00e0 l\u2019occasion d\u2019une interview avec AJ Awesome:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Oui, j\u2019ai entendu parler de cette volont\u00e9. Nous avons plein de grands lutteurs \u00e0 l\u2019AEW hommes comme femmes. J\u2019ai d\u00e9j\u00e0 pens\u00e9 \u00e0 faire cela (ajouter des titres) et nous continuons d\u2019agrandir notre roster avec je l\u2019esp\u00e8re plus d\u2019\u00e9quipes. Des gens actuellement bless\u00e9es vont \u00e9galement revenir. C\u2019est quelque chose que j\u2019aimerais faire dans le futur. Le titre Trios est quelque chose que je pense les fans aimeraient et qu\u2019ils demandent. J\u2019adorerais ajouter plus de titres et avoir plus de champions que nous avons actuellement, mais seulement si cela fait sens et qu\u2019il s\u2019agisse d\u2019id\u00e9es cools.<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Parlant de championnes par \u00e9quipe. Il y a une semaine maintenant durant SmackDown, Michael Cole annon\u00e7ait que\u00a0Sasha Banks et Naomi \u00e9taient suspendues ind\u00e9finiment de la WWE,\u00a0apr\u00e8s avoir quitt\u00e9 l&rsquo;ar\u00e9na de RAW la semaine derni\u00e8re. <\/p>\n\n\n\n<p>Pour r\u00e9sumer, les championnes par \u00e9quipe n&rsquo;avaient plus envie de prendre part aux shows puisqu&rsquo;elles \u00e9taient m\u00e9contentes du booking que la compagnie leur proposait. Elles avaient m\u00eame d\u00e9cid\u00e9 de l\u00e2cher les ceintures dans le bureau de John Laurinaitis, responsable des relations avec les talents, selon la compagnie.<\/p>\n\n\n\n<p>Mais \u00e0 en croire Dave Meltzer,\u00a0Sasha Banks et Naomi ne seraient pas pay\u00e9es par la WWE durant leur suspension. Leurs marchandises \u00e9tant \u00e9galement retir\u00e9es du WWEshop, les deux Superstars ne pourront pas non plus avoir un revenu li\u00e9 aux marchandises.\u00a0<\/p>\n\n\n\n<p>Nous vous rappelons que le contrat liant Sasha Banks et Naomi \u00e0 la WWE devrait se terminer cette ann\u00e9e. Naomi \u00e9tait m\u00eame en pleine n\u00e9gociation avec la f\u00e9d\u00e9ration avant de partir en plein show.\u00a0<\/p>\n\n\n\n<p>Par contre la WWE ne semble pas vouloir les lib\u00e9rer directement, ce qui antamerait leur 90 jours de non comp\u00e9tition les rendant disponible pour<strong> All-Out<\/strong>! Nous vous tiendrons au courant de l&rsquo;avanc\u00e9 de cette affaire.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Avec un roster qui ne fait que prendre de l\u2019ampleur jour apr\u00e8s jour, les fans de la AEW \u00e9voque r\u00e9guli\u00e8rement l\u2019id\u00e9e d\u2019ajouter de nouveaux titres au sein de la compagnie afin d\u2019ajouter de l\u2019enjeu aux rivalit\u00e9s. Alors que Tony Khan avait d\u00e9j\u00e0 \u00e9voqu\u00e9 son int\u00e9r\u00eat pour un titre par \u00e9quipe f\u00e9minin, il a remis une&#8230;<\/p>\n","protected":false},"author":609,"featured_media":69653,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,4,43,36,23],"tags":[],"ppma_author":[295],"class_list":["post-69651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-news","category-raw-wwe","category-smackdown","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/69651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=69651"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/69651\/revisions"}],"predecessor-version":[{"id":69654,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/69651\/revisions\/69654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/69653"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=69651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=69651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=69651"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=69651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}