{"id":69260,"date":"2022-05-18T01:03:00","date_gmt":"2022-05-18T05:03:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=69260"},"modified":"2022-05-18T13:10:20","modified_gmt":"2022-05-18T17:10:20","slug":"les-usos-ont-conseille-solo-sikoa","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/05\/18\/les-usos-ont-conseille-solo-sikoa\/","title":{"rendered":"Les Usos ont conseill\u00e9 Solo Sikoa!"},"content":{"rendered":"\n<p>Derniers invit\u00e9s du podcast After The Bell, The Usos (Jimmy &amp; Jey Uso) nous ont parl\u00e9 de Solo Sikoa et ils ont r\u00e9v\u00e9l\u00e9 les conseils qu\u2019ils lui ont donn\u00e9s.<\/p>\n\n\n\n<p><strong>Jimmy Uso\u00a0 dit :\u00a0<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Venant d&rsquo;une grande famille, c&rsquo;est difficile de laisser sa propre empreinte. On a dit au petit fr\u00e8re : \u00ab\u00a0Tu dois trouver ta voie. Nous avons travers\u00e9 ce feu avant. Tu dois trouver ce qui marche pour toi.\u00a0\u00bb Il est l\u00e0 pour faire son truc. Chaque jour, il se dit : \u00ab\u00a0Vous avez regard\u00e9 le match ? Et mes promos ? Tu peux me dire ce que je dois faire ?\u00a0\u00bb La premi\u00e8re chose, c&rsquo;est de ne pas nous ressembler parce qu&rsquo;on se ressemble beaucoup. D&rsquo;accord, je vois.<\/p><p>Il avait les cheveux longs, il les a coup\u00e9s, teints, il est pass\u00e9 des Air Forces aux pieds nus. Il n&rsquo;est pas \u00e0 l&rsquo;aise sur le ring pieds nus, mais il fait ce qu&rsquo;il doit faire pour laisser sa marque. Je lui ai dit qu&rsquo;il la trouverait. Je me souviens de Randy Orton nous disant qu&rsquo;il n&rsquo;\u00e9tait pas Randy Orton avant six ans de carri\u00e8re. J&rsquo;ai commenc\u00e9 \u00e0 comprendre, j&rsquo;\u00e9tais assis l\u00e0 et je me disais : \u00ab\u00a0C&rsquo;est comme \u00e7a.\u00a0\u00bb Il faut sans cesse se jeter dans le grand bain et tout ce qui colle, colle. Si \u00e7a ne colle pas, on continue. Tout ce qu&rsquo;on fait, c&rsquo;est se lancer dans la bataille.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p><strong>Jey Uso dit :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Il faut toujours essayer d&rsquo;\u00e9voluer. C&rsquo;est le jeu. Soit tu te laisses distancer, soit tu restes dans le coup. Quand tu arrives ici, soit tu coules, soit tu nages. C&rsquo;est aussi simple que \u00e7a. Peu importe si vous dirigez les choses l\u00e0-bas ou ailleurs, quand vous serez ici, nous allons d\u00e9couvrir de quoi vous \u00eates fait et vous craquez, soit vous livrez la marchandise comme nous le faisons. Ce qui craint dans tout \u00e7a, petit fr\u00e8re, c&rsquo;est que \u00e7a va \u00eatre dur.<\/p><p>On est tous des grands, et puis il y a le petit fr\u00e8re, c&rsquo;est le prochain sur la liste. \u00c7a va \u00eatre dur pour lui et il le sait, mais il faut suivre le script et on le soutiendra toujours. Nous l&rsquo;aimons et il se d\u00e9brouille bien l\u00e0-bas. J&rsquo;ai h\u00e2te d&rsquo;\u00e9tendre cette Bloodline, croyez-moi, nous nous agrandissons.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Solo Sikoa fait ses armes du c\u00f4t\u00e9 de NXT 2.0 en se cr\u00e9ant son propre univers malgr\u00e9 le fait que beaucoup de fans chantent le nom des Usos et veulent le voir rejoindre la Bloodline. C\u2019est tr\u00e8s intelligent de la part de la WWE et des Usos de le laisser voler de ses propres ailes pour ne pas les br\u00fbler en n&rsquo;\u00e9tant associ\u00e9 qu&rsquo;\u00e0 sa Bloodline.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2022\/05\/17\/regardez-le-wwe-nxt-2-0-du-17-mai-2022-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Regardez le WWE NXT 2.0 du 17 Mai 2022!<\/a><\/strong><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Derniers invit\u00e9s du podcast After The Bell, The Usos (Jimmy &amp; Jey Uso) nous ont parl\u00e9 de Solo Sikoa et ils ont r\u00e9v\u00e9l\u00e9 les conseils qu\u2019ils lui ont donn\u00e9s. Jimmy Uso\u00a0 dit :\u00a0 \u00ab\u00a0Venant d&rsquo;une grande famille, c&rsquo;est difficile de laisser sa propre empreinte. On a dit au petit fr\u00e8re : \u00ab\u00a0Tu dois trouver ta&#8230;<\/p>\n","protected":false},"author":4,"featured_media":69263,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[292],"class_list":["post-69260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/69260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=69260"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/69260\/revisions"}],"predecessor-version":[{"id":69264,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/69260\/revisions\/69264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/69263"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=69260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=69260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=69260"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=69260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}