{"id":69001,"date":"2022-05-10T03:42:00","date_gmt":"2022-05-10T07:42:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=69001"},"modified":"2022-05-10T15:45:03","modified_gmt":"2022-05-10T19:45:03","slug":"un-echange-entre-raw-et-smackdown","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2022\/05\/10\/un-echange-entre-raw-et-smackdown\/","title":{"rendered":"Un \u00e9change entre RAW et Smackdown!"},"content":{"rendered":"\n<p>Il semble bien que Lacey Evans avait effectu\u00e9 son retour apr\u00e8s plus d&rsquo;un an d&rsquo;absence lors du SmackDown after WrestleMania 38. Elle avait pris une pause afin de donner naissance \u00e0 son second enfant en fin d&rsquo;ann\u00e9e 2021. Depuis son retour,\u00a0Lacey Evans apparait dans des vid\u00e9os hebdomadaires afin de nous partager son pass\u00e9, de son enfance difficile \u00e0 Superstar de la WWE, en passant par sa p\u00e9riode de marine.<\/p>\n\n\n\n<p>Celle qui a abandonn\u00e9 son ancien personnage de Heel pour revenir du c\u00f4t\u00e9 des gentils. Mais la WWE ne semble pas vouloir la garder Face tr\u00e8s longtemps. Ainsi, le PWInsider nous r\u00e9v\u00e8le que Lacey Evans fait d\u00e9sormais partie du roster de RAW et plus de SmackDown. Une nouvelle vignette a d&rsquo;ailleurs \u00e9t\u00e9 diffus\u00e9e lors du show rouge cette semaine. Mais ce n&rsquo;est pas tout,\u00a0Lacey Evans l\u00e2chera bient\u00f4t son personnage Face pour revenir en Heel.<\/p>\n\n\n\n<p>La WWE pr\u00e9voit ainsi de retrouver la m\u00e9chante Lacey Evans \u00e0 RAW. Nous verrons bien comment sera faite la transition du personnage.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il semble bien que Lacey Evans avait effectu\u00e9 son retour apr\u00e8s plus d&rsquo;un an d&rsquo;absence lors du SmackDown after WrestleMania 38. Elle avait pris une pause afin de donner naissance \u00e0 son second enfant en fin d&rsquo;ann\u00e9e 2021. Depuis son retour,\u00a0Lacey Evans apparait dans des vid\u00e9os hebdomadaires afin de nous partager son pass\u00e9, de son&#8230;<\/p>\n","protected":false},"author":4,"featured_media":69002,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,36,23],"tags":[],"ppma_author":[292],"class_list":["post-69001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/69001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=69001"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/69001\/revisions"}],"predecessor-version":[{"id":69003,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/69001\/revisions\/69003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/69002"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=69001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=69001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=69001"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=69001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}