{"id":689,"date":"2019-03-19T18:58:06","date_gmt":"2019-03-19T18:58:06","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=689"},"modified":"2019-03-19T18:58:08","modified_gmt":"2019-03-19T18:58:08","slug":"deux-matchs-annonces-pour-le-wwe-extreme-rules-2019","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2019\/03\/19\/deux-matchs-annonces-pour-le-wwe-extreme-rules-2019\/","title":{"rendered":"Deux Matchs Annonc\u00e9s pour le WWE EXtreme Rules 2019!"},"content":{"rendered":"\n<p>Dans cet Express, d\u00e9couvrez deux matchs qui sont d\u00e9j\u00e0 annonc\u00e9s pour le WWE Extreme Rules, et bien plus.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p> Le 14 juillet prochain, la WWE tiendra son PPV Extreme Rules. Bien que  la compagnie tiendra trois \u00e9v\u00e9nements sp\u00e9ciaux entre temps tel que Wrestlemania , Money In The Bank ainsi que Backlash, deux matchs sont d\u00e9j\u00e0 annonc\u00e9s. Par contre, la carte est toujours sujette \u00e0 changements mais pour le moment voici les plans. <br><br> C\u2019est ainsi que <em>CBS Philly 3<\/em>, une cha\u00eene de TV de Philadelphie  qui accueillera Extreme Rules annonce que  Roman Reigns va affronter Baron Corbin et pour Seth Rollins  ce sera Drew McIntyre. <br><br>Avec autant de temps \u00e0 passer d&rsquo;ici l\u00e0, il est possible que ce ne soit que des annonces pour remplir les publicit\u00e9s. Nous vous tiendrons bien s\u00fbre au courant des d\u00e9veloppements. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans cet Express, d\u00e9couvrez deux matchs qui sont d\u00e9j\u00e0 annonc\u00e9s pour le WWE Extreme Rules, et bien plus. Le 14 juillet prochain, la WWE tiendra son PPV Extreme Rules. Bien que la compagnie tiendra trois \u00e9v\u00e9nements sp\u00e9ciaux entre temps tel que Wrestlemania , Money In The Bank ainsi que Backlash, deux matchs sont d\u00e9j\u00e0 annonc\u00e9s&#8230;.<\/p>\n","protected":false},"author":2,"featured_media":699,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"ppma_author":[287],"class_list":["post-689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"authors":[{"term_id":287,"user_id":2,"is_guest":0,"slug":"jason","display_name":"Jason Desc\u00f4teaux","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/f64adf6d13198c3a532c061cecd8672089a1e9a3d07c702dffe886a7e55a15eb?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=689"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/689\/revisions"}],"predecessor-version":[{"id":701,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/689\/revisions\/701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/699"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=689"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}